{"id":75112,"date":"2026-03-23T07:30:33","date_gmt":"2026-03-23T07:30:33","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/un-iphone-sans-4g-en-espagne-2\/"},"modified":"2026-08-24T02:07:51","modified_gmt":"2026-08-24T02:07:51","slug":"un-iphone-sans-4g-en-espagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/un-iphone-sans-4g-en-espagne-2\/","title":{"rendered":"Un iPhone sans 4G en Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>L&rsquo;iPhone 5 sera dot\u00e9 de la technologie 4G, mais les r\u00e9seaux espagnols n&rsquo;en permettront pas encore l&rsquo;utilisation. Explications.<\/strong>  La sortie d&rsquo;un nouveau produit Apple se transforme toujours en\u00a0\u00e9v\u00e8nement\u00a0mondial. L&rsquo;iPhone 5, qui sera pr\u00e9sent\u00e9 le 12 septembre prochain, n&rsquo;\u00e9chappe pas \u00e0 la r\u00e8gle et devrait combler les esp\u00e9rances des utilisateurs comme des investisseurs. L&rsquo;une des principales innovations attendues est bien s\u00fbr l&rsquo;int\u00e9gration de la technologie 4G, offrant une vitesse de t\u00e9l\u00e9chargement, largement am\u00e9lior\u00e9e, de 100 m\u00e9gabits par seconde. Les utilisateurs du nouvel iPhone r\u00e9sidant en Espagne ne pourront toutefois pas en profiter puisqu&rsquo;ils continueront d&rsquo;utiliser les r\u00e9seaux 3G (40 m\u00e9gas par seconde) en attendant une plus grande g\u00e9n\u00e9ralisation du tr\u00e8s haut d\u00e9bit. C&rsquo;est en r\u00e9alit\u00e9 l&rsquo;Europe toute enti\u00e8re qui a pris du retard dans l&rsquo;adaptation de ses r\u00e9seaux \u00e0 la t\u00e9l\u00e9phonie de 4\u00e8me g\u00e9n\u00e9ration. Fin 2011, on comptait d\u00e9j\u00e0 pr\u00e8s de 10 millions d&rsquo;abonn\u00e9s dans le monde, principalement en Asie et aux \u00c9tats-Unis. Sur le vieux continent, les op\u00e9rateurs se sont montr\u00e9s plus frileux et commencent \u00e0 peine \u00e0 investir pour s&rsquo;adapter \u00e0 la 4G. Cons\u00e9quence\u00a0: l&rsquo;Europe ne devrait pas \u00eatre connect\u00e9e avant 2014 ou 2015.  <strong>Apple au centre-ville de Madrid et de Barcelone<\/strong>  Malgr\u00e9 les retards technologiques, la marque am\u00e9ricaine continue de parier sur l&rsquo;Espagne. Le 28 juillet dernier, l&rsquo;ouverture d&rsquo;un nouvel Apple Store sur le prestigieux Paseo de Gracia de Barcelone a attir\u00e9 des milliers de visiteurs et clients. Apr\u00e8s l&rsquo;ouverture en 2010 d&rsquo;un Apple Store au centre commercial barcelonais \u00ab\u00a0la maquinista\u00a0\u00bb, la marque a install\u00e9 au c\u0153ur de la capitale catalane son plus grand magasin d&rsquo;Europe du Sud. Elle ouvrira prochainement un concept store sur la Plaza del Sol de Madrid, un magasin que l&rsquo;on annonce grandiose, et plus important que celui de la 5\u00e8me avenue \u00e0 New-York. La date d&rsquo;inauguration n&rsquo;a pas encore \u00e9t\u00e9 confirm\u00e9e.  <em>\u00a0AC<\/em>  &nbsp;<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;iPhone 5 sera dot\u00e9 de la technologie 4G, mais les r\u00e9seaux espagnols n&rsquo;en permettront pas encore l&rsquo;utilisation. Explications. La sortie d&rsquo;un nouveau produit Apple se transforme toujours en\u00a0\u00e9v\u00e8nement\u00a0mondial. L&rsquo;iPhone 5, qui sera pr\u00e9sent\u00e9 le 12 septembre prochain, n&rsquo;\u00e9chappe pas \u00e0 la r\u00e8gle et devrait combler les esp\u00e9rances des utilisateurs comme des investisseurs. L&rsquo;une des principales [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-75112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75112"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46797"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}