{"id":75101,"date":"2026-03-23T07:20:07","date_gmt":"2026-03-23T07:20:07","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/jose-manuel-soria-en-chine-pour-promouvoir-lespagne-2\/"},"modified":"2026-08-24T01:19:58","modified_gmt":"2026-08-24T01:19:58","slug":"jose-manuel-soria-en-chine-pour-promouvoir-lespagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/jose-manuel-soria-en-chine-pour-promouvoir-lespagne-2\/","title":{"rendered":"Jos\u00e9 Manuel Soria en Chine pour promouvoir l&rsquo;Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<figure id=\"attachment_6643\" aria-describedby=\"caption-attachment-6643\" style=\"width: 300px\" class=\"wp-caption alignleft\"><figcaption id=\"caption-attachment-6643\" class=\"wp-caption-text\">Cr\u00e9dits : Flickr\/\/CCommons\/\/Dainis Matisons<\/figcaption><\/figure>\n<p>  <strong><em>Le ministre espagnol de l&rsquo;industrie et du transport, Jos\u00e9 Manuel Soria, se rendra en Chine la semaine prochaine afin d&rsquo;assurer la promotion de l&rsquo;Espagne sur le march\u00e9 asiatique.<\/em><\/strong>  Il devrait y rencontrer des repr\u00e9sentants des grandes agences de voyages chinoises afin de discuter de projets de d\u00e9veloppement et d&rsquo;investissements possibles dans le secteur touristiques. Le ministre a rappel\u00e9 dans un entretien \u00e0 Telecinco que \u00ab\u00a0<em>sur 100 euros en Espagne, 11 proviennent du secteur touristique<\/em>\u00ab\u00a0.  Comme pour prouver l&rsquo;importance du secteur dans l&rsquo;\u00e9conomie nationale, le 27 septembre prochain la journ\u00e9e internationale du tourisme se tiendra \u00e0 Las Palomas, sur l&rsquo;\u00eele de la Grande Canarie. Organis\u00e9e en partenariat avec l&rsquo;Organisation mondiale du tourisme, il s&rsquo;agit pour l&rsquo;Espagne de s\u00e9duire aussi bien visiteurs nationaux qu&rsquo;internationaux.  Le pays a en effet battu cette ann\u00e9e <a href=\"https:\/\/lecourrier.es\/le-tourisme-progresse-en-espagne\/\" target=\"_blank\">un record en termes de fr\u00e9quentation<\/a> par des touristes \u00e9trangers, mais le tourisme national est en berne. Avec une \u00e9conomie morose, il est donc vital de se tourner vers de nouveaux march\u00e9s. Soria souhaite \u00e9galement d\u00e9velopper le tourisme culturel, mettant en valeur le patrimoine du pays, afin de s&rsquo;adresser \u00e0 une nouvelle client\u00e8le pas forc\u00e9ment attir\u00e9e par les plages espagnoles.  &nbsp;  LCE \u00a0 <a href=\"https:\/\/mobile.twitter.com\/lecourrierES\" target=\"_blank\">@lecourrierES<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dits : Flickr\/\/CCommons\/\/Dainis Matisons Le ministre espagnol de l&rsquo;industrie et du transport, Jos\u00e9 Manuel Soria, se rendra en Chine la semaine prochaine afin d&rsquo;assurer la promotion de l&rsquo;Espagne sur le march\u00e9 asiatique. Il devrait y rencontrer des repr\u00e9sentants des grandes agences de voyages chinoises afin de discuter de projets de d\u00e9veloppement et d&rsquo;investissements possibles dans [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-75101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75101"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46743"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}