{"id":75100,"date":"2026-03-23T07:15:39","date_gmt":"2026-03-23T07:15:39","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/telefonica-obtient-930-millions-deuros-des-banques-chinoises-2\/"},"modified":"2026-08-24T01:19:55","modified_gmt":"2026-08-24T01:19:55","slug":"telefonica-obtient-930-millions-deuros-des-banques-chinoises-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/telefonica-obtient-930-millions-deuros-des-banques-chinoises-2\/","title":{"rendered":"Telef\u00f3nica obtient 930 millions d\u2019euros des banques chinoises"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Les ventes de l\u2019op\u00e9rateur de t\u00e9l\u00e9communications Telef\u00f3nica sont en baisse en Espagne comme en Am\u00e9rique Latine. De plus, la compagnie est actuellement en train de perdre des clients. Malgr\u00e9 cela la multinationale a r\u00e9ussi \u00e0 conclure une op\u00e9ration de financement avec la Chine.<\/strong>  &nbsp;  Telef\u00f3nica a obtenu une ligne de cr\u00e9dit de 1,2 milliards de dollars (environ 929 millions d\u2019euros) sur 10 ans avec les banques chinoises CDB (China Development Bank) et ICBC (Industrial and Commercial Bank of China).\u00a0 Les fonds seront destin\u00e9s \u00e0 l\u2019acquisition de produits et services technologiques par l\u2019entreprise de t\u00e9l\u00e9communications dans le monde entier.  Il s\u2019agit de la deuxi\u00e8me phase d\u2019une op\u00e9ration r\u00e9alis\u00e9e au mois de janvier dernier dans laquelle BBVA a particip\u00e9 comme conseiller interm\u00e9diaire. C\u2019est la premi\u00e8re initiative de ce type annonc\u00e9e par CDB avec une entreprise espagnole qui contribue donc \u00e0 l\u2019avanc\u00e9e de la nouvelle tendance de coop\u00e9ration patronale hispano-chinoise.  <strong>9,2 milliards d\u2019euros de cr\u00e9dits<\/strong>  Depuis le d\u00e9but de l\u2019ann\u00e9e, Telef\u00f3nica a r\u00e9alis\u00e9 plusieurs op\u00e9rations de financement pour un montant global d\u2019environ 9,2 milliards d\u2019euros. Des \u00e9missions atteignant 3,3 milliards d\u2019euros ont \u00e9t\u00e9 lanc\u00e9es dans le march\u00e9 obligataire (euro et livre).  Des placements priv\u00e9s en euros, couronnes tch\u00e8ques et yens japonais ont \u00e9galement eu lieu pour un montant approximatif de 300 millions d\u2019euros. Dans le march\u00e9 des emprunts, 4 milliards d\u2019euros ont servi au refinancement d\u2019un syndicat ainsi qu\u2019\u00e0 d\u2019autres financements alternatifs, y compris l\u2019accord cit\u00e9 avec les banques chinoises pour un montant total de 1,5 milliards d\u2019euros.  <strong>Investissements en Espagne<\/strong>  Il y a quelques jours, Telef\u00f3nica et La Caixa ont annonc\u00e9 un investissement conjoint de trois millions d\u2019euros dans la compagnie addFleet sp\u00e9cialis\u00e9e dans les syst\u00e8mes intelligents pour le transport. Les deux entreprises souhaitent d\u00e9velopper la commercialisation des produits d\u2019addFleet dans le monde entier. C\u2019est le premier investissement que r\u00e9alise Telef\u00f3nica Ventures en Espagne\u00a0 apr\u00e8s avoir auparavant mis\u00e9 sur l\u2019international avec des entreprises technologiques comme Quantenna Communications, Joyent ou bien Boku.  N.B.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les ventes de l\u2019op\u00e9rateur de t\u00e9l\u00e9communications Telef\u00f3nica sont en baisse en Espagne comme en Am\u00e9rique Latine. De plus, la compagnie est actuellement en train de perdre des clients. Malgr\u00e9 cela la multinationale a r\u00e9ussi \u00e0 conclure une op\u00e9ration de financement avec la Chine. &nbsp; Telef\u00f3nica a obtenu une ligne de cr\u00e9dit de 1,2 milliards de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-75100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75100"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46739"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}