{"id":75099,"date":"2026-03-23T07:15:31","date_gmt":"2026-03-23T07:15:31","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/pullmantur-et-avanza-concluent-un-accord-pour-le-transport-de-passagers-2\/"},"modified":"2026-08-24T01:19:50","modified_gmt":"2026-08-24T01:19:50","slug":"pullmantur-et-avanza-concluent-un-accord-pour-le-transport-de-passagers-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/pullmantur-et-avanza-concluent-un-accord-pour-le-transport-de-passagers-2\/","title":{"rendered":"Pullmantur et Avanza concluent un accord pour le transport de passagers"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><em>Pullmantur, la premi\u00e8re compagnie de croisi\u00e8res espagnole, a conclu un accord avec le transporteur Avanza afin de faciliter les d\u00e9placements de ses voyageurs.<\/em>  &nbsp;  <\/p>\n<figure id=\"attachment_6836\" aria-describedby=\"caption-attachment-6836\" style=\"width: 300px\" class=\"wp-caption alignleft\"><figcaption id=\"caption-attachment-6836\" class=\"wp-caption-text\">Cr\u00e9dits : Flickr\/\/CCommons\/\/Retols Torcal<\/figcaption><\/figure>\n<p>  Le groupe de croisi\u00e8res inaugurera en effet \u00e0 la fin du mois son nouveau circuit,\u00a0<a href=\"https:\/\/www.pullmantur.es\/cruceros?p_p_id=cruiseSearch_WAR_portalcruisewebsearch01&amp;p_p_lifecycle=1&amp;p_p_state=normal&amp;p_p_mode=view&amp;_cruiseSearch_WAR_portalcruisewebsearch01_action=showCruises&amp;_cruiseSearch_WAR_portalcruisewebsearch01_redirect=%2Fcruceros%2Fmediterraneo%2Fleyendas-del-mediterraneo%2Fpalma%2Foctubre-2012.html\" target=\"_blank\">\u00ab\u00a0L\u00e9gendes de la M\u00e9diterran\u00e9e\u00a0\u00bb<\/a>, qui fera d\u00e9couvrir aux vacanciers les villes de la M\u00e9diterran\u00e9e, de Valence \u00e0 La Valette, en passant par Palma de Majorque, Messine, Naples et Cagliari. Avec des d\u00e9parts tous les samedis, pour des prix \u00e0 partir de 500 euros, Pullmantur esp\u00e8re accueillir plusieurs milliers de voyageurs \u00e0 bord de son navire\u00a0<em>MS Empress<\/em>.  Pour attirer plus de clients, la compagnie propose d\u00e9sormais un partenariat avec Avanza, qui emm\u00e8nera directement les passagers de Madrid \u00e0 Valence , port de d\u00e9part de la croisi\u00e8re. Pour une trentaine d&rsquo;euros aller-retour, il sera possible de prendre des navettes de bus, entre Estacion Sur \u00e0 Madrid et le port de croisi\u00e8res de Valence. Les billets peuvent \u00eatre acheter dans les agences de voyage.  LCE \u00a0<a href=\"https:\/\/mobile.twitter.com\/lecourrierES\" target=\"_blank\">@lecourrierES<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pullmantur, la premi\u00e8re compagnie de croisi\u00e8res espagnole, a conclu un accord avec le transporteur Avanza afin de faciliter les d\u00e9placements de ses voyageurs. &nbsp; Cr\u00e9dits : Flickr\/\/CCommons\/\/Retols Torcal Le groupe de croisi\u00e8res inaugurera en effet \u00e0 la fin du mois son nouveau circuit,\u00a0\u00ab\u00a0L\u00e9gendes de la M\u00e9diterran\u00e9e\u00a0\u00bb, qui fera d\u00e9couvrir aux vacanciers les villes de la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46735,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[941,660,272],"class_list":["post-75099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-croisiere","tag-tourisme","tag-valence"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75099"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46735"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}