{"id":75090,"date":"2026-03-23T06:58:46","date_gmt":"2026-03-23T06:58:46","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/la-crise-provoque-la-fermeture-des-restaurants-mythiques-de-la-capitale-2\/"},"modified":"2026-08-24T00:48:04","modified_gmt":"2026-08-24T00:48:04","slug":"la-crise-provoque-la-fermeture-des-restaurants-mythiques-de-la-capitale-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/la-crise-provoque-la-fermeture-des-restaurants-mythiques-de-la-capitale-2\/","title":{"rendered":"La crise provoque la fermeture des restaurants mythiques de la capitale"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Depuis l\u2019ann\u00e9e derni\u00e8re la crise ne cesse d\u2019entra\u00eener dans sa spirale infernale quelques-uns des restaurants mythiques du panorama gastronomique madril\u00e8ne. Paradoxalement, de nouveaux \u00e9tablissements continuent d\u2019ouvrir leurs portes comme le \u2018Ten con Ten\u2019 du groupe Paraguas qui affiche une liste d\u2019attente de plusieurs semaines.<\/strong>  Mais la crise touche \u00e9galement la haute h\u00f4tellerie et restauration. Une chute de la consommation brutale et la hausse des imp\u00f4ts sont les principaux facteurs responsables de cette baisse de fr\u00e9quentation des restaurants luxueux. Le probl\u00e8me n\u2019est pas seulement une question de cuisine sinon du concept classique et traditionnel en g\u00e9n\u00e9ral. Malgr\u00e9 les efforts de modernisation et l\u2019ajustement des prix effectu\u00e9 par ce type de restaurant, certains \u00e9tablissements mythiques de la capitale ont d\u00fb mettre la cl\u00e9 sous la porte derni\u00e8rement.  <strong>L\u2019empire culinaire des Cort\u00e9s<\/strong>  C\u2019est notamment le cas des restaurants \u2018Jockey\u2019 et \u2018Club 31\u2019 propri\u00e9t\u00e9 de la famille Cort\u00e9s. Ces deux restaurants classiques, piliers de la cuisine traditionnelle madril\u00e8ne, n\u2019ont pas r\u00e9ussi \u00e0 faire face \u00e0 leurs dettes malgr\u00e9 un processus de restructuration mis en place il y a deux ans. Le \u2018Jockey\u2019, fond\u00e9 en 1945, \u00e9tait la r\u00e9f\u00e9rence culinaire de la derni\u00e8re moiti\u00e9 du XXe si\u00e8cle \u00e0 Madrid tout comme les \u00e9tablissements \u2018Horcher\u2019 et \u2018Zalaca\u00edn\u2019, \u00e9galement en difficult\u00e9 actuellement. Sa cuisine traditionnelle avec une touche fran\u00e7aise a \u00e9t\u00e9 savour\u00e9e par bon nombre de princes et monarques du monde entier mais aussi par l\u2019\u00e9lite patronale et politique du pays.  Quant au luxueux \u2018Club 31\u2019, il disposait d\u2019une tr\u00e8s grande cave et offrait un des meilleurs services de salle du pays appr\u00e9ci\u00e9 par la classe dirigeante et les artistes comme Dal\u00ed ou bien Alberti. Malgr\u00e9 les efforts de la famille Cort\u00e9s tant au niveau de la modernisation comme des prix, passant d\u2019une centaine d\u2019euros en moyenne \u00e0 40 euros, ces deux r\u00e9f\u00e9rences gastronomiques madril\u00e8nes n\u2019existent d\u00e9sormais plus. <\/p>\n<div>  <strong>La liste continue<\/strong>  <\/p>\n<figure id=\"attachment_6862\" aria-describedby=\"caption-attachment-6862\" style=\"width: 300px\" class=\"wp-caption alignleft\"><figcaption id=\"caption-attachment-6862\" class=\"wp-caption-text\">Cr\u00e9dits : Flickr\/\/CCommons\/\/Pablo Monteagudo<\/figcaption><\/figure>\n<p>  D\u2019autres enseignes de la restauration classique de Madrid ont d\u00fb cesser leur activit\u00e9 comme le \u2018Balzac\u2019, un endroit o\u00f9<strong>\u00a0<\/strong>sont pass\u00e9s aux fourneaux de prestigieux chefs comme Andr\u00e9 Madrigal ou C\u00e9sar Mart\u00edn.<strong>\u00a0<\/strong>Le &lsquo;Pr\u00edncipe de Viana&rsquo;, autre restaurant mythique ferm\u00e9 depuis un an, \u00e9tait connu pour sa cuisine raffin\u00e9e inspir\u00e9e du Pays Basque et de la Navarre.<strong>\u00a0<\/strong>L\u2019&rsquo;Antojo&rsquo;, sp\u00e9cialis\u00e9 dans la cuisine fusion, \u00e9tait consid\u00e9r\u00e9 comme l\u2019un des meilleurs endroits pour se restaurer dans la capitale. Mais aussi le &lsquo;Chafl\u00e1n&rsquo; r\u00e9put\u00e9 pour sa cuisine m\u00e9diterran\u00e9enne avant-gardiste notamment les risottos, le thon et la soupe.<strong><\/strong>  <strong>Nouveaux concepts<\/strong>  <\/div>\n<p> Paradoxalement, de nombreux restaurants continuent \u00e0 fleurir dans la capitale. Ces nouveaux \u00e9tablissements appartiennent dans la plupart des cas \u00e0 des personnes ayant perdu leur emploi ou leur entreprise qui d\u00e9cident de placer leurs \u00e9conomies dans une \u2018affaire s\u00fbre\u2019. D\u2019autre part, beaucoup de restaurants \u00e0 l\u2019origine r\u00e9put\u00e9s pour leurs prix \u00e9lev\u00e9s d\u00e9cident d\u2019ouvrir des filiales \u00ab\u00a0plus jeunes, informelles\u00a0 et bon march\u00e9\u00a0\u00bb pour faire face \u00e0 la crise. C\u2019est le cas notamment des \u00e9tablissements \u2018Astrid y Gast\u00f3n\u2019, \u2018Dassa Bassa\u2019 ou bien le \u2018Teatriz\u2019 qui ont install\u00e9 dans leurs\u00a0restaurants d\u2019origine un espace \u2018bis\u2019 proposant une cuisine \u00e0 des prix plus abordables.  N.B.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis l\u2019ann\u00e9e derni\u00e8re la crise ne cesse d\u2019entra\u00eener dans sa spirale infernale quelques-uns des restaurants mythiques du panorama gastronomique madril\u00e8ne. Paradoxalement, de nouveaux \u00e9tablissements continuent d\u2019ouvrir leurs portes comme le \u2018Ten con Ten\u2019 du groupe Paraguas qui affiche une liste d\u2019attente de plusieurs semaines. Mais la crise touche \u00e9galement la haute h\u00f4tellerie et restauration. Une [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3092,1279,375,2363],"class_list":["post-75090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-cuisine","tag-gastronomie","tag-madrid","tag-restaurant"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75090"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46701"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}