{"id":75078,"date":"2026-03-23T06:48:28","date_gmt":"2026-03-23T06:48:28","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/rencontre-avec-le-chef-belge-etienne-bastaits-2\/"},"modified":"2026-08-23T23:59:51","modified_gmt":"2026-08-23T23:59:51","slug":"rencontre-avec-le-chef-belge-etienne-bastaits-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/rencontre-avec-le-chef-belge-etienne-bastaits-2\/","title":{"rendered":"Rencontre avec le Chef belge Etienne Bastaits"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Cette ann\u00e9e, l&rsquo;Atelier Belge, l&rsquo;unique restaurant belge actuellement dans la capitale, a souffle sa premi\u00e8re bougie. L&rsquo;occasion pour son chef, Etienne Bastaits, de nous pr\u00e9senter son nouvel \u00e9tablissement \u00e0 quelques pas du Hollywood Boulevard madril\u00e8ne, la rue Mart\u00edn de los H\u00e9ros.<\/strong>  Apr\u00e8s avoir travaill\u00e9 dans de nombreux restaurants \u00e9toil\u00e9s, Etienne Bastaits d\u00e9cide de se lancer dans un nouveau projet: la cr\u00e9ation d&rsquo;un \u00e9tablissement qui propose une cuisine belge de qualit\u00e9 \u00e0 un prix abordable. Un retour au source pour ce chef belge expatri\u00e9 en Espagne depuis des ann\u00e9es et passionn\u00e9 par son m\u00e9tier.  Peu de restaurants \u00e0 Madrid offrent un service de qualit\u00e9 dans une ambiance brasserie. Le souci du d\u00e9tail se retrouve dans la pr\u00e9sentation des plats &#8211; digne d&rsquo;un restaurant de haute gastronomie &#8211; et dans l&rsquo;attention particuli\u00e8re de ses serveurs. Une d\u00e9coration raffin\u00e9e qui offre un joli clin d&rsquo;\u0153il \u00e0 la Belgique &#8211; on y retrouve Georges Simenon, Magritte ou Eddy Merckx &#8211; sans tomber dans l&rsquo;univers clich\u00e9 d&rsquo;un \u00e9tablissement pour expatri\u00e9s. La carte propose un menu d\u00e9gustation et une s\u00e9lection de plats fid\u00e8les aux saveurs belges: On y retrouvera le waterzooi, la raie au beurre, les moules marini\u00e8res accompagn\u00e9es d&rsquo;excellentes frites, les croquettes aux crevettes dignes de celles d&rsquo;Ostende et d&rsquo;autres classiques tout aussi d\u00e9licieux. Sans oublier les bi\u00e8res belges, un hommage absolu \u00e0 la culture du plat pays.  En pleine \u00e9volution, l&rsquo;Atelier belge proposera bient\u00f4t au public des cours de cuisine avec d\u00e9gustation. Une excellente mani\u00e8re de d\u00e9couvrir la gastronomie de la Belgique sous un concept diff\u00e9rent. Et d&rsquo;autre part, un bar <em>tapeo <\/em>pour appr\u00e9cier l&rsquo;ambiance tapas tout en mangeant quelques sp\u00e9cialit\u00e9s belges.  L&rsquo;ATELIER BELGE  C\/Mart\u00edn de los Heros, 36  28008 Madrid  Couvert: entre 30 et 35\u20ac\/pp.  &nbsp;  Marie Lampe  <a href=\"http:\/\/www.madridandco.com\/fr\/home_fr.html\">Madrid&amp;Co<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, l&rsquo;Atelier Belge, l&rsquo;unique restaurant belge actuellement dans la capitale, a souffle sa premi\u00e8re bougie. L&rsquo;occasion pour son chef, Etienne Bastaits, de nous pr\u00e9senter son nouvel \u00e9tablissement \u00e0 quelques pas du Hollywood Boulevard madril\u00e8ne, la rue Mart\u00edn de los H\u00e9ros. Apr\u00e8s avoir travaill\u00e9 dans de nombreux restaurants \u00e9toil\u00e9s, Etienne Bastaits d\u00e9cide de se lancer [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46657,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4440],"tags":[],"class_list":["post-75078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75078"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46657"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}