{"id":75066,"date":"2026-03-23T06:34:54","date_gmt":"2026-03-23T06:34:54","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/volotea-la-compagnie-aerienne-iberique-low-cost-qui-senvole-2\/"},"modified":"2026-08-23T23:27:28","modified_gmt":"2026-08-23T23:27:28","slug":"volotea-la-compagnie-aerienne-iberique-low-cost-qui-senvole-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/volotea-la-compagnie-aerienne-iberique-low-cost-qui-senvole-2\/","title":{"rendered":"Volotea, la compagnie a\u00e9rienne ib\u00e9rique low-cost qui s&rsquo;envole"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong><\/strong>  <strong>Le secteur des transports a\u00e9riens ne rencontre pas de nuages. Les transporteurs \u00e0 bas co\u00fbts fleurissent et s&rsquo;implantent dans toute l&rsquo;Europe.\u00a0Apr\u00e8s Easy Jet, Ryanair et Norwegan l&rsquo;offre a\u00e9rienne low-cost se d\u00e9multiplie.\u00a0<\/strong>  Volotea \u00ab\u00a0<em>La compagnie des capitales r\u00e9gionales europ\u00e9ennes<\/em>\u00a0\u00bb s&rsquo;impose petit \u00e0 petit en Espagne mais aussi sur le march\u00e9 europ\u00e9en. La jeune firme espagnole qui se d\u00e9veloppe op\u00e8re des vols r\u00e9gionaux \u00e0\u00a0travers une grande partie de l&rsquo;Europe et au d\u00e9part de l&rsquo;Espagne. Pour \u00e9chapper \u00e0 la crise les entreprises pr\u00e9f\u00e8rent d&rsquo;habitude op\u00e9rer un repli et\u00a0se concentrer sur le march\u00e9 national. Ce n&rsquo;est pas le cas de Volotea.\u00a0Plusieurs fr\u00e9quences par semaine en direction de r\u00e9gions diff\u00e9rentes ouvrent des perspectives nouvelles pour les voyageurs et pour les entreprises. Et en effet ce ne sont pas que les grandes capitales europ\u00e9ennes\u00a0qui sont desservies mais bien les capitales de r\u00e9gion. Malaga, Bastia, ou Munich par exemple profitent de ces nouveaux r\u00e9seaux et peuvent d\u00e9velopper leurs strat\u00e9gies touristiques et \u00e9conomiques.  &nbsp;  <strong>Volotea veut doubler son activit\u00e9 en Espagne dans l&rsquo;ann\u00e9e<\/strong>  &nbsp;  Nantes est la derni\u00e8re base investie par la compagnie. Les 100.000 usagers de la compagnie en 2012 pourront doubler d&rsquo;ici la fin de l&rsquo;ann\u00e9e. Interrog\u00e9 par le quotidien Ouest-France, Carlos Mu\u00f1oz, PDG de Volotea dresse un bilan positif de l&rsquo;ann\u00e9e 2012 et se projette. \u00ab\u00a0<em>Pour 2013, nous pensons doubler cette activit\u00e9 pour arriver \u00e0 200 000 passagers transport\u00e9s \u00e0 travers 20 destinations<\/em>.\u00a0\u00bb, et ca, rien que pour le march\u00e9 francais.  Sa flotte constitu\u00e9e exclusivement de Boeing 117 \u00e0 125 places en location est un type d&rsquo;avion peu courant. Dans les ann\u00e9es \u00e0 venir, l&rsquo;entreprise esp\u00e8re pouvoir se doter de quatre \u00e0 cinq avions dans chaque base \u00ab\u00a0<em>pour pouvoir transporter 300.000 \u00e0 400.000 passagers<\/em>\u00a0\u00bb ajoute Carlos Mu\u00f1oz.  48 destinations de vol sont pr\u00e9vues avec des d\u00e9parts de\u00a0M\u00e1laga,\u00a0Bilbao ou encore Valence. La compagnie qui ne compte pas s&rsquo;arr\u00eater en si bon chemin pr\u00e9voit d\u00e9j\u00e0 d&rsquo;autres liaisons de l&rsquo;Espagne vers la France. Des liaisons r\u00e9guli\u00e8res comme Bordeaux-Malaga devraient leur permettre de d\u00e9velopper leur pr\u00e9sence sur le march\u00e9 francais.  &nbsp;  <strong>J.C.<\/strong><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur des transports a\u00e9riens ne rencontre pas de nuages. Les transporteurs \u00e0 bas co\u00fbts fleurissent et s&rsquo;implantent dans toute l&rsquo;Europe.\u00a0Apr\u00e8s Easy Jet, Ryanair et Norwegan l&rsquo;offre a\u00e9rienne low-cost se d\u00e9multiplie.\u00a0 Volotea \u00ab\u00a0La compagnie des capitales r\u00e9gionales europ\u00e9ennes\u00a0\u00bb s&rsquo;impose petit \u00e0 petit en Espagne mais aussi sur le march\u00e9 europ\u00e9en. La jeune firme espagnole qui [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":31229,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1030,332,1469,1115],"class_list":["post-75066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-compagnie-aerienne","tag-espagne","tag-low-cost","tag-volotea"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75066"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/31229"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}