{"id":75055,"date":"2026-03-23T06:24:18","date_gmt":"2026-03-23T06:24:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/vodafone-espana-pourrait-licencier-25-de-son-staff-2\/"},"modified":"2026-08-23T22:40:56","modified_gmt":"2026-08-23T22:40:56","slug":"vodafone-espana-pourrait-licencier-25-de-son-staff-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/vodafone-espana-pourrait-licencier-25-de-son-staff-2\/","title":{"rendered":"Vodafone Espa\u00f1a pourrait licencier 25% de son staff"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Selon les syndicats, Vodafone Espa\u00f1a pr\u00e9voit de pr\u00e9senter un plan de restructuration qui pourrait affecter environ mille employ\u00e9s, c\u2019est-\u00e0-dire 25% du personnel du groupe. C&rsquo;est courant janvier que la firme devrait pr\u00e9senter ce plan de licenciement au minist\u00e8re du Travail.<\/strong>  Vodafone a expliqu\u00e9 aux syndicats sa pr\u00e9occupation concernant la baisse des revenus annuels qui affecte l\u2019entreprise. \u00a0La crise touche en effet tous les secteurs de l\u2019\u00e9conomie espagnole. Des discussions entre l&rsquo;entreprise et les partenaires sociaux s&rsquo;ouvrent pour arriver \u00e0 trouver un accord.  L&rsquo;entreprise a \u00e9galement fait part de ses inqui\u00e9tudes \u00a0pour la baisse de revenus qu&rsquo;elle a connu.\u00a0En accord avec les derniers chiffres donn\u00e9s par la firme, les revenus de la filiale au premier semestre ont chut\u00e9 de 11%. Ces baisses sont imput\u00e9es \u00e0 une r\u00e9duction des prix des abonnements, et \u00e0 la crise qui entraine un changement dans les usages du t\u00e9l\u00e9phone mobile.  Les personnels ont reconnu que l&rsquo;Espagne est l&rsquo;un des pays qui accuse le plus la crise. Hors d&rsquo;Europe, la compagnie obtient de bons r\u00e9sultats qui contrastent avec la situation du pays. \u00a0L&rsquo;Asie et plus particuli\u00e8rement l&rsquo;Inde sont de bons clients de la firme. De quoi \u00eatre optimiste. Cependant, dans un pays si touch\u00e9 par la crise, les abonnements baissent. Les foyers doivent arbitrer leurs d\u00e9penses et les mobiles font partie de celles qui sont supprim\u00e9es en premier. Selon Reuters, le nombre de lignes mobiles en service a chut\u00e9 de 3.8% dans l&rsquo;ann\u00e9e \u00e9coul\u00e9e.  Actuellement, le personnel de Vodafone en Espagne compte 4.300 employ\u00e9s.  &nbsp;  <strong>J.C.<\/strong><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon les syndicats, Vodafone Espa\u00f1a pr\u00e9voit de pr\u00e9senter un plan de restructuration qui pourrait affecter environ mille employ\u00e9s, c\u2019est-\u00e0-dire 25% du personnel du groupe. C&rsquo;est courant janvier que la firme devrait pr\u00e9senter ce plan de licenciement au minist\u00e8re du Travail. Vodafone a expliqu\u00e9 aux syndicats sa pr\u00e9occupation concernant la baisse des revenus annuels qui affecte [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":75056,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1076,3221,1651],"class_list":["post-75055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-crise","tag-licenciements","tag-vodafone"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75055"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/75056"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}