{"id":75033,"date":"2026-03-23T05:59:51","date_gmt":"2026-03-23T05:59:51","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/25-millions-de-touristes-pour-les-mayas-2\/"},"modified":"2026-08-23T21:21:34","modified_gmt":"2026-08-23T21:21:34","slug":"25-millions-de-touristes-pour-les-mayas-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/25-millions-de-touristes-pour-les-mayas-2\/","title":{"rendered":"25 millions de touristes pour les Mayas"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>On annon\u00e7ait sa fin, le \u00ab\u00a0Monde Maya\u00a0\u00bb, compos\u00e9 de cinq pays d&rsquo;Am\u00e9rique Centrale, a battu tous les records de visiteurs en 2011 et 2012. <\/strong>  D\u00e9but f\u00e9vrier, et en marge du <a href=\"https:\/\/lecourrier.es\/salon-du-tourisme-fitur-2013-independance-et-pays-emergents\/\" target=\"_blank\">FITUR<\/a>, l&rsquo;Organisation du Monde Maya (OMM) a tenu sa r\u00e9union annuelle \u00e0 Madrid pour entreprendre de nouvelles actions touristiques durant les cinq prochaines ann\u00e9es. L&rsquo;organisation, qui r\u00e9unit le Mexique, le Salvador, le Honduras, le Guatemala et le Belize, s&rsquo;est par ailleurs f\u00e9licit\u00e9e de son fort attrait touristique et de son nouveau record de visiteurs\u00a0: 25 millions entre 2011 et 2012. Les touristes se sont rendus pour la plupart au Mexique (15 millions de visiteurs), puis au Salvador (1,8 millions), au Guatemala (1,8 millions), au Honduras (1,6 millions) et au Belize (1 million). Napoleon Duarte, pr\u00e9sident de l&rsquo;OMM et Ministre du Tourisme du Salvador, a reconnu que 2012 a largement b\u00e9n\u00e9fici\u00e9 dans la r\u00e9gion du ph\u00e9nom\u00e8ne \u00ab\u00a0fin du monde\u00a0\u00bb ou \u00ab\u00a0fin de l&rsquo;\u00e8re maya\u00a0\u00bb.   <strong>Protection des populations<\/strong>  L&rsquo;OMM compte bien poursuivre sur sa lanc\u00e9e, forte de ses excellents r\u00e9sultats 2011-2012, et d&rsquo;objectifs touristiques largement d\u00e9pass\u00e9s par les cinq pays de l&rsquo;organisation durant ces deux derni\u00e8res ann\u00e9es. Pour continuer \u00e0 attirer des touristes du monde entier, l&rsquo;OMM a r\u00e9cemment sign\u00e9 des accords de collaboration avec plus de 100 universit\u00e9s pour l&rsquo;\u00e9tude du monde maya, et a d\u00e9velopp\u00e9 sa plate-forme technologique. Elle a \u00e9galement entrepris un programme d&rsquo;aide financi\u00e8re et \u00e9ducative aux huit communaut\u00e9s mayas les plus pauvres, et un programme d&rsquo;accompagnement au d\u00e9veloppement des pme mayas. Objectif annonc\u00e9\u00a0: poursuivre la conqu\u00eate touristique et d\u00e9velopper la r\u00e9gion en y impliquant ses habitants.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On annon\u00e7ait sa fin, le \u00ab\u00a0Monde Maya\u00a0\u00bb, compos\u00e9 de cinq pays d&rsquo;Am\u00e9rique Centrale, a battu tous les records de visiteurs en 2011 et 2012. D\u00e9but f\u00e9vrier, et en marge du FITUR, l&rsquo;Organisation du Monde Maya (OMM) a tenu sa r\u00e9union annuelle \u00e0 Madrid pour entreprendre de nouvelles actions touristiques durant les cinq prochaines ann\u00e9es. L&rsquo;organisation, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3826,3685,866,660],"class_list":["post-75033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-3826","tag-maya","tag-mexique","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=75033"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/75033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46481"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=75033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=75033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=75033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}