{"id":74956,"date":"2026-03-23T04:29:16","date_gmt":"2026-03-23T04:29:16","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/hameaux-a-vendre-2\/"},"modified":"2026-08-23T16:37:54","modified_gmt":"2026-08-23T16:37:54","slug":"hameaux-a-vendre-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/hameaux-a-vendre-2\/","title":{"rendered":"Hameaux \u00e0 vendre"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Selon l&rsquo;Institut National de Statistiques, l&rsquo;Espagne compte quelques 3000 hameaux abandonn\u00e9s. <\/strong>  Les derni\u00e8res d\u00e9cennies ont vu les campagnes espagnoles se d\u00e9serter au profit des grandes agglom\u00e9rations. Plus des trois quarts de la population vit d\u00e9sormais en ville et de nombreux hameaux se sont vus abandonn\u00e9s. Certaines agences immobili\u00e8res y ont alors discern\u00e9 une opportunit\u00e9 et se sont mises \u00e0 vendre non plus maison par maison, mais des hameaux entiers voire de petits villages. C&rsquo;est le cas du portail web Aldeas Abandonadas qui regroupe environ 2000 annonces de domaines ruraux et hameaux abandonn\u00e9s. Le site re\u00e7oit entre 300 et 400 demandes d&rsquo;information chaque jour. Plus de 90% des acheteurs sont d&rsquo;origine \u00e9trang\u00e8re. Les opportunit\u00e9s g\u00e9n\u00e9r\u00e9es par la crise immobili\u00e8re incitent beaucoup \u00e0 investir dans ce secteur. Sur le site, on trouve par exemple un hameau de trois maisons pr\u00e8s des plages de la Corogne pour 60.000\u20ac ou encore un ensemble de plus de 150 hectares, situ\u00e9 \u00e0 35 kilom\u00e8tres de Barcelone, pour 1,120 million d&rsquo;euros.  <strong>Opportunit\u00e9s d&rsquo;achat et retour \u00e0 la nature<\/strong>  Les ventes de hameaux ou villages ont augment\u00e9 de 19% depuis 2011. Si la sensation de saisir des opportunit\u00e9s et d&rsquo;investir dans des biens qui prendront de la valeur compte beaucoup dans la d\u00e9cision d&rsquo;achat, elle n&rsquo;en est souvent pas le moteur principal. \u00ab<em>Entre 15 et 20% des acheteurs le voient comme un investissement<\/em>, explique Rafael Canales responsable du site Aldeas Abandonadas, <em>mais beaucoup sont \u00e9galement int\u00e9ress\u00e9s par la tranquillit\u00e9 qu&rsquo;ils peuvent trouver dans ces maisons, par exemple pour vivre \u00e0 la campagne lorsqu&rsquo;ils partent \u00e0 la retraite<\/em>\u00bb. La tendance des familles urbaines \u00e0 d\u00e9laisser la ville, accrue par la possibilit\u00e9 de d\u00e9sormais t\u00e9l\u00e9-travailler depuis n&rsquo;importe quel endroit du monde, est \u00e9galement tr\u00e8s palpable\u00a0: \u00ab <em>Les gens recherchent une bonne qualit\u00e9 de vie<\/em>, explique Rafael Canales,<em> ce n&rsquo;est pas la m\u00eame chose de travailler depuis Madrid que depuis un hameau, et pour moins d&rsquo;argent que ce que vaudrait un appartement dans le centre, on peut s&rsquo;acheter un village entier<\/em>\u00a0\u00bb. Selon l&rsquo;INE, 70% des hameaux abandonn\u00e9s se trouvent en Galice, et nombreuses y sont les propri\u00e9t\u00e9s r\u00e9cemment vendues par le site sp\u00e9cialis\u00e9: \u00ab\u00a0N<em>ous sommes en train de remplir la Galice d&rsquo;\u00e9trangers, des Anglais, des Am\u00e9ricains, des Hollandais, un peu comme ce qu&rsquo;il s&rsquo;est pass\u00e9 avec les Allemandes sur l&rsquo;\u00eele de Majorque<\/em>\u00a0\u00bb conclut l&rsquo;entrepreneur.  (notes: nous avons re\u00e7u de nombreux mails sur ce sujet. Si vous recherchez un hameau en Espagne; ,nous pourrons vous orienter. contactez-nous \u00e0 com.lecourrier@gmail.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon l&rsquo;Institut National de Statistiques, l&rsquo;Espagne compte quelques 3000 hameaux abandonn\u00e9s. Les derni\u00e8res d\u00e9cennies ont vu les campagnes espagnoles se d\u00e9serter au profit des grandes agglom\u00e9rations. Plus des trois quarts de la population vit d\u00e9sormais en ville et de nombreux hameaux se sont vus abandonn\u00e9s. Certaines agences immobili\u00e8res y ont alors discern\u00e9 une opportunit\u00e9 et [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46191,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-74956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74956"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/46191"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}