{"id":74935,"date":"2026-03-23T04:02:45","date_gmt":"2026-03-23T04:02:45","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/huitres-doleron-et-galettes-bretonnes-au-27eme-salon-du-gourmets-de-madrid-2\/"},"modified":"2026-08-23T15:18:01","modified_gmt":"2026-08-23T15:18:01","slug":"huitres-doleron-et-galettes-bretonnes-au-27eme-salon-du-gourmets-de-madrid-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/huitres-doleron-et-galettes-bretonnes-au-27eme-salon-du-gourmets-de-madrid-2\/","title":{"rendered":"Hu\u00eetres d\u2019Ol\u00e9ron et galettes bretonnes au 27\u00e8me Salon du Gourmets de Madrid"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><b><\/b>  <b>La 27<sup>\u00e8me<\/sup> \u00e9dition du Salon de Gourmets se tient du 8 au 11 avril 2013 \u00e0 Madrid, au Parc des expositions. Cette ann\u00e9e encore, des producteurs et entreprises de gastronomie fran\u00e7aises seront pr\u00e9sent\u00e9s.<\/b>  Consid\u00e9r\u00e9 comme le premier salon du secteur de l\u2019alimentation et des boissons d\u2019Europe, le Salon de Gourmets s\u2019installera \u00e0 Madrid en avril prochain pour pr\u00e9senter les merveilles culinaires des professionnels de l\u2019alimentation venus de toute l\u2019Europe.  Une cuisine gastronomique et des boissons hautes de gamme y sont pr\u00e9sent\u00e9es. Cette ann\u00e9e, le Salon du Gourmets r\u00e9unira plus de 1\u00a0100 exposants, et devrait atteindre les 75\u00a0000 visiteurs. Cet \u00e9v\u00e8nement, adress\u00e9 aux professionnels de la gastronomie, pr\u00e9sente plus de 30\u00a0000 produits venus de\u00a0 20 pays europ\u00e9ens.  Parmi les entreprises fran\u00e7aises le foie gras sera \u00e0 l\u2019honneur, mais \u00e9galement les hu\u00eetres de l\u2019\u00eele d\u2019Ol\u00e9ron, ou encore les fameuses galettes de la M\u00e8re Poulard. Le \u00ab\u00a0pavillon France\u00a0\u00bb sera situ\u00e9 entre les halls 4 et 6 du salon.  Ubifrance, le groupe Sorlut, Salaisons Montserret, la biscuiterie La M\u00e8re Poulard, le Boiron Fr\u00e8res, le Ch\u00e2teau Blanc, la Britexa,\u00a0 et Le M\u00e9daillon Corr\u00e9zien viendront pr\u00e9senter leurs mets. https:\/\/www.youtube.com\/watch?v=u1bR0wIsPT4<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 27\u00e8me \u00e9dition du Salon de Gourmets se tient du 8 au 11 avril 2013 \u00e0 Madrid, au Parc des expositions. Cette ann\u00e9e encore, des producteurs et entreprises de gastronomie fran\u00e7aises seront pr\u00e9sent\u00e9s. Consid\u00e9r\u00e9 comme le premier salon du secteur de l\u2019alimentation et des boissons d\u2019Europe, le Salon de Gourmets s\u2019installera \u00e0 Madrid en avril [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":29610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4440],"tags":[678,1279,375,3556],"class_list":["post-74935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-networking","tag-france","tag-gastronomie","tag-madrid","tag-salons-du-gourmets"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74935"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/29610"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}