{"id":74887,"date":"2026-03-23T03:13:14","date_gmt":"2026-03-23T03:13:14","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/lespagne-tres-primee-par-les-conde-nast-traveler-2\/"},"modified":"2026-08-23T12:54:39","modified_gmt":"2026-08-23T12:54:39","slug":"lespagne-tres-primee-par-les-conde-nast-traveler-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/lespagne-tres-primee-par-les-conde-nast-traveler-2\/","title":{"rendered":"L\u2019Espagne, tr\u00e8s prim\u00e9e par les Cond\u00e9 Nast Traveler"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p style=\"text-align: justify\"><b>Cond\u00e9 Nast Traveler a r\u00e9cemment r\u00e9compens\u00e9 les sites touristiques internationaux pour l\u2019ann\u00e9e 2013. Cette ann\u00e9e encore l\u2019Espagne est \u00e0 l\u2019honneur et les \u00eeles Canaries ont gagn\u00e9 le prix de la meilleure \u00eele.<\/b><\/p>\n<p style=\"text-align: justify\">L\u2019Espagne est l\u2019un des spots touristiques phares au niveau europ\u00e9en et son succ\u00e8s ne se d\u00e9ment pas. Cond\u00e9 Nast, grand groupe de communication a organis\u00e9 une remise de prix dans le milieu du tourisme\u00a0: Cond\u00e9 Nast traveler, par le biais de son magazine \u00e9ponyme.<\/p>\n<p style=\"text-align: justify\">L\u2019Andalousie est \u00e0 l\u2019honneur. L\u2019h\u00f4tel Alfonso XIII de S\u00e9ville a \u00e9t\u00e9 r\u00e9compens\u00e9 comme le \u00ab\u00a0<i>meilleur h\u00f4tel national urbain\u00a0<\/i>\u00bb. C\u2019est l\u2019h\u00f4tel La Mamounia de Marrakech qui a remport\u00e9 le prix pour la cat\u00e9gorie internationale. Cadiz a gagn\u00e9 le prix du \u00ab\u00a0meilleur resort\u00a0\u00bb gr\u00e2ce \u00e0 l\u2019Almenara Golf Resort de Sotogrande.<\/p>\n<p style=\"text-align: justify\">Les h\u00f4tels des \u00eeles se sont taill\u00e9 une place de choix dans le classement. Majorque et Tenerife ont \u00e9t\u00e9 r\u00e9compens\u00e9es pour leurs resorts et spas. Quant aux \u00eeles Canaries, elles ont remport\u00e9 le titre de \u00ab\u00a0meilleure \u00eele de l\u2019ann\u00e9e\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify\">Le classement compte \u00e9galement avec la ville de San Sebastian, au pays Basque, comme \u00ab\u00a0meilleure ville nationale\u00a0\u00bb, et avec l\u2019AVE, le train \u00e0 grande vitesse.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cond\u00e9 Nast Traveler a r\u00e9cemment r\u00e9compens\u00e9 les sites touristiques internationaux pour l\u2019ann\u00e9e 2013. Cette ann\u00e9e encore l\u2019Espagne est \u00e0 l\u2019honneur et les \u00eeles Canaries ont gagn\u00e9 le prix de la meilleure \u00eele. L\u2019Espagne est l\u2019un des spots touristiques phares au niveau europ\u00e9en et son succ\u00e8s ne se d\u00e9ment pas. Cond\u00e9 Nast, grand groupe de communication [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[2140,3495,3496,881,628],"class_list":["post-74887","post","type-post","status-publish","format-standard","hentry","category-breaking-news","tag-cadiz","tag-caneries","tag-conde-nast-traveler","tag-san-sebastian","tag-seville"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74887"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74887\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}