{"id":74846,"date":"2026-03-23T02:32:58","date_gmt":"2026-03-23T02:32:58","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/barcelona-world-les-noms-des-premiers-investisseurs-2\/"},"modified":"2026-08-23T10:32:55","modified_gmt":"2026-08-23T10:32:55","slug":"barcelona-world-les-noms-des-premiers-investisseurs-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/barcelona-world-les-noms-des-premiers-investisseurs-2\/","title":{"rendered":"Barcelona World | Les noms des premiers investisseurs"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Aujourd\u2019hui, les noms des investisseurs du Barcelona World ont \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9s par Enrique Ba\u00f1uelos : Lawrence Ho, le fils ain\u00e9 de Stanley Ho, consid\u00e9r\u00e9 comme le magnat du jeu \u00e0 Macao, le groupe hotelier Meli\u00e0 et la soci\u00e9t\u00e9 Value Retail, promoteur des villages \u201coutlet\u201d comme ceux de la La Roca et de Las Rozas.  Hier, suite \u00e0 la la publication de l\u2019article sur l\u2019annonce prochaine des investisseurs du projet,\u00a0nous avons d\u00e9cid\u00e9 de demander l&rsquo;avis des personnes directement concern\u00e9es par le projet : les catalans. \u00a0Le projet ne fait pas l\u2019unanimit\u00e9 !  &nbsp;    &nbsp;  D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, les gens ne comprennent pas pourquoi ce projet vient faire de la concurrence au projet EuroVegas de Madrid. Ils soulignent \u00e9galement le c\u00f4t\u00e9 non-\u00e9cologique du projet.  &nbsp;    &nbsp;  Au del\u00e0 du projet Barcelona World, c&rsquo;est le syst\u00e8me \u00e9conomique espagnol qui est remis en cause, pour R\u00e9mi il faut arr\u00eater de s&rsquo;appuyer uniquement sur le tourisme et au contraire d\u00e9velopper l&rsquo;industrie, l&rsquo;agriculture et l&rsquo;exportation. Il ajoute\u00a0\u00ab\u00a0Moi \u00e7a me fait mal d&rsquo;acheter des oranges du Chili parce qu\u00b4elles sont moins ch\u00e8res que celle de Valencia\u00a0\u00bb  N\u00e9anmoins, il y a aussi certaines personnes qui voient le projet d&rsquo;un bon oeil, le consid\u00e9rant comme un moteur pour l&rsquo;\u00e9conomie et et l&#8217;emploi : \u00ab\u00a0Je pense que c&rsquo;est un excellent projet qui va cr\u00e9er des emplois et relancer l&rsquo;economie\u00a0\u00bb  Venez poursuivre le d\u00e9bat sur <a href=\"https:\/\/www.facebook.com\/pages\/Le-Courrier-dEspagne\/140225787872\">Facebook<\/a> et <a href=\"https:\/\/mobile.twitter.com\/lecourrierES\">Twitter<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, les noms des investisseurs du Barcelona World ont \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9s par Enrique Ba\u00f1uelos : Lawrence Ho, le fils ain\u00e9 de Stanley Ho, consid\u00e9r\u00e9 comme le magnat du jeu \u00e0 Macao, le groupe hotelier Meli\u00e0 et la soci\u00e9t\u00e9 Value Retail, promoteur des villages \u201coutlet\u201d comme ceux de la La Roca et de Las Rozas. Hier, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3446,2210,375],"class_list":["post-74846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-barcelona-world","tag-investisseurs","tag-madrid"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74846"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45829"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}