{"id":74816,"date":"2026-03-23T01:57:31","date_gmt":"2026-03-23T01:57:31","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/privatisation-des-hopitaux-madrilenes-seules-trois-entreprises-en-concurrence-2\/"},"modified":"2026-08-23T08:56:49","modified_gmt":"2026-08-23T08:56:49","slug":"privatisation-des-hopitaux-madrilenes-seules-trois-entreprises-en-concurrence-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/privatisation-des-hopitaux-madrilenes-seules-trois-entreprises-en-concurrence-2\/","title":{"rendered":"Privatisation des h\u00f4pitaux madril\u00e8nes : seules trois entreprises en concurrence"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><i><\/i>  Madrid a d\u00e9cid\u00e9 de privatiser six de ses h\u00f4pitaux et vingt-sept \u00e9tablissements de soin publics afin d\u2019obtenir 20% d\u2019\u00e9conomies sur son budget\u00a0: Vallecas, San Sebastian de los Reyes, Parla, Arganda, Coslada et Aranjuez.  Selon la revue <i><span style=\"text-decoration: underline\">elEconomista Sanidad<\/span><\/i>, seules trois entreprises, IDCSalud (ex Capio), Ribera Salud et Sanitas, pr\u00e9senteront une offre de transfert. Capio d\u00e9tient une place de choix sur le march\u00e9 de la sant\u00e9 et dispose d\u2019une soixantaine d\u2019\u00e9tablissements \u00e0 travers l\u2019Europe dont quatre h\u00f4pitaux publics de Madrid (Fundaci\u00f3n Jim\u00e9nez D\u00edaz, Infanta Elena de Valdemoro, Rey Juan Carlos de Mostoles\u00a0et Collado Villalba) et l\u2019h\u00f4pital g\u00e9n\u00e9ral de Catalogne. Le fonds de placement semble \u00eatre le mieux positionn\u00e9, 77 millions d\u2019euros du secteur public et 27,8 du priv\u00e9 sont rentr\u00e9 dans ses caisses au cours du premier semestre 2011. Ribera Salud g\u00e8re cinq h\u00f4pitaux et cent centres de sant\u00e9 et Sanitas a r\u00e9cemment r\u00e9cup\u00e9r\u00e9 50% de la gestion de l\u2019h\u00f4pital de Torrejon. On ignore encore si l&rsquo;offre des trois puissances du secteur couvrira les six h\u00f4pitaux ou si des h\u00f4pitaux ne recevront pas d&rsquo;offre \u00e0 cause des risques \u00e9conomiques \u00e9lev\u00e9s que la transaction repr\u00e9sente.  Une attractivit\u00e9 en berne en effet, depuis que le Minist\u00e8re de la Sant\u00e9 a exig\u00e9 que les entreprises assument l\u2019ensemble du personnel, ce qui repr\u00e9sente environ 5 200 professionnels de la sant\u00e9.  N\u00e9anmoins, la Communaut\u00e9 de Madrid a choisi de laisser les entreprises sanitaires fixer leur limite de b\u00e9n\u00e9fice annuel, \u00e0 l\u2019instar de la Communaut\u00e9 de Valence o\u00f9 le rapport est born\u00e9 \u00e0 7,5% du taux interne de rentabilit\u00e9 annuelle.  Pourtant, les pertes de gestion semblent in\u00e9vitables et sont estim\u00e9es entre 20 et 30 millions d\u2019euros pour chaque bilan. \u00ab\u00a0Ce volume de pertes est quelque chose que beaucoup d&rsquo;entreprises ne peuvent pas assumer ou, au moins, ne veulent pas faire courir le risque que cela suppose\u00a0\u00bb, selon <i><span style=\"text-decoration: underline\">elEconomista Sanidad<\/span><\/i>. D\u2019autant plus que les premiers r\u00e9sultats positifs ne sont pr\u00e9vus qu\u2019\u00e0 partir de la cinqui\u00e8me ann\u00e9e, et la marge de rentabilit\u00e9 de l\u2019investissement peu convaincante.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid a d\u00e9cid\u00e9 de privatiser six de ses h\u00f4pitaux et vingt-sept \u00e9tablissements de soin publics afin d\u2019obtenir 20% d\u2019\u00e9conomies sur son budget\u00a0: Vallecas, San Sebastian de los Reyes, Parla, Arganda, Coslada et Aranjuez. Selon la revue elEconomista Sanidad, seules trois entreprises, IDCSalud (ex Capio), Ribera Salud et Sanitas, pr\u00e9senteront une offre de transfert. Capio d\u00e9tient [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3413,2074,375,3414,3415,1073],"class_list":["post-74816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-capio","tag-hopitaux","tag-madrid","tag-ribera-salud","tag-sanitas","tag-sante"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74816"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45711"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}