{"id":74809,"date":"2026-03-23T01:53:26","date_gmt":"2026-03-23T01:53:26","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/le-costa-rica-sexporte-en-chine-2\/"},"modified":"2026-08-23T08:25:49","modified_gmt":"2026-08-23T08:25:49","slug":"le-costa-rica-sexporte-en-chine-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/le-costa-rica-sexporte-en-chine-2\/","title":{"rendered":"Le Costa-Rica s\u2019exporte en Chine"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><em>Il y a quelques jours, le pr\u00e9sident chinois Xi Jinping, visitait le Costa-Rica. Selon le journal La Rep\u00fablica, sa visite fut l\u2019occasion de signer diff\u00e9rents accords avec le pays qui ouvriront les portes aux exportations nationales<\/em>.    Dans la liste des diff\u00e9rents accords, on trouve l\u2019autorisation de pr\u00eat pour financer la nouvelle Route 32, ainsi qu\u2019un cr\u00e9dit pour r\u00e9nover les transports. Les deux pays se sont \u00e9galement trouv\u00e9 un point d\u2019entente concernant le protocole sanitaire pour l\u2019exportation de viande de porc. Pour que leurs produits soient commercialis\u00e9s en Chine, les exportateurs du Costa-Rica devront suivre ce r\u00e8glement.  Suite \u00e0 ce rapprochement, l\u2019entreprise Dos Pinos a d\u00e9cid\u00e9 de miser sur le march\u00e9 chinois, elle a en effet annonc\u00e9 qu\u2019elle exporterait ses produits laitiers vers le pays asiatique. Et ce \u00e0 un travers un accord avec SDIC International, antenne commerciale de State Development et Investment Corporation, le plus gros holding d\u2019entreprise de Chine. Les premi\u00e8res exportations de produits laitiers devraient se r\u00e9aliser au cours des prochaines semaines.  Cependant dans la liste des accords sign\u00e9s, ne figurait pas la construction de la nouvelle raffinerie de p\u00e9trole.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a quelques jours, le pr\u00e9sident chinois Xi Jinping, visitait le Costa-Rica. Selon le journal La Rep\u00fablica, sa visite fut l\u2019occasion de signer diff\u00e9rents accords avec le pays qui ouvriront les portes aux exportations nationales. Dans la liste des diff\u00e9rents accords, on trouve l\u2019autorisation de pr\u00eat pour financer la nouvelle Route 32, ainsi qu\u2019un [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1590,1196,3406],"class_list":["post-74809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-chine","tag-costa-rica","tag-xi-jinping"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74809"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45685"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}