{"id":74800,"date":"2026-03-23T01:42:54","date_gmt":"2026-03-23T01:42:54","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/la-troika-pourrait-prolonger-son-plan-daide-aux-banques-espagnoles-2\/"},"modified":"2026-08-23T07:54:26","modified_gmt":"2026-08-23T07:54:26","slug":"la-troika-pourrait-prolonger-son-plan-daide-aux-banques-espagnoles-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/la-troika-pourrait-prolonger-son-plan-daide-aux-banques-espagnoles-2\/","title":{"rendered":"La tro\u00efka pourrait prolonger son plan d\u2019aide aux banques espagnoles"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Cens\u00e9 expirer au 31 d\u00e9cembre 2013, le programme d\u2019aide financi\u00e8re mis en place par la tro\u00efka (FMI, BCE, UE) l\u2019ann\u00e9e derni\u00e8re pour aider \u00e0 la restructuration du syst\u00e8me bancaire espagnol pourrait \u00eatre prolong\u00e9 si besoin est, annon\u00e7ait <em>El Pa\u00eds <\/em>lundi 10 juin<em>. <\/em><i>\u00a0<\/i>   Mariano Rajoy et Mario Draghi  Malgr\u00e9 une restructuration bancaire en bonne voie, les march\u00e9s restent inquiets quant \u00e0 l\u2019\u00e9tat du syst\u00e8me espagnol. Aussi, si la prochaine \u00e9valuation europ\u00e9enne (pr\u00e9vue pour le printemps 2014) venait \u00e0 souligner le besoin de fonds, cette possibilit\u00e9 serait un moyen de venir rassurer les march\u00e9s.  Pour le moment, l\u2019Espagne n\u2019a demand\u00e9 que 41 milliards d\u2019euros sur les 100 accord\u00e9s et le quotidien estime que le gouvernement n\u2019a aucun int\u00e9r\u00eat \u00e0 tirer plus sur la corde. L\u2019\u00e9ventuelle rallonge offerte par les institutions pourrait \u00eatre accept\u00e9e seulement sous certaines conditions. Tout d\u2019abord, l\u2019impact positif d\u2019une telle solution doit contrebalancer nettement la stigmatisation politique qui y est associ\u00e9e, faute de quoi l&rsquo;effet escompt\u00e9 ne serait pas atteint. Ensuite, les partenaires de l\u2019Espagne ne doivent pas imposer des contreparties trop contraignantes, ce qui plomberait d&rsquo;autant plus le moral des financiers qui doivent d\u00e9j\u00e0 faire face \u00e0 une hausse de leurs provisions (r\u00e9serves de fonds anticipant les pertes attendues) exig\u00e9e par la Banque d&rsquo;Espagne.  Par ailleurs, il convient de rappeler que le gouvernement se pla\u00eet \u00e0 rappeler fr\u00e9quemment que si les institutions bancaires venaient \u00e0 manquer de fonds, le FROB (fonds pour la restructuration bancaire<b> <\/b>ordonn\u00e9e) comme le Tr\u00e9sor espagnol pourraient y palier.  Ainsi, le recours \u00e0 une rallonge de la tro\u00efka ne semble pas \u00eatre au programme des autorit\u00e9s espagnoles.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cens\u00e9 expirer au 31 d\u00e9cembre 2013, le programme d\u2019aide financi\u00e8re mis en place par la tro\u00efka (FMI, BCE, UE) l\u2019ann\u00e9e derni\u00e8re pour aider \u00e0 la restructuration du syst\u00e8me bancaire espagnol pourrait \u00eatre prolong\u00e9 si besoin est, annon\u00e7ait El Pa\u00eds lundi 10 juin. \u00a0 Mariano Rajoy et Mario Draghi Malgr\u00e9 une restructuration bancaire en bonne voie, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3388,3106,3389,3390,3391],"class_list":["post-74800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-bce","tag-fmi","tag-frob","tag-systeme-bancaire-espagnol","tag-troika"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74800"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45645"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}