{"id":74756,"date":"2026-03-23T00:53:33","date_gmt":"2026-03-23T00:53:33","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/le-gouvernement-detaille-sa-reforme-des-administrations-publiques-2\/"},"modified":"2026-08-23T05:33:54","modified_gmt":"2026-08-23T05:33:54","slug":"le-gouvernement-detaille-sa-reforme-des-administrations-publiques-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/le-gouvernement-detaille-sa-reforme-des-administrations-publiques-2\/","title":{"rendered":"Le gouvernement d\u00e9taille sa r\u00e9forme des administrations publiques"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><b>La semaine derni\u00e8re, le pr\u00e9sident du gouvernement Mariano Rajoy a pr\u00e9sent\u00e9 les conclusions tir\u00e9es du rapport de la CORA, la Commission de R\u00e9forme des Administrations Publiques. <\/b>  &nbsp;    &nbsp;  Ce projet de rationalisation de l\u2019administration s\u2019inscrit dans le plan d\u2019aust\u00e9rit\u00e9 impos\u00e9 \u00e0 l\u2019Espagne dans tous les secteurs. Le gouvernement esp\u00e8re ainsi une \u00e9conomie de 37,7 milliards d\u2019euros.  La vice-pr\u00e9sidente Soraya Saenz de Santamaria a declar\u00e9 que l\u2019objectif de cette r\u00e9forme \u00e9tait de disposer d\u2019une administration beaucoup plus efficace, qu\u2019elle soit actuelle, moderne, ancr\u00e9e dans le XXI\u00e8me si\u00e8cle et agisse comme un tremplin pour sortir de la crise \u00e9conomique.  Le rapport de la Commission comportait 217 mesures dont le gouvernement s\u2019est largement inspir\u00e9 pour \u00e9laborer sa r\u00e9forme. On peut notamment \u00e9voquer la distinction de statut au sein du personnel entre fonctionnaires et employ\u00e9s. Par ailleurs, le rapport pr\u00e9voit une mobilit\u00e9 interne plus importante entre les diff\u00e9rentes administrations afin de s\u2019adapter \u00e0 leurs besoins en termes d\u2019effectifs.  Cette mesure rend d\u00e9sormais possible le d\u00e9placement temporaire des fonctionnaires dans d\u2019autres administrations, voire d\u2019autres communaut\u00e9s autonomes en fonction des n\u00e9cessit\u00e9s et des demandes de celles-ci.  Malgr\u00e9 les objectifs affich\u00e9s\u00a0par le gouvernement (renforcer la discipline budg\u00e9taire et la transparence publique, rationaliser le secteur public, am\u00e9liorer\u00a0l\u2019efficacit\u00e9 de l\u2019administration\u2026), cette r\u00e9forme est vue comme un nouveau coup port\u00e9 \u00e0 la s\u00e9curit\u00e9 de l\u2019emploi et aux acquis sociaux des fonctionnaires qui deviennent chaque jour un peu plus des travailleurs interchangeables.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La semaine derni\u00e8re, le pr\u00e9sident du gouvernement Mariano Rajoy a pr\u00e9sent\u00e9 les conclusions tir\u00e9es du rapport de la CORA, la Commission de R\u00e9forme des Administrations Publiques. &nbsp; &nbsp; Ce projet de rationalisation de l\u2019administration s\u2019inscrit dans le plan d\u2019aust\u00e9rit\u00e9 impos\u00e9 \u00e0 l\u2019Espagne dans tous les secteurs. Le gouvernement esp\u00e8re ainsi une \u00e9conomie de 37,7 milliards [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3271,2957,3274],"class_list":["post-74756","post","type-post","status-publish","format-standard","hentry","category-breaking-news","tag-austerite","tag-mariano-rajoy","tag-reforme-des-administrations-publiques"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74756"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74756\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}