{"id":74750,"date":"2026-03-23T00:48:19","date_gmt":"2026-03-23T00:48:19","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/prisa-aux-prises-avec-la-cession-de-canal-2\/"},"modified":"2026-08-23T05:17:52","modified_gmt":"2026-08-23T05:17:52","slug":"prisa-aux-prises-avec-la-cession-de-canal-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/prisa-aux-prises-avec-la-cession-de-canal-2\/","title":{"rendered":"Prisa aux prises avec la cession de Canal+"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le groupe espagnol de presse Prisa aurait re\u00e7u une offre de NewsCorporation entre 180 et 200 millions d\u2019euros pour les 56% de Canal+ Espagne, que le groupe esp\u00e8re c\u00e9der \u00e0 1 milliard, selon les sources d\u2019El Economista.    L\u2019int\u00e9r\u00eat du magnat des m\u00e9dias, Rupert Murdoch, pour la chaine a \u00e9t\u00e9 \u00e9voqu\u00e9 pour la premi\u00e8re fois il y a quelques semaines. Saisir Canal+ Espagne repr\u00e9sente pour l\u2019Australien l\u2019occasion de se faire une place sur le march\u00e9 de la t\u00e9l\u00e9vision payante en Espagne et de s\u2019installer sur le march\u00e9 du football notamment, lui qui d\u00e9tient les droits de plusieurs grands championnats.  Dans une situation financi\u00e8re d\u00e9licate le groupe espagnol se voit dans l\u2019obligation de c\u00e9der la chaine payante si elle veut survivre. Face aux difficult\u00e9s rencontr\u00e9es dans cette cession, Prisa a renforc\u00e9 ses contacts avec les acheteurs potentiels que sont BSkyB, News Corporation et Telefonica, sans succ\u00e8s jusqu\u2019\u00e0 maintenant. Parall\u00e8lement un plan de r\u00e9organisation visant \u00e0 r\u00e9duire les co\u00fbts de travail du personnel de 10%, avec notamment 8 licenciements chez Canal+, a \u00e9t\u00e9 engag\u00e9.  Pour le moment, il semblerait qu\u2019aucune op\u00e9ration ne soit tent\u00e9e avant la fin de l\u2019\u00e9t\u00e9, pour que passe la traditionnelle guerre du football entre Mediapro et Prisa.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe espagnol de presse Prisa aurait re\u00e7u une offre de NewsCorporation entre 180 et 200 millions d\u2019euros pour les 56% de Canal+ Espagne, que le groupe esp\u00e8re c\u00e9der \u00e0 1 milliard, selon les sources d\u2019El Economista. L\u2019int\u00e9r\u00eat du magnat des m\u00e9dias, Rupert Murdoch, pour la chaine a \u00e9t\u00e9 \u00e9voqu\u00e9 pour la premi\u00e8re fois il [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45457,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3311,3312,3313,3314],"class_list":["post-74750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-canal-espagne","tag-cession","tag-murdoch","tag-prisa"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74750"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45457"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}