{"id":74699,"date":"2026-03-23T00:03:08","date_gmt":"2026-03-23T00:03:08","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/hotusa-ouvre-lhotel-eurostars-plaza-mayor-au-coeur-de-la-capitale-2\/"},"modified":"2026-08-23T02:38:30","modified_gmt":"2026-08-23T02:38:30","slug":"hotusa-ouvre-lhotel-eurostars-plaza-mayor-au-coeur-de-la-capitale-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/23\/hotusa-ouvre-lhotel-eurostars-plaza-mayor-au-coeur-de-la-capitale-2\/","title":{"rendered":"Hotusa ouvre l\u2019h\u00f4tel Eurostars Plaza Mayor au coeur de la capitale"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><i>  Le groupe Hotusa a ouvert un nouvel \u00e9tablissement, le premier dans le centre de Madrid.<\/i>  Le Groupe Hotusa a inaugur\u00e9 un nouvel h\u00f4tel quatre \u00e9toiles au coeur de Madrid le 5 juillet. L&rsquo;h\u00f4tel Eurostars Plaza Mayor se compose de l&rsquo;ensemble de deux \u00e9difices et de 92 chambres doubles con\u00e7u dans une \u00ab\u00a0architecture singuli\u00e8re et une situation privil\u00e9gi\u00e9e\u00a0\u00bb. Situ\u00e9 en plein centre, l\u2019\u00e9tablissement est situ\u00e9 \u00e0 150 m\u00e8tres de la station de m\u00e9tro Tirso de Molina, et \u00e0 300 m\u00e8tres de la Plaza Mayor comme de la Puerta del Sol. L\u2019h\u00f4tel se trouve \u00e9galement \u00e0 quelques minutes des atouts touristiques de la capitale.  Avec l&rsquo;ouverture de ce nouvel h\u00f4tel, Eurostars Hotels dispose de 70 \u00e9tablissements de luxe dont six dans la communaut\u00e9 de Madrid.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe Hotusa a ouvert un nouvel \u00e9tablissement, le premier dans le centre de Madrid. Le Groupe Hotusa a inaugur\u00e9 un nouvel h\u00f4tel quatre \u00e9toiles au coeur de Madrid le 5 juillet. L&rsquo;h\u00f4tel Eurostars Plaza Mayor se compose de l&rsquo;ensemble de deux \u00e9difices et de 92 chambres doubles con\u00e7u dans une \u00ab\u00a0architecture singuli\u00e8re et une [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3255,3175],"class_list":["post-74699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hotel-eurostars-plaza-mayor","tag-hotusa"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74699"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45291"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}