{"id":74682,"date":"2026-03-22T23:42:26","date_gmt":"2026-03-22T23:42:26","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/hyatt-entre-au-capital-du-groupe-barcelo-2\/"},"modified":"2026-08-23T01:36:06","modified_gmt":"2026-08-23T01:36:06","slug":"hyatt-entre-au-capital-du-groupe-barcelo-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/hyatt-entre-au-capital-du-groupe-barcelo-2\/","title":{"rendered":"Hyatt entre au capital du groupe Barcel\u00f3"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>76 millions d\u2019euros, c\u2019est la somme engag\u00e9e par Hyatt pour acqu\u00e9rir 20% du capital de Playa Hotels &amp; Resorts, un fonds h\u00f4telier propri\u00e9t\u00e9 du groupe Barcel\u00f3.<\/strong>    Cette acquisition repr\u00e9sente 2800 chambres suppl\u00e9mentaires pour la cha\u00eene h\u00f4teli\u00e8re Hyatt qui esp\u00e8re conclure l\u2019affaire d\u2019ici \u00e0 la fin de l\u2019ann\u00e9e 2013. Elle est actuellement dans l\u2019attente de l\u2019accord des autorit\u00e9s mexicaines o\u00f9 s\u2019op\u00e8re la plus importante transaction.  En 2014 et 2015 Hyatt devrait acqu\u00e9rir d\u2019autres parts d\u2019h\u00f4tels en R\u00e9publique Dominicaine et en Jama\u00efque notamment.  En \u00e9change de cette participation, le fonds Playa Hotels &amp; Resorts s\u2019engage \u00e0 promouvoir de nouvelles formules \u00ab\u00a0tout inclus\u00a0\u00bb dans cinq pays d\u2019Am\u00e9rique Latine et des Cara\u00efbes en gardant \u00e0 Hyatt une place de choix dans l\u2019op\u00e9ration.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>76 millions d\u2019euros, c\u2019est la somme engag\u00e9e par Hyatt pour acqu\u00e9rir 20% du capital de Playa Hotels &amp; Resorts, un fonds h\u00f4telier propri\u00e9t\u00e9 du groupe Barcel\u00f3. Cette acquisition repr\u00e9sente 2800 chambres suppl\u00e9mentaires pour la cha\u00eene h\u00f4teli\u00e8re Hyatt qui esp\u00e8re conclure l\u2019affaire d\u2019ici \u00e0 la fin de l\u2019ann\u00e9e 2013. Elle est actuellement dans l\u2019attente de l\u2019accord [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45227,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3237,798,703],"class_list":["post-74682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-fonds-hotelier","tag-groupe-barcelo","tag-hyatt"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74682"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45227"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}