{"id":74673,"date":"2026-03-22T23:33:09","date_gmt":"2026-03-22T23:33:09","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-restaurant-etoile-can-fabes-la-derniere-victime-de-la-crise-economique-2\/"},"modified":"2026-08-23T01:19:48","modified_gmt":"2026-08-23T01:19:48","slug":"le-restaurant-etoile-can-fabes-la-derniere-victime-de-la-crise-economique-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-restaurant-etoile-can-fabes-la-derniere-victime-de-la-crise-economique-2\/","title":{"rendered":"Le Restaurant \u00e9toil\u00e9 Can Fabes: \u00ab\u00a0La derni\u00e8re victime de la crise \u00e9conomique\u00a0\u00bb"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&nbsp;   Fa\u00e7ade du restaurant Can Fabes \u00e0 Sant Celoni, \u00e0 Barcelone  C.R.I.S.E. Ce mot de cinq lettres ne s&rsquo;accorde pas seulement avec l&rsquo;\u00e9conomie ou les finances. Elle serait responsable de la fermeture d&rsquo;un grand restaurant \u00e9toil\u00e9, le Can Fabes, \u00e0 Sant Celoni, \u00e0 50km de Barcelone.  \u00ab\u00a0Nous avons d\u00e9cid\u00e9 de mettre fin \u00e0 un des chapitres les plus glorieux de la cuisine catalane et espagnole\u00a0\u00bb, a annonc\u00e9 la famille Santamaria-Serra, propri\u00e9taire du local \u00a0dans un communiqu\u00e9 de presse. L&rsquo;\u00e9tablissement mettra la cl\u00e9 sous la porte avant la fin du mois d&rsquo;ao\u00fbt.  Le restaurant avait connu sur r\u00e9organisation de son \u00e9quipe apr\u00e8s la mort \u00e0 Singapour de Santi Santamaria en fevrier 2011. Sa fille, Regina Santamaria reprend le restaurant avec le chef Xavier Pellice. Ce dernier quitta son poste en d\u00e9but 2013.  Le restaurant avait ouvert ses portes il y a 32 ans et a \u00e9t\u00e9 r\u00e9compens\u00e9 par trois \u00e9toiles au guide Michelin. Il perdit une \u00e9toile en novembre 2011.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fa\u00e7ade du restaurant Can Fabes \u00e0 Sant Celoni, \u00e0 Barcelone C.R.I.S.E. Ce mot de cinq lettres ne s&rsquo;accorde pas seulement avec l&rsquo;\u00e9conomie ou les finances. Elle serait responsable de la fermeture d&rsquo;un grand restaurant \u00e9toil\u00e9, le Can Fabes, \u00e0 Sant Celoni, \u00e0 50km de Barcelone. \u00ab\u00a0Nous avons d\u00e9cid\u00e9 de mettre fin \u00e0 un des [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45197,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4440],"tags":[],"class_list":["post-74673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74673"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45197"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}