{"id":74670,"date":"2026-03-22T23:27:48","date_gmt":"2026-03-22T23:27:48","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/les-caves-espagnoles-inspectees-par-la-chine-2\/"},"modified":"2026-08-23T01:03:51","modified_gmt":"2026-08-23T01:03:51","slug":"les-caves-espagnoles-inspectees-par-la-chine-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/les-caves-espagnoles-inspectees-par-la-chine-2\/","title":{"rendered":"Les caves espagnoles inspect\u00e9es par la Chine"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><i><\/i>  La Chine a ouvert une enqu\u00eate sur les vins europ\u00e9ens \u00e0 travers une vaste<i> proc\u00e9dure antidumping et antisubventions, les caves espagnoles ne seront pas \u00e9pargn\u00e9es.<\/i>  Face au rel\u00e8vement des droits de douanes europ\u00e9ens concernant l\u2019importation de ses panneaux solaires, la Chine contre-attaque. En effet, le pays lance une enqu\u00eate sur les exportations de vins europ\u00e9ens. En 2012, 11,4% des exportations de vins de l\u2019UE \u00e9taient en direction de la Chine, repr\u00e9sentant 763 millions d\u2019euros. Apr\u00e8s la France (140 millions de litres de vin vendus, soit 546 millions d\u2019euros), l\u2019Espagne est l\u2019un des premiers acteurs europ\u00e9ens touch\u00e9 (89 millions d\u2019euros).  Les caves \u00e0 vin espagnoles semblent \u00eatre les victimes collat\u00e9rales d\u2019un conflit entre la Chine et l\u2019Union Europ\u00e9enne. En effet, la France se refuse \u00e0 importer des panneaux solaires chinois. En r\u00e9plique \u00e0 cet affront, la Chine a d\u00e9cid\u00e9 de boycotter le march\u00e9 du vin, un march\u00e9 pourtant en grande partie accapar\u00e9 par les caves fran\u00e7aises. Mais cet affront affecte \u00e9galement les autres acteurs du march\u00e9 du vin, notamment l\u2019Espagne.  L\u2019antidumping consiste en une s\u00e9rie de mesures commerciales impos\u00e9es par un pays (ici l\u2019UE) aux exportateurs \u00e9trangers (la Chine) en raison du fait qu\u2019ils pratiquent des prix inf\u00e9rieurs pour les produits export\u00e9s aux co\u00fbts de production des entreprises du pays pour l\u2019importation. L&rsquo;Association chinoise de l&rsquo;industrie des boissons alcoolis\u00e9e a ainsi accus\u00e9 les exportateurs europ\u00e9ens de vendre leurs produits 21,5 % moins chers que dans leur pays d&rsquo;origine (vente \u00e0 perte) et de recevoir des subventions ill\u00e9gales.  Le Gouvernement chinois a d\u00e9velopp\u00e9 un m\u00e9canisme pour que les entreprises se portent volontairement \u00e0 une inspection dite \u00ab\u00a0recherche antidumping\u00a0\u00bb et puissent d\u00e9montrer qu\u2019elles ne concurrencent pas \u00e0 outrance les tarifs chinois. Seront concern\u00e9es les boissons suivantes\u00a0: vins p\u00e9tillants et vins de raisin dont la fermentation a \u00e9t\u00e9 emp\u00each\u00e9e par l\u2019ajout d\u2019alcool. Face aux 1200 firmes fran\u00e7aises, pr\u00e8s de 300 entreprises espagnoles se seraient pr\u00e9sent\u00e9es d\u00e9lib\u00e9r\u00e9ment jusqu\u2019au 21juillet, date limite pour l\u2019enregistrement. Parmi elles, entre 6 et 12 entreprises pourraient \u00eatre s\u00e9lectionn\u00e9es, dont deux voire trois pourraient \u00eatre des caves espagnoles. Le co\u00fbt de l\u2019inspection pourrait monter \u00e0 200 000 euros.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chine a ouvert une enqu\u00eate sur les vins europ\u00e9ens \u00e0 travers une vaste proc\u00e9dure antidumping et antisubventions, les caves espagnoles ne seront pas \u00e9pargn\u00e9es. Face au rel\u00e8vement des droits de douanes europ\u00e9ens concernant l\u2019importation de ses panneaux solaires, la Chine contre-attaque. En effet, le pays lance une enqu\u00eate sur les exportations de vins europ\u00e9ens. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1590,1281],"class_list":["post-74670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-chine","tag-vin-espagnol"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74670"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45187"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}