{"id":74662,"date":"2026-03-22T23:22:36","date_gmt":"2026-03-22T23:22:36","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-touriste-nordique-commence-a-voir-les-canaries-comme-une-destination-estivale-2\/"},"modified":"2026-08-23T00:32:27","modified_gmt":"2026-08-23T00:32:27","slug":"le-touriste-nordique-commence-a-voir-les-canaries-comme-une-destination-estivale-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-touriste-nordique-commence-a-voir-les-canaries-comme-une-destination-estivale-2\/","title":{"rendered":"\u00abLe touriste nordique commence \u00e0 voir les Canaries comme une destination estivale\u00bb"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">133.000 touristes des pays nordiques en plus cette ann\u00e9e aux Canaries. L&rsquo;autorit\u00e9 des Canaries en charge du tourisme chiffre une augmentation de 50% de places vendues sur les avions partant de la Norv\u00e8ge. 60% depuis la Finlande et 65% au d\u00e9part de la Su\u00e8de.   Plage des Anglais aux Canaries o\u00f9 affluent de nombreux touristes en cette p\u00e9riode estivale  Le vice-conseiller espagnol du tourisme du gouvernement des Canaries, Ricardo de la Puente, se f\u00e9licite de ce changement de mentalit\u00e9 chez les visiteurs venus des pays scandinaves. \u00ab\u00a0Le touriste nordique commence \u00e0 voir les Canaries comme une destination estivale.\u00a0\u00bb  Sur cette derni\u00e8re p\u00e9riode, l&rsquo;Espagne a vu \u00e0 la hausse le nombre de visiteurs. Les experts attribuent cette hausse \u00e0 la crise des pays m\u00e9diterran\u00e9ens.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>133.000 touristes des pays nordiques en plus cette ann\u00e9e aux Canaries. L&rsquo;autorit\u00e9 des Canaries en charge du tourisme chiffre une augmentation de 50% de places vendues sur les avions partant de la Norv\u00e8ge. 60% depuis la Finlande et 65% au d\u00e9part de la Su\u00e8de. Plage des Anglais aux Canaries o\u00f9 affluent de nombreux touristes en [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45155,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-74662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74662"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45155"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}