{"id":74642,"date":"2026-03-22T22:57:48","date_gmt":"2026-03-22T22:57:48","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/perou-augmentation-de-la-production-de-mangues-de-46-2\/"},"modified":"2026-08-22T23:28:47","modified_gmt":"2026-08-22T23:28:47","slug":"perou-augmentation-de-la-production-de-mangues-de-46-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/perou-augmentation-de-la-production-de-mangues-de-46-2\/","title":{"rendered":"P\u00e9rou : augmentation de la production de mangues de 46%"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La production de mangues a atteint 105 000 tonnes au cours de l\u2019ann\u00e9e 2012-2013, ce qui repr\u00e9sente un d\u00e9veloppement de 46 %.  \u00ab\u00a0La production de mangues ne cro\u00eet pas constamment mais a des variations. La mangue est un fruit saisonnier et d\u00e9pend chaque ann\u00e9e du climat. S&rsquo;il est favorable il y aura une production, dans le cas contraire, il n&rsquo;y aura pas de si bonne production\u00a0\u00bb, a remarqu\u00e9 le g\u00e9rant g\u00e9n\u00e9ral de l&rsquo;APEM (Association p\u00e9ruvienne des exportateurs de mangues), Juan Charles Rivera.  La surface cultiv\u00e9e de mangues d\u00e9di\u00e9es \u00e0 l\u2019exportation est de 22 500 hectares.  La r\u00e9gion Piura repr\u00e9sente 74 % de la production nationale de mangues d\u00e9di\u00e9e \u00e0 l\u2019exportation, suivie par Lambayeque (18 %) et Ancash (8 %).  Enfin, les march\u00e9s principaux concernant l\u2019exportation des mangues p\u00e9ruviennes sont les \u00c9tats-Unis (39 %), le Canada (5 %), la Hollande (37 %) et le Royaume-Uni (10 %).<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La production de mangues a atteint 105 000 tonnes au cours de l\u2019ann\u00e9e 2012-2013, ce qui repr\u00e9sente un d\u00e9veloppement de 46 %. \u00ab\u00a0La production de mangues ne cro\u00eet pas constamment mais a des variations. La mangue est un fruit saisonnier et d\u00e9pend chaque ann\u00e9e du climat. S&rsquo;il est favorable il y aura une production, dans [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":45072,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[871,3192,3193],"class_list":["post-74642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-amerique-latine","tag-mangues","tag-perou"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74642"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/45072"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}