{"id":74621,"date":"2026-03-22T22:31:34","date_gmt":"2026-03-22T22:31:34","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/la-chine-autorise-les-citoyens-damerique-latine-a-effectuer-de-courts-sejours-sans-visa-2\/"},"modified":"2026-08-22T22:08:48","modified_gmt":"2026-08-22T22:08:48","slug":"la-chine-autorise-les-citoyens-damerique-latine-a-effectuer-de-courts-sejours-sans-visa-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/la-chine-autorise-les-citoyens-damerique-latine-a-effectuer-de-courts-sejours-sans-visa-2\/","title":{"rendered":"La Chine autorise les citoyens d&rsquo;Am\u00e9rique Latine \u00e0 effectuer de courts s\u00e9jours sans visa"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><span style=\"color: #000000\"><span style=\"font-family: &#039;Times New Roman&#039;, serif\"><span style=\"font-size: medium\">Ma Yilang, membre de l&rsquo;Acad\u00e9mie de tourisme de Chine, propose aux touristes de 45 pays dont la France, l&rsquo;Espagne, le Mexique, l&rsquo;Argentine, le Chile et le Br\u00e9sil de pouvoir visiter Guanzhou, P\u00e9kin et Shanghai en 3 jours sans visa.<\/span><\/span><\/span>  <span style=\"color: #000000\"><span style=\"font-family: &#039;Times New Roman&#039;, serif\"><span style=\"font-size: medium\">P\u00e9kin attendait 2 millions de touristes pour des s\u00e9jours de courts dur\u00e9e. Les autorit\u00e9s comp\u00e9tentes n&rsquo;ont pour le moment communiqu\u00e9 aucun chiffre sur le nombre de personne ayant b\u00e9n\u00e9fici\u00e9 de ce programme.<\/span><\/span><\/span>  <span style=\"color: #000000\"><span style=\"font-family: &#039;Times New Roman&#039;, serif\"><span style=\"font-size: medium\">Ces mesures symboliques sont aussi un moyen pour le pays de dynamiser le tourisme. <\/span><\/span><\/span>  <span style=\"color: #000000\"><span style=\"font-family: &#039;Times New Roman&#039;, serif\"><span style=\"font-size: medium\">Pour autant, l&rsquo;annulation de demande de visa pour tout s\u00e9jour de 3 jours n&rsquo;est pas une nouveaut\u00e9, puisque cette pratique existe \u00e0<\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: &#039;Times New Roman&#039;, serif\"><span style=\"font-size: medium\">\u00a0Shenzen, dans le sud du pays, depuis 1994.<\/span><\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma Yilang, membre de l&rsquo;Acad\u00e9mie de tourisme de Chine, propose aux touristes de 45 pays dont la France, l&rsquo;Espagne, le Mexique, l&rsquo;Argentine, le Chile et le Br\u00e9sil de pouvoir visiter Guanzhou, P\u00e9kin et Shanghai en 3 jours sans visa. P\u00e9kin attendait 2 millions de touristes pour des s\u00e9jours de courts dur\u00e9e. Les autorit\u00e9s comp\u00e9tentes n&rsquo;ont [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[234],"tags":[1590,660],"class_list":["post-74621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logistique-retail","tag-chine","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74621"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44976"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}