{"id":74619,"date":"2026-03-22T22:31:21","date_gmt":"2026-03-22T22:31:21","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/whatsapp-se-lance-dans-les-messages-vocaux-2\/"},"modified":"2026-08-22T21:52:55","modified_gmt":"2026-08-22T21:52:55","slug":"whatsapp-se-lance-dans-les-messages-vocaux-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/whatsapp-se-lance-dans-les-messages-vocaux-2\/","title":{"rendered":"WhatsApp se lance dans les messages vocaux"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><i>  Avec plus de 300 millions d\u2019utilisateurs actifs, dont 20 millions en Espagne, l\u2019application Whatsapp s\u2019est impos\u00e9 comme une plateforme de communication cl\u00e9.<\/i>  L\u2019entreprise californienne WhatsApp le revendique clairement\u00a0: elle veut \u00eatre \u00ab la communication du XXIe si\u00e8cle\u00a0\u00bb. Par cons\u00e9quent, WhatsApp se met \u00e0 jour de la m\u00eame mani\u00e8re que ses principaux concurrents et propose d\u00e9sormais des appels voix.  Les appels sont inclus dans le prix d\u2019utilisation annuel (environ 89 centimes d&rsquo;euro).  \u00ab\u00a0Cette nouvelle option permet de communiquer en temps r\u00e9el avec les amis ou la famille, que l\u2019utilisateur soit dans la chambre d&rsquo;\u00e0 le c\u00f4t\u00e9 ou \u00e0 des milliers de kilom\u00e8tres de distance\u00a0\u00bb a indiqu\u00e9 l\u2019entreprise.  Chaque jour plus de 11 000 millions de messages sont envoy\u00e9s et 325 millions de photos sont partag\u00e9es.  Bien que n\u2019ayant que 40 employ\u00e9s, WhatsApp a d\u00e9j\u00e0 plus de 300 millions d&rsquo;actifs utilisateurs dans tout le monde.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec plus de 300 millions d\u2019utilisateurs actifs, dont 20 millions en Espagne, l\u2019application Whatsapp s\u2019est impos\u00e9 comme une plateforme de communication cl\u00e9. L\u2019entreprise californienne WhatsApp le revendique clairement\u00a0: elle veut \u00eatre \u00ab la communication du XXIe si\u00e8cle\u00a0\u00bb. Par cons\u00e9quent, WhatsApp se met \u00e0 jour de la m\u00eame mani\u00e8re que ses principaux concurrents et propose d\u00e9sormais [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44972,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3163],"class_list":["post-74619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-whatsapp"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74619"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44972"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}