{"id":74610,"date":"2026-03-22T22:17:22","date_gmt":"2026-03-22T22:17:22","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-gouvernement-dominicain-envisage-dabaisser-les-impots-des-lignes-aeriennes-2\/"},"modified":"2026-08-22T21:20:11","modified_gmt":"2026-08-22T21:20:11","slug":"le-gouvernement-dominicain-envisage-dabaisser-les-impots-des-lignes-aeriennes-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-gouvernement-dominicain-envisage-dabaisser-les-impots-des-lignes-aeriennes-2\/","title":{"rendered":"Le gouvernement dominicain envisage d\u2019abaisser les imp\u00f4ts des lignes a\u00e9riennes"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><i> Le gouvernement de la R\u00e9publique dominicaine \u00e9tudie la possibilit\u00e9 de baisser les imp\u00f4ts pour attirer d\u2019autres lignes a\u00e9riennes que Air Europa et Jet Blue.<\/i>  La R\u00e9publique dominicaine veut en finir avec le \u00ab\u00a0monopole\u00a0\u00bb des compagnies a\u00e9riennes comme Air Europa ou Jet Blue. En effet, selon le directeur g\u00e9n\u00e9ral du D\u00e9partement A\u00e9roportuaire, Ar\u00edstides Fern\u00e1ndez Zucco, le Gouvernement dominicain serait dispos\u00e9 \u00e0 baisser les imp\u00f4ts afin de faciliter la captation d\u2019autres lignes a\u00e9riennes et d\u00e9velopper la comp\u00e9titivit\u00e9 du march\u00e9.  Une baisse possible des imp\u00f4ts des lignes a\u00e9riennes est ainsi envisag\u00e9e afin que d\u2019autres compagnies comme GOL et DAE (Dutch Antilles Express) se tournent vers le pays.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement de la R\u00e9publique dominicaine \u00e9tudie la possibilit\u00e9 de baisser les imp\u00f4ts pour attirer d\u2019autres lignes a\u00e9riennes que Air Europa et Jet Blue. La R\u00e9publique dominicaine veut en finir avec le \u00ab\u00a0monopole\u00a0\u00bb des compagnies a\u00e9riennes comme Air Europa ou Jet Blue. En effet, selon le directeur g\u00e9n\u00e9ral du D\u00e9partement A\u00e9roportuaire, Ar\u00edstides Fern\u00e1ndez Zucco, le [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44940,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[869],"class_list":["post-74610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-republique-dominicaine"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74610"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44940"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}