{"id":74540,"date":"2026-03-22T21:01:40","date_gmt":"2026-03-22T21:01:40","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lhotel-palace-a-barcelone-en-vente-pour-62-millions-2\/"},"modified":"2026-08-22T16:52:05","modified_gmt":"2026-08-22T16:52:05","slug":"lhotel-palace-a-barcelone-en-vente-pour-62-millions-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lhotel-palace-a-barcelone-en-vente-pour-62-millions-2\/","title":{"rendered":"L&rsquo;H\u00f4tel Palace \u00e0 Barcelone en vente pour 62 millions"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><!--:fr-->L&rsquo;H\u00f4tel Palace \u00e0 Barcelone, l&rsquo;ancien Ritz, est de retour sur le march\u00e9. Son propri\u00e9taire, l&rsquo;homme d&rsquo;affaires d&rsquo;origine alg\u00e9rienne Ali Haddad qui a achet\u00e9 le b\u00e2timent il y a deux ans pour 68 millions d&rsquo;euros, le vendrait maintenant pour 62 millions.  <b>Des probl\u00e8mes pour Husa Hoteles<\/b> <\/p>\n<p style=\"text-align: left\">L&rsquo;h\u00f4tel est lou\u00e9 \u00e0 Husa Hoteles, propri\u00e9t\u00e9 de Joan Gaspart, qui traverse des probl\u00e8mes de flux de tr\u00e9sorerie, ce qui a entra\u00een\u00e9 des retards dans les paiements. L&rsquo;H\u00f4tel Palace, un cinq \u00e9toiles de luxe avec un total de 125 chambres, est l&rsquo;un des joyaux de la cha\u00eene de Joan Gaspart. En raison de sa d\u00e9licate situation financi\u00e8re, \u00a0Husa Hoteles a \u00e9t\u00e9 oblig\u00e9e de vendre l\u2019h\u00f4tel en 2011, mais l\u2019entreprise a en suite lou\u00e9 l\u2019immeuble. Des sources proches \u00e0 l\u2019op\u00e9ration assurent que le loyer convenu \u00e0 l\u2019\u00e9poque \u00e9tait tr\u00e8s difficile \u00e0 payer, m\u00eame pour une cha\u00eene assainie. Pr\u00e8s de deux ans plus tard, le propri\u00e9taire, par un repr\u00e9sentant en Espagne, essaye de trouver une solution pour l&rsquo;h\u00f4tel. Selon des sources proches, il a d\u00e9j\u00e0 discut\u00e9 avec des cha\u00eenes h\u00f4teli\u00e8res internationales int\u00e9ress\u00e9es par l\u2019exploitation.<\/p>\n<p> <b>De Ritz \u00e0 Palace<\/b> <\/p>\n<p style=\"text-align: left\">L&rsquo;h\u00f4tel, construit en 1919 par C\u00e9sar Ritz, a \u00e9t\u00e9 le premier cinq \u00e9toiles \u00e0 Barcelone. Pendant de nombreuses ann\u00e9es le Ritz a \u00e9t\u00e9 une r\u00e9f\u00e9rence dans la capitale catalane et a accueilli des gens comme Cary Grant, Sophia Loren, Pel\u00e9 et Madonna. Salvador Dal\u00ed a v\u00e9cu pendant un certain temps dans l&rsquo;h\u00f4tel et l&rsquo;une des suites porte maintenant le nom du peintre. En 2007, l&rsquo;h\u00f4tel a subi une restauration minutieuse qui a co\u00fbt\u00e9 30 millions et a rouvert en 2009 en conservant son style classique, mais sous un autre nom\u00a0:\u00a0Palace H\u00f4tel, au lieu de Ritz, \u00e0 cause d\u2019un litige avec ses anciens propri\u00e9taires.<\/p>\n<p> <b>Investisseurs \u00e9trangers<\/b> <\/p>\n<p style=\"text-align: left\">L&rsquo;H\u00f4tel Palace a suscit\u00e9 l&rsquo;int\u00e9r\u00eat de nombreux investisseurs, mais beaucoup ont d\u00e9cid\u00e9 ne pas l\u2019acheter \u00e0 cause du prix. Actuellement, il ya au moins une offre ferme de la part d&rsquo;un fonds \u00e9tranger, selon des sources du secteur. La correction des prix de l&rsquo;immobilier espagnol a favoris\u00e9 l&rsquo;arriv\u00e9e de groupes \u00e9trangers au march\u00e9 de l&rsquo;h\u00f4telier, jusqu&rsquo;\u00e0 maintenant r\u00e9gi par des cha\u00eenes espagnoles.<\/p>\n<p style=\"text-align: left\">L&rsquo;essor du tourisme international \u00e0 Barcelone \u00a0a \u00e9galement favoris\u00e9 l\u2019int\u00e9r\u00eat par ce secteur des fonds fran\u00e7ais (H\u00f4tel Diagonal Port), allemands (H\u00f4tel Barcel\u00f3 Raval) et portugais (H\u00f4tel Vincci Arena), sans oublier le fonds britannique Aginyo (propri\u00e9t\u00e9 d\u2019Ali Haddad) qui a achet\u00e9 l&rsquo;H\u00f4tel Palace il y a deux ans.<\/p>\n<p style=\"text-align: left\"><strong>Versi\u00f3n espa\u00f1ola<\/strong><\/p>\n<p> <!--:--><!--:es-->El Hotel Palace de Barcelona, el antiguo Ritz, est\u00e1 de nuevo en el mercado. Su due\u00f1o, el hombre de negocios de origen argelino Ali Haddad que compr\u00f3 el edificio hace 2 a\u00f1os por 68 millones de euros, lo vender\u00e1 ahora \u00a0por 62 millones.  <b>Problemas para Husa Hoteles <\/b>  El hotel est\u00e1 alquilado a Husa Hoteles, propiedad de Joan Gaspart, el cual sufre actualmente problemas en su flujo de tesorer\u00eda, lo que ha llevado a largos retrasos en los pagos. El Hotel Palace, un \u00a05 estrellas de lujo con un total de 125 habitaciones, es una de las joyas de la cadena de Joan Gaspart.  Como consecuencia de su delicada situaci\u00f3n financiera, Husa Hoteles se vio obligada a vender el hotel en 2011, pero la empresa alquil\u00f3 el inmueble inmediatamente. Fuentes cercanas a la operaci\u00f3n aseguran que el alquiler convenido en la \u00e9poca era realmente dif\u00edcil de pagar, incluso para una cadena de esta magnitud.  Casi dos a\u00f1os despu\u00e9s, y a trav\u00e9s de un representante en Espa\u00f1a, el propietario intenta encontrar una soluci\u00f3n para el hotel. Seg\u00fan las mismas fuentes, el representante ya ha discutido con algunas cadenas hoteleras internacionales interesadas en la explotaci\u00f3n del lugar.  <b>De Ritz a Palace<\/b>  <b><\/b>El hotel, construido en 1919 por C\u00e9sar Ritz, fue el primer cinco estrellas construido en Barcelona. Durante varios a\u00f1os, el Ritz fue una referencia en la capital catalana y ha recibido a personalidades como Cary Grant, Sophia Loren, Pel\u00e9 y Maradona. Una de las habitaciones lleva el nombre de Salvador Dal\u00ed , el cual habit\u00f3 ah\u00ed por un tiempo.  En 2007 el hotel fue restaurado minuciosamente, operaci\u00f3n que cost\u00f3 alrededor de 30 millones, y reabri\u00f3 en 2009, conservando su estilo cl\u00e1sico pero con otro nombre: Palace Hotel, en lugar de Ritz, a causa de un litigio con los antiguos propietarios por el nombre del lugar.  <b>Inversores Extranjeros<\/b>  El Hotel Palace ha suscitado el inter\u00e9s de varios inversores extranjeros, pero muchos han decidido no comprarlo a causa del precio. Actualmente existe al menos una oferta fuerte por parte de un fondo extranjero, seg\u00fan las fuentes del sector. El cambio en los precios del inmobiliario espa\u00f1ol han favorecido la llegada de grupos extranjeros al mercado hotelero, que hasta ahora estaba controlado por cadenas espa\u00f1olas.  El alza del turismo internacional en Barcelona ha despertado igualmente el inter\u00e9s por este sector en los fondos franceses (Hotel Diagonal Port), alemanes ( Hotel Barcel\u00f3 Raval) y portugueses ( Hotel Vincci Arena) , sin dejar de lado el fondo brit\u00e1nico Aginyo (propiedad de Ali Haddad ), el mismo que compr\u00f3 el Palace hace dos a\u00f1os.<!--:--><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;H\u00f4tel Palace \u00e0 Barcelone, l&rsquo;ancien Ritz, est de retour sur le march\u00e9. Son propri\u00e9taire, l&rsquo;homme d&rsquo;affaires d&rsquo;origine alg\u00e9rienne Ali Haddad qui a achet\u00e9 le b\u00e2timent il y a deux ans pour 68 millions d&rsquo;euros, le vendrait maintenant pour 62 millions. Des probl\u00e8mes pour Husa Hoteles L&rsquo;h\u00f4tel est lou\u00e9 \u00e0 Husa Hoteles, propri\u00e9t\u00e9 de Joan Gaspart, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44661,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3073,3074,447,1403,3075,3076,3077],"class_list":["post-74540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-aginyo","tag-ali-haddad","tag-barcelone","tag-htel-ritz","tag-hotel-palace","tag-husa-hoteles","tag-joan-gaspart"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74540"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44661"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}