{"id":74532,"date":"2026-03-22T20:52:18","date_gmt":"2026-03-22T20:52:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lespagne-change-peu-a-peu-sa-vision-de-la-location-2\/"},"modified":"2026-08-22T16:20:36","modified_gmt":"2026-08-22T16:20:36","slug":"lespagne-change-peu-a-peu-sa-vision-de-la-location-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lespagne-change-peu-a-peu-sa-vision-de-la-location-2\/","title":{"rendered":"L&rsquo;Espagne change, peu \u00e0 peu, sa vision de la location"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Aujourd&rsquo;hui, 19,3% de la population vit dans une location, en Espagne. Un pourcentage bien plus bas que celui enregistr\u00e9 dans d&rsquo;autres pays de l&rsquo;UE , mais en nette augmentation (pr\u00e8s de 4%!) par rapport aux donn\u00e9es de 2011, alors que 15,3 % vivaient en location . Selon le rapport \u00ab Les Espagnols et leur relation au logement 2013\u00bb , \u00e9tabli par le portail immobilier Fotocasa.es non seulement, crise oblige ,de plus en plus d&rsquo;Espagnols louent au lieu d&rsquo;acheter, mais leur perception de ce mode de vie change aussi . Ainsi, 76 % des r\u00e9pondants d\u00e9clarent que la location est une bonne mani\u00e8re de ne pas subir la crise, et 45 % estiment cela reste plus rentable de louer que d&rsquo;acheter vu le niveau actuel des prix. Quatre Espagnols sur dix pensent que \u00ab\u00a0louer c&rsquo;est de jeter l&rsquo;argent par les fen\u00eatres \u00bb , alors qu&rsquo;en 2011, il y en avait six sur dix pour soutenir cela. D&rsquo;autre part , la plupart des locataires interrog\u00e9s affirment que la principale raison qui les am\u00e8nent \u00e0 louer plut\u00f4t que d&rsquo;acheter une maison reste leur situation \u00e9conomique (19%). Ainsi, 9,1% disent qu&rsquo;ils ne peuvent pas d\u00e9penser assez pour effectuer l&rsquo;achat d&rsquo;une maison et 9,1%, \u00e9galement, disent qu&rsquo;ils attendent que les prix baissent encore.  <b>Les jeunes encore plus ouverts \u00e0 la location<\/b>  Cependant, l&rsquo;Espagne est encore un pays qui poss\u00e8de une culture profond\u00e9ment enracin\u00e9e de l&rsquo;accession \u00e0 la propri\u00e9t\u00e9 . Les chiffres sont clairs: 71,8% des r\u00e9pondants pr\u00e9f\u00e8rent vivre dans un appartement ou une maison \u00e0 leur nom, contre 11,8 % qui pensent qu&rsquo;il est mieux de prendre une location . Un chiffre assez faible, mais tout de m\u00eame&#8230; trois fois plus que les 4 % des Espagnols qui se disaient favorables \u00e0 la location en 2011\u00a0! Les jeunes restent les plus \u00e0 m\u00eame de choisir la location. Dans le panel des personnes interrog\u00e9es, \u00e2g\u00e9es de 18 \u00e0 30 ans , 44% des r\u00e9pondants vivent encore chez leurs parents , contre 29 % qui pr\u00e9tendent \u00eatre propri\u00e9taire et 27 % vivent en location. En outre, 53,5% des personnes interrog\u00e9es ayant cet \u00e2ge l\u00e0, pensent qu&rsquo;il est plus rentable de louer , et 28,4 % pensent que cette option leur fait \u00ab jeter de l&rsquo;argent par les fen\u00eatres\u00a0\u00bb. Pourtant, la plupart de ces jeunes gens sont s\u00fbr \u200b\u200bde leur avenir. 54,6% sont , par exemple, convaincus qu&rsquo;il vont acheter un peu plus tard une propri\u00e9t\u00e9.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, 19,3% de la population vit dans une location, en Espagne. Un pourcentage bien plus bas que celui enregistr\u00e9 dans d&rsquo;autres pays de l&rsquo;UE , mais en nette augmentation (pr\u00e8s de 4%!) par rapport aux donn\u00e9es de 2011, alors que 15,3 % vivaient en location . Selon le rapport \u00ab Les Espagnols et leur relation [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44620,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-74532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74532"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44620"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}