{"id":74512,"date":"2026-03-22T20:26:16","date_gmt":"2026-03-22T20:26:16","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/primark-va-ouvrir-de-nouveaux-magasins-en-espagne-2\/"},"modified":"2026-08-22T15:16:53","modified_gmt":"2026-08-22T15:16:53","slug":"primark-va-ouvrir-de-nouveaux-magasins-en-espagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/primark-va-ouvrir-de-nouveaux-magasins-en-espagne-2\/","title":{"rendered":"Primark va ouvrir de nouveaux magasins en Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Les r\u00e9sultats sont excellents. Impressionnants, m\u00eame. De quoi, en tout cas, donner l&rsquo;envie de continuer. La compagnie irlandaise Primark, qui propose des v\u00eatements \u00e0 bas-prix, et qui appartient \u00e0 l&rsquo;Associated British Foods , a r\u00e9alis\u00e9, sur son dernier exercice financier (achev\u00e9 en septembre dernier) un b\u00e9n\u00e9fice de pr\u00e8s de 612 millions d&rsquo;euros , soit 44,4 % de plus que l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. La soci\u00e9t\u00e9 a d&rsquo;ailleurs annonc\u00e9 qu&rsquo;elle ouvrirait cinq nouveaux magasins en Espagne , juste \u00e0 temps pour les courses de No\u00ebl . Les ventes de la cha\u00eene l&rsquo;an dernier ont augment\u00e9 de 22 %, passant de 4 168 millions d&rsquo;euros \u00e0 pr\u00e8s de 5 milliards. \u00abCette excellente performance a \u00e9t\u00e9 obtenue par l&rsquo;augmentation de l&rsquo;espace de vente au d\u00e9tail, de l&rsquo;augmentation de 5% des ventes comparables, et une plus forte concentration des produits vendus dans de nouvelles installations plus grandes \u00bb, a d\u00e9clar\u00e9 la compagnie dans un communiqu\u00e9.  <b>Treize nouvelles ouvertures en Europe<\/b>  En Espagne, cette ann\u00e9e, la soci\u00e9t\u00e9 a ouvert de nouveaux magasins \u00e0 Santander , Santiago de Compostela , Orihuela , Valladolid , Vitoria et Zaragoza . Le 14 septembre dernier, par exemple, Primark avait 257 magasins ouverts dans le monde avec plus de 836.000 m\u00e8tres carr\u00e9s de ventes , soit 15 magasins de plus , (ouverture de 16 nouveaux et fermeture d&rsquo;un autre, au Royaume-Uni). Une augmentation qui va continuer, puisque la compagnie va lancer un \u00a0\u00bb programme charg\u00e9 \u00a0\u00bb d&rsquo;ouverture dans toute l&rsquo;Europe avec treize nouveaux magasins qui ouvriront leurs portes avant No\u00ebl, dont les cinq en Espagne, qui seront bas\u00e9s \u00e0 Huelva, Almer\u00eda, Albacete M\u00e1laga et Murcia, mais aussi les premiers fran\u00e7ais \u00e0 Dijon, Paris et Marseille.  &nbsp;  &nbsp;<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9sultats sont excellents. Impressionnants, m\u00eame. De quoi, en tout cas, donner l&rsquo;envie de continuer. La compagnie irlandaise Primark, qui propose des v\u00eatements \u00e0 bas-prix, et qui appartient \u00e0 l&rsquo;Associated British Foods , a r\u00e9alis\u00e9, sur son dernier exercice financier (achev\u00e9 en septembre dernier) un b\u00e9n\u00e9fice de pr\u00e8s de 612 millions d&rsquo;euros , soit 44,4 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[3020,3021,880,3022,2816],"class_list":["post-74512","post","type-post","status-publish","format-standard","hentry","category-breaking-news","tag-inauguration","tag-magasins","tag-primark","tag-soldes","tag-succes"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74512"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74512\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}