{"id":74499,"date":"2026-03-22T20:11:15","date_gmt":"2026-03-22T20:11:15","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/loi-de-soutien-aux-entrepreneurs-volet-fiscal-nouveau-en-espagne-2\/"},"modified":"2026-08-22T14:13:04","modified_gmt":"2026-08-22T14:13:04","slug":"loi-de-soutien-aux-entrepreneurs-volet-fiscal-nouveau-en-espagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/loi-de-soutien-aux-entrepreneurs-volet-fiscal-nouveau-en-espagne-2\/","title":{"rendered":"Loi de soutien aux entrepreneurs : volet fiscal nouveau en Espagne!"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Loi 14\/2013, du 27 septembre 2013, de soutien aux entrepreneurs et de d\u00e9veloppement de leur activit\u00e9 \u00e0 l\u2019international<a title=\"\" href=\"\/Users\/alcampo\/Downloads\/Loi%2014-2013%20volet%20fiscal-%20texte%20complet%20v2.docx#_ftn1\">[1]<\/a>, a introduit un ensemble de dispositifs fiscaux favorables aux entreprises. Le pr\u00e9sent article a pour objet d\u2019exposer les principales caract\u00e9ristiques des nouveaux dispositifs applicables en mati\u00e8re de TVA, d\u2019Imp\u00f4t sur le revenu et d\u2019Imp\u00f4t sur les Soci\u00e9t\u00e9s.  <b>1.1.\u00a0<\/b><b>TVA\u00a0: nouvelles r\u00e8gles d\u2019exigibilit\u00e9 sur les encaissements visant \u00e0 r\u00e9duire les difficult\u00e9s de tr\u00e9sorerie des entreprises<\/b>  Le principe, en mati\u00e8re de TVA, est que la taxe devient exigible au moment o\u00f9 l\u2019op\u00e9ration est r\u00e9alis\u00e9e. Ainsi, un prestataire facturant un service au mois de janvier 2014 et qui encaisserait le montant de sa facture en novembre 2014, devra reverser la TVA due \u00e0 l\u2019Etat espagnol entre le 1<sup>er<\/sup> et le 20 avril 2014 (d\u00e9claration du 1<sup>er<\/sup> trimestre 2014<a title=\"\" href=\"\/Users\/alcampo\/Downloads\/Loi%2014-2013%20volet%20fiscal-%20texte%20complet%20v2.docx#_ftn2\">[2]<\/a>) et ce, ind\u00e9pendamment de la date d\u2019encaissement de sa facture. En pratique, cette r\u00e8gle a souvent pour effet de contraindre les entreprises \u00e0 reverser la TVA \u00e0 l\u2019Etat avant m\u00eame d\u2019avoir encaiss\u00e9 le montant de leurs factures. De toute \u00e9vidence, compte tenu des d\u00e9lais de paiement d\u00e9j\u00e0 traditionnellement longs en Espagne, et qui s\u2019\u00e9tirent d\u00e9mesur\u00e9ment dans le contexte actuel de crise \u00e9conomique, cette r\u00e8gle entra\u00eene des difficult\u00e9s de tr\u00e9sorerie majeures pour de nombreuses entreprises.  Afin de rem\u00e9dier \u00e0 ce type de situations, la Loi 14\/2013 a introduit un r\u00e9gime particulier d\u2019exigibilit\u00e9 de la TVA applicable, \u00e0 compter du 1<sup>er<\/sup> janvier 2014, sur option de l\u2019assujetti concern\u00e9.\u00a0 <b>En application de ce nouveau r\u00e9gime, la taxe devient exigible non pas au moment de la r\u00e9alisation de l\u2019op\u00e9ration mais<\/b> <b>au moment de l\u2019encaissement total ou partiel du prix<\/b>. Bien que l\u2019intention du l\u00e9gislateur soit manifestement favorable aux int\u00e9r\u00eats des entreprises, la port\u00e9e du dispositif demeure limit\u00e9e, notamment parce qu\u2019il ne concerne que certaines entreprises. <\/p>\n<ul>\n<li><b>Champ d\u2019application du r\u00e9gime <\/b><\/li>\n<\/ul>\n<p> Le dispositif concerne tous les assujettis (personnes physiques et morales) <b>dont le volume des op\u00e9rations n\u2019a pas d\u00e9pass\u00e9 le seuil de 2 millions d\u2019euros au cours de l\u2019ann\u00e9e pr\u00e9c\u00e9dente et dont les encaissements aupr\u00e8s d\u2019un m\u00eame client, n\u2019a pas d\u00e9pass\u00e9, au cours de l\u2019ann\u00e9e civile, le seuil de 100.000 euros.<\/b>  Le r\u00e9gime s\u2019applique sur option et est tacitement reconduit ann\u00e9e apr\u00e8s ann\u00e9e, \u00e0 moins que l\u2019assujetti n\u2019y renonce, cette renonciation produisant des effets pour trois ans. L\u2019option doit \u00eatre exerc\u00e9e au mois de d\u00e9cembre de l\u2019ann\u00e9e pr\u00e9c\u00e9dant celle au titre de laquelle le r\u00e9gime sera appliqu\u00e9. En cas de d\u00e9but d\u2019activit\u00e9, l\u2019option doit \u00eatre exerc\u00e9e lors du d\u00e9p\u00f4t de la d\u00e9claration d\u2019existence.  Sont vis\u00e9es par ces nouvelles r\u00e8gles l\u2019ensemble des livraisons de biens et prestations de services r\u00e9alis\u00e9es sur le territoire espagnol, \u00e0 l\u2019exception toutefois de certaines op\u00e9rations particuli\u00e8res, telles que les op\u00e9rations de commerce international, les op\u00e9rations pour lesquelles le destinataire est redevable de la taxe (\u00ab\u00a0reverse charge\u00a0\u00bb), ainsi que les op\u00e9rations soumises \u00e0 certains r\u00e9gimes sp\u00e9cifiques (r\u00e9gime simplifi\u00e9, r\u00e9gime des producteurs agricoles, r\u00e9gime des commer\u00e7ants d\u00e9taillants, r\u00e9gime de l\u2019or d\u2019investissement, r\u00e9gime des services fournis par voie \u00e9lectronique, r\u00e9gime des groupements TVA).  Le r\u00e8glement d\u2019application introduit des obligations sp\u00e9cifiques, notamment en mati\u00e8re de facturation et de comptabilit\u00e9. <\/p>\n<ul>\n<li><b>Principales caract\u00e9ristiques du r\u00e9gime <\/b><\/li>\n<\/ul>\n<p> Conform\u00e9ment \u00e0 ce nouveau r\u00e9gime, la TVA devient exigible au moment de l\u2019encaissement de tout ou partie du prix. Ainsi, dans l\u2019exemple pr\u00e9sent\u00e9 ci-dessus, un prestataire qui facturerait un service au mois de janvier 2014 et qui encaisserait le montant de sa facture en novembre 2014, serait tenu de reverser le montant de taxe exigible non pas entre le 1<sup>er<\/sup> et le 20 avril 2014 (d\u00e9claration du 1<sup>er<\/sup> trimestre 2014) mais entre le 1<sup>er<\/sup> et le 30 janvier 2015 (d\u00e9claration du 4<sup>\u00e8me<\/sup>\u00a0 trimestre 2015).  Ce nouveau dispositif est assorti d\u2019une d\u00e9rogation importante. En effet, en cas d\u2019absence de paiement par le client au 31 d\u00e9cembre de l\u2019ann\u00e9e suivant celle au cours de laquelle l\u2019op\u00e9ration a \u00e9t\u00e9 r\u00e9alis\u00e9e, l\u2019exigibilit\u00e9 de la taxe intervient en tout \u00e9tat de cause \u00e0 cette date, le prestataire \u00e9tant ainsi tenu de verser la taxe \u00e0 l\u2019Etat. Ainsi, dans l\u2019exemple pr\u00e9c\u00e9dent, si au 31 d\u00e9cembre \u00a02015, le paiement n\u2019\u00e9tait pas intervenu, le prestataire serait tout de m\u00eame tenu de reverser la TVA \u00e0 l\u2019Etat espagnol lors du d\u00e9p\u00f4t de la d\u00e9claration du 4<sup>\u00e8me<\/sup> trimestre 2015, c\u2019est-\u00e0-dire entre le 1<sup>er<\/sup> et le 30 janvier 2016. <\/p>\n<ul>\n<li><b>Impact sur le droit \u00e0 d\u00e9duction <\/b><\/li>\n<\/ul>\n<p> Le principe, en mati\u00e8re de TVA, est que le droit \u00e0 d\u00e9duction prend naissance au moment o\u00f9 la taxe est devenue exigible, c\u2019est-\u00e0-dire, en r\u00e8gle g\u00e9n\u00e9rale, au moment o\u00f9 l\u2019op\u00e9ration a \u00e9t\u00e9 r\u00e9alis\u00e9e. Par d\u00e9rogation \u00e0 ce principe, le l\u00e9gislateur a pr\u00e9vu que les assujettis ayant opt\u00e9 pour le r\u00e9gime de TVA sur les encaissements ne pourront d\u00e9duire les montants de TVA qui leur sont factur\u00e9s qu\u2019\u00e0 partir de la date \u00e0 laquelle ils r\u00e8glent la facture de leur fournisseur ou de leur prestataire. En cas de d\u00e9faut de paiement, la r\u00e8gle du 31 d\u00e9crite ci-avant d\u00e9cembre trouve \u00e0 s\u2019appliquer. Ainsi, un client qui acquiert un service en janvier 2014 et qui, au 31 d\u00e9cembre 2015, n\u2019a pas r\u00e9gl\u00e9 la facture correspondante, pourra proc\u00e9der \u00e0 la d\u00e9duction de la taxe \u00e0 partir de cette derni\u00e8re date.  &nbsp;  L\u2019option, par le prestataire ou le fournisseur, pour l\u2019application du r\u00e9gime particulier de TVA sur les encaissements, a \u00e9galement un impact sur la date \u00e0 partir de laquelle le client, qui n\u2019a pas opt\u00e9 pour le r\u00e9gime, est autoris\u00e9 \u00e0 d\u00e9duire la taxe. Ainsi, le client ne peut proc\u00e9der \u00e0 la d\u00e9duction de la taxe qu\u2019\u00e0 compter de la date de r\u00e8glement de la facture de son fournisseur ou de son prestataire ou, en cas de d\u00e9faut de paiement, au 31 d\u00e9cembre de l\u2019ann\u00e9e suivant celle de la r\u00e9alisation de l\u2019op\u00e9ration.  &nbsp;  <b>1.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Imp\u00f4t sur le revenu\u00a0: nouveaux avantages fiscaux li\u00e9s aux investissements dans des entreprises nouvelles ou r\u00e9cemment constitu\u00e9es<\/b>  La loi 14\/2013 a introduit deux nouveaux dispositifs visant \u00e0 inciter les personnes physiques \u00e0 investir dans de nouvelles entreprises. Ces dispositifs sont entr\u00e9s en vigueur le 29 septembre 2013. <\/p>\n<ul>\n<li><b>D\u00e9duction d\u2019imp\u00f4t au titre des investissements r\u00e9alis\u00e9s dans des entreprises nouvelles ou r\u00e9cemment constitu\u00e9es<\/b><\/li>\n<\/ul>\n<p> <b>Les personnes physiques soumises \u00e0 l\u2019imp\u00f4t sur le revenu peuvent d\u00e9sormais d\u00e9duire 20% des sommes vers\u00e9es au titre de la souscription d\u2019actions ou de parts d\u2019entreprises nouvelles ou r\u00e9cemment constitu\u00e9es.<\/b> Le dispositif concerne aussi bien les personnes dont l\u2019apport est strictement financier, que celles qui apportent du capital ainsi que des connaissances \u00e9conomiques ou professionnelles adapt\u00e9es au d\u00e9veloppement de l\u2019activit\u00e9 de l\u2019entreprise.  L\u2019assiette de la d\u00e9duction est \u00e9gale \u00e0 la valeur d\u2019acquisition des titres et est limit\u00e9e \u00e0 50.000 euros. Le texte pr\u00e9voit toutefois certaines exclusions.  La d\u00e9duction s\u2019applique sous r\u00e9serve que le souscripteur des titres remplisse les conditions suivantes\u00a0:  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 acquisition des titres lors de la constitution de la soci\u00e9t\u00e9 ou dans le cadre d\u2019une augmentation de capital r\u00e9alis\u00e9e dans les trois ans suivant la constitution\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 conservation des titres pendant une dur\u00e9e de 3 \u00e0 12 ans\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 d\u00e9tention d\u2019une participation directe ou indirecte non sup\u00e9rieure \u00e0 40% du capital\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 les titres ne peuvent porter sur le capital d\u2019une entit\u00e9 exer\u00e7ant une activit\u00e9 identique \u00e0 celle qui \u00e9tait exerc\u00e9e par le contribuable dans une autre soci\u00e9t\u00e9.  Par ailleurs, la soci\u00e9t\u00e9 dont les titres sont souscrits doit r\u00e9unir les conditions suivantes\u00a0:  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00eatre une soci\u00e9t\u00e9 commerciale (\u00ab\u00a0SA\u00a0\u00bb ou \u00ab\u00a0SRL\u00a0\u00bb) ou une soci\u00e9t\u00e9 coop\u00e9rative (\u00ab\u00a0SAL\u00bb ou \u00ab\u00a0SLL\u00a0\u00bb). Les soci\u00e9t\u00e9s cot\u00e9es sont exclues du dispositif\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 exercer une activit\u00e9 \u00e9conomique et disposer des moyens mat\u00e9riels et humains adapt\u00e9s \u00e0 cette fin. Sont notamment exclues les activit\u00e9s de gestion de patrimoine mobilier ou immobilier\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 disposer de fonds propres non sup\u00e9rieurs \u00e0 400.000 euros au commencement de l\u2019ann\u00e9e au cours de laquelle les titres ont \u00e9t\u00e9 souscrits.  <span style=\"text-decoration: underline\">\u00a0<\/span> <\/p>\n<ul>\n<li><b>Exon\u00e9ration des plus-values de cession de titres d\u2019entreprises nouvelles <\/b><\/li>\n<\/ul>\n<p> Les plus-values de cession de titres pour lesquels le contribuable a pr\u00e9alablement b\u00e9n\u00e9fici\u00e9 de la d\u00e9duction d\u00e9crite ci-dessus, sont exon\u00e9r\u00e9es d\u2019imp\u00f4t sur le revenu.  L\u2019exon\u00e9ration de la plus-value est toutefois subordonn\u00e9e au fait que le montant total de la cession soit r\u00e9investi dans l\u2019acquisition de titres d\u2019entreprises nouvelles ou r\u00e9cemment constitu\u00e9es. Le r\u00e9investissement d\u2019une partie du prix de cession n\u2019ouvre droit qu\u2019\u00e0 une exon\u00e9ration partielle.  Le texte \u00e9carte l\u2019application de cet avantage fiscal dans certains cas de figure, notamment lorsque les titres sont c\u00e9d\u00e9s au conjoint, \u00e0 une personne ayant un lien de parent\u00e9 avec le c\u00e9dant, ou \u00e0 une entit\u00e9 faisant partie du m\u00eame groupe de soci\u00e9t\u00e9s que celui auquel le c\u00e9dant appartient.  Ce nouveau dispositif est assorti de la suppression de l\u2019ancien r\u00e9gime d\u2019exon\u00e9ration des plus-values de cession de titres de participations d\u2019entreprises nouvelles.  <b>1.3. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Imp\u00f4t sur les soci\u00e9t\u00e9s\u00a0: nouvelle d\u00e9duction d\u2019imp\u00f4t en cas d\u2019investissement des b\u00e9n\u00e9fices dans l\u2019acquisition de certains \u00e9l\u00e9ments d\u2019actifs<\/b>  La loi 14\/2013 a introduit une nouvelle d\u00e9duction pour les PME dont les b\u00e9n\u00e9fices sont affect\u00e9s \u00e0 l\u2019acquisition de certains \u00e9l\u00e9ments d\u2019actifs. Ce dispositif \u00a0concerne les b\u00e9n\u00e9fices r\u00e9alis\u00e9s \u00e0 compter du 1<sup>e<\/sup> janvier 2013.  Sont concern\u00e9es par cette mesure les <b>PME dont le chiffre d\u2019affaires est inf\u00e9rieur \u00e0 10 millions d\u2019euros<\/b> et dont la fraction de la base d\u2019imposition comprise entre 0 et 300.000 euros est soumise au taux r\u00e9duit de 25%.  <b>La d\u00e9duction est \u00e9gale \u00e0 10% des b\u00e9n\u00e9fices avant imp\u00f4t de l\u2019exercice<\/b>, investis dans l\u2019acquisition de nouvelles immobilisations corporelles ou utilis\u00e9s dans le cadre de la r\u00e9alisation d\u2019investissements immobiliers affect\u00e9s \u00e0 des activit\u00e9s \u00e9conomiques.  L\u2019assiette de la d\u00e9duction est multipli\u00e9e par un coefficient r\u00e9sultant d\u2019une formule fix\u00e9e par le texte. La d\u00e9duction intervient au titre de la p\u00e9riode d\u2019imposition au cours de laquelle l\u2019investissement est r\u00e9alis\u00e9.  Le droit \u00e0 d\u00e9duction est subordonn\u00e9 au respect des conditions suivantes\u00a0:  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 l\u2019investissement doit intervenir dans un d\u00e9lai compris entre le d\u00e9but de la p\u00e9riode d\u2019imposition au cours de laquelle les b\u00e9n\u00e9fices sont obtenus et les deux ann\u00e9es suivantes. Un plan d\u2019investissement peut exceptionnellement \u00eatre autoris\u00e9 par l\u2019administration sur demande de la soci\u00e9t\u00e9 concern\u00e9e.  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les \u00e9l\u00e9ments acquis doivent \u00eatre conserv\u00e9s par la soci\u00e9t\u00e9 pendant 5 ans.  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La soci\u00e9t\u00e9 concern\u00e9e doit constituer une r\u00e9serve indisponible d\u2019un montant \u00e9gal \u00e0 l\u2019assiette de la d\u00e9duction et maintenir cette r\u00e9serve aussi longtemps qu\u2019elle d\u00e9tient les nouveaux \u00e9l\u00e9ments d\u2019actifs.  Par ailleurs,\u00a0la Loi 14\/2013 a introduit trois autres dispositifs non comment\u00e9s dans le pr\u00e9sent document en raison de leur int\u00e9r\u00eat relatif\u00a0:  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 modification du dispositif de d\u00e9duction d\u2019IS b\u00e9n\u00e9ficiant aux entreprises exer\u00e7ant une activit\u00e9 de recherche et d\u00e9veloppement\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 modification du dispositif de r\u00e9duction d\u2019IS relatif aux revenus issus de la cession du droit d\u2019utilisation ou d\u2019exploitation de certaines immobilisations incorporelles (brevets, formules ou proc\u00e9dures secr\u00e8tes, informations relatives \u00e0 des exp\u00e9riences industrielles, commerciales ou scientifiques)\u00a0;  &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 modification du dispositif de d\u00e9duction b\u00e9n\u00e9ficiant aux entreprises qui embauchent des personnes handicap\u00e9es.  <\/p>\n<address>Virginie Molinier et Laurent Dommergues<\/address>\n<address>M&amp;B Avocats\u00a0<\/address>\n<address><a href=\"http:\/\/www.mbabogados.eu\/Presentation\">http:\/\/www.mbabogados.eu\/<\/a><\/address>\n<div>  <\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div>  <em><a title=\"\" href=\"\/Users\/alcampo\/Downloads\/Loi%2014-2013%20volet%20fiscal-%20texte%20complet%20v2.docx#_ftnref1\">[1]<\/a> \u201cLey 14\/2013, de 27 de septiembre, de apoyo a los emprendedores y su internacionalizaci\u00f3n (BOE 28\/09\/2013)\u201d \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><em><a title=\"\" href=\"\/Users\/alcampo\/Downloads\/Loi%2014-2013%20volet%20fiscal-%20texte%20complet%20v2.docx#_ftnref2\">[2]<\/a> \u00a0Dans cet exemple, l\u2019assujetti est soumis au r\u00e9gime d\u00e9claratif trimestriel.<\/em>  <\/div>\n<\/p>\n<\/div>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Loi 14\/2013, du 27 septembre 2013, de soutien aux entrepreneurs et de d\u00e9veloppement de leur activit\u00e9 \u00e0 l\u2019international[1], a introduit un ensemble de dispositifs fiscaux favorables aux entreprises. Le pr\u00e9sent article a pour objet d\u2019exposer les principales caract\u00e9ristiques des nouveaux dispositifs applicables en mati\u00e8re de TVA, d\u2019Imp\u00f4t sur le revenu et d\u2019Imp\u00f4t sur les [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44451,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4392],"tags":[2901,1304],"class_list":["post-74499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-patrimoine","tag-buzz-juridique","tag-entrepreneur"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74499"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44451"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}