{"id":74472,"date":"2026-03-22T19:35:44","date_gmt":"2026-03-22T19:35:44","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/a-madrid-le-thermometre-des-restaurants-remonte-mais-pas-les-concepts-2\/"},"modified":"2026-08-22T12:22:59","modified_gmt":"2026-08-22T12:22:59","slug":"a-madrid-le-thermometre-des-restaurants-remonte-mais-pas-les-concepts-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/a-madrid-le-thermometre-des-restaurants-remonte-mais-pas-les-concepts-2\/","title":{"rendered":"\u00c0 Madrid, le thermom\u00e8tre des restaurants remonte. Mais pas les concepts."},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\"><span style=\"font-size: 13px\">La reprise \u00e9conomique n&rsquo;est pas juste une histoire de macro-\u00e9conomie ou de tableau Excel. Les impressions que l&rsquo;on ressent dans la rue ou dans les restaurants constituent \u00e9galement un v\u00e9ritable thermom\u00e8tre. \u00c0 en croire les professionnels du secteur, ils remplissent \u00e0 nouveau leurs salles. Mais Barcelone a pris de l\u2019avance.\u00a0<\/span>La confiance est revenue et la reprise est bien l\u00e0. Et les financiers qui ont l\u2019habitude d\u2019\u00e9valuer les actions en fonction de la confiance des march\u00e9s, en connaissent les r\u00e9percutions. Standard and Poors vient de monter la note de l\u2019Espagne, non\u202f? <strong>Les restaurants se remplissent de nouveau en semaine.<\/strong> Mais, en Espagne, le thermom\u00e8tre n\u2019est-il pas dans la rue\u202f? Un pays dont le taux de p\u00e9n\u00e9tration des Smartphones est l\u2019un des plus \u00e9lev\u00e9s d\u2019Europe et dont la vie et le business se font plus dans la rue que derri\u00e8re l\u2019ordinateur n\u2019est-il pas assujetti \u00e0 l\u2019ambiance de celle-ci\u202f? La r\u00e9alit\u00e9 est tr\u00e8s simple\u202f: ceux qui fr\u00e9quentent r\u00e9guli\u00e8rement les bars \u00e0 tapas des quartiers chics ou des quartiers d\u2019affaires (ceux de Sol n\u2019ont cependant jamais d\u00e9sempli) savent que le vent tourne. Ils se remplissent \u00e0 nouveau d\u00e8s le mercredi, voire le mardi. Il suffit de regarder autour de soi. Les premiers concern\u00e9s, les patrons de ces bars, l\u2019ont remarqu\u00e9 depuis septembre. <strong>\u00c0 Madrid, il est devenu de bon ton de calculer.<\/strong> Il faut dire que les restaurants de Madrid, bien plus conservateurs que ceux de Barcelone dans leur gestion, se sont un peu r\u00e9organis\u00e9s. Ils ont compris qu\u2019il valait mieux vendre beaucoup de \u00ab\u202fpaniers moyens\u202f\u00bb que quelques repas hors de prix. Ainsi, l\u2019historique de la brasserie Espejo de la Castellana de la place Col\u00f3n propose des menus \u00e0 10 euros \u00e0 midi. Impensable il y a encore 2 ans\u202f! Ou encore ce restaurant italien plut\u00f4t chic, Lucca, rue Ortega y Gasset, qui propose des menus \u00e0 15 euros (entr\u00e9e, plat et dessert) et o\u00f9 l\u2019on y croise tous les Country Managers \u00e9trangers. Les restaurants de Madrid s\u2019alignent enfin sur ceux de Barcelone\u202f! Ils ont compris que si la client\u00e8le est ais\u00e9e, c\u2019est tout simplement parce qu\u2019elle fait aussi attention \u00e0 ses d\u00e9penses. Aujourd\u2019hui \u00e0 Madrid, il est enfin de bon ton de calculer. Surtout au niveau des entreprises. <strong>La diversification est bien plus riche \u00e0 Barcelone qu\u2019\u00e0 Madrid.<\/strong> Si les restaurants de Madrid se remplissent de nouveau, la diversit\u00e9 de l\u2019offre est loin, tr\u00e8s loin derri\u00e8re sa rivale, Barcelone. La faible offre h\u00f4teli\u00e8re de Madrid ne s\u00e9duit pas les investisseurs de l\u2019h\u00f4tellerie. Une chose est claire, celui qui vient tous les mois pour affaires&#8230; va vite s\u2019ennuyer \u00e0 Madrid. Pas de nouveaux restaurants, hormis quelques nouveaux pseudos asiatiques chill out rue Serrano, pas de nouveaux palaces, aucun nouvel h\u00f4tel 5 \u00e9toiles depuis 10 ans, et surtout, aucune originalit\u00e9 au niveau des concepts. Le seul \u00e0 avoir innov\u00e9 depuis 10 ans, c\u2019est Ten Con Ten, rue Hermosilla. D\u2019ailleurs, il est affiche complet tous les soirs. Un peu plus exotique, ce nouveau restaurant russe Fishka, toujours bien fr\u00e9quent\u00e9. C\u00f4t\u00e9 bars\/bo\u00eetes de nuit, n\u2019en parlons m\u00eame plus, c\u2019est le n\u00e9ant total dans la capitale espagnole. Les seuls qui existent sont r\u00e9serv\u00e9s aux \u00e9tudiants. Incomparable avec des villes telles que New York ou m\u00eame Kiev, o\u00f9 de v\u00e9ritables complexes restaurants\/bars\/bo\u00eetes sont ouverts 24h\/24, c\u2019est le jour et la nuit. La Movida doit \u00eatre culturelle. La culture espagnole et l\u2019avantage comparatif des villes se jouent sur le terrain de la Movida, de la capacit\u00e9 pour une ville \u00e0 vivre le soir et animer ses touristes \u00e0 sortir. Pendant la crise, Barcelone s\u2019est impos\u00e9e en mati\u00e8re de sorties et les m\u00e9dias du monde entier y r\u00e9alisent plus de reportages qu\u2019\u00e0 Madrid. Il semble que les autorit\u00e9s de Madrid n\u2019ont pas encore compris ce que peut repr\u00e9senter pour une ville sa capacit\u00e9 \u00e0 faire profiter et impressionner ses visiteurs, qu\u2019ils viennent pour affaires ou loisirs. Le tourisme a baiss\u00e9 de 11% \u00e0 Madrid cette ann\u00e9e et il serait temps que la capitale espagnole se r\u00e9veille. PC- (Photo Julia Robles pour WOMMs)<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La reprise \u00e9conomique n&rsquo;est pas juste une histoire de macro-\u00e9conomie ou de tableau Excel. Les impressions que l&rsquo;on ressent dans la rue ou dans les restaurants constituent \u00e9galement un v\u00e9ritable thermom\u00e8tre. \u00c0 en croire les professionnels du secteur, ils remplissent \u00e0 nouveau leurs salles. Mais Barcelone a pris de l\u2019avance.\u00a0La confiance est revenue et la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-74472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74472"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44308"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}