{"id":74457,"date":"2026-03-22T19:11:36","date_gmt":"2026-03-22T19:11:36","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/vodafone-rachete-ono-au-prix-de-72-milliards-deuros-2\/"},"modified":"2026-08-22T11:34:42","modified_gmt":"2026-08-22T11:34:42","slug":"vodafone-rachete-ono-au-prix-de-72-milliards-deuros-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/vodafone-rachete-ono-au-prix-de-72-milliards-deuros-2\/","title":{"rendered":"Vodafone rach\u00e8te ONO au prix de 7,2 milliards d&rsquo;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">&nbsp;  Vodafone annonce ce lundi matin le rachat de l&rsquo;espagnole ONO pour 7.200 milliards d&rsquo;euros. Le prix propos\u00e9 est 10,5 fois l&rsquo;EBITDA de 2013, situ\u00e9 \u00e0 686 millions d&rsquo;euros. Gr\u00e2ce \u00e0 cette op\u00e9ration, les actionnaires d&rsquo;ONO recevront 3,8 milliards d\u2019euros en \u00e9change de leurs actions.  En 2005, ONO avait d\u00e9j\u00e0 commenc\u00e9 l&rsquo;internationalisation de son capital en en c\u00e9dant une partie \u00e0 des fonds \u00e9trangers (CCMP, Providence, Thomas H. Lee et Quadrangle).  Avec cette op\u00e9ration, Vodafone ouvre sa porte \u00e0 7,2 millions de foyers suppl\u00e9mentaires.  LCE<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Vodafone annonce ce lundi matin le rachat de l&rsquo;espagnole ONO pour 7.200 milliards d&rsquo;euros. Le prix propos\u00e9 est 10,5 fois l&rsquo;EBITDA de 2013, situ\u00e9 \u00e0 686 millions d&rsquo;euros. Gr\u00e2ce \u00e0 cette op\u00e9ration, les actionnaires d&rsquo;ONO recevront 3,8 milliards d\u2019euros en \u00e9change de leurs actions. En 2005, ONO avait d\u00e9j\u00e0 commenc\u00e9 l&rsquo;internationalisation de son capital [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[332,2951],"class_list":["post-74457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-espagne","tag-ono"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74457"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44239"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}