{"id":74430,"date":"2026-03-22T18:55:38","date_gmt":"2026-03-22T18:55:38","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/un-fonds-de-soros-rachete-un-hotel-a-marbella-pour-214-millions-deuros-2\/"},"modified":"2026-08-22T10:15:57","modified_gmt":"2026-08-22T10:15:57","slug":"un-fonds-de-soros-rachete-un-hotel-a-marbella-pour-214-millions-deuros-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/un-fonds-de-soros-rachete-un-hotel-a-marbella-pour-214-millions-deuros-2\/","title":{"rendered":"Un fonds de Soros rach\u00e8te un h\u00f4tel \u00e0 Marbella pour 21,4 millions d&rsquo;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le fonds d&rsquo;investissement Hispania, pr\u00e9sid\u00e9 par l&rsquo;ancien PDG de Endesa, Rafael Miranda, dont l&rsquo;actionnaire est Georges Soros, vient de racheter un h\u00f4tel \u00e0 Marbella pour une valeur de 21,4 millions d&rsquo;euros.  Il s&rsquo;agit de l&rsquo;h\u00f4tel Guadalmina SPA &amp; Resort de 4 *. L&rsquo;h\u00f4tel jouit d&rsquo;un fort potentiel touristique. Avec 178 chambres, une situation au bord de la mer et un acc\u00e8s direct \u00e0 un terrain de golf, il fait partie des quelques perles de Marbella.  Le fonds Hispania a pr\u00e9sent\u00e9 le mois dernier ses ambitions vis-\u00e0-vis du march\u00e9 espagnol, qui ne manque pas d&rsquo;actifs \u00e0 la vente. Hispania cotise en bourse depuis le 14 mars.  &nbsp;  LCE  &nbsp;<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fonds d&rsquo;investissement Hispania, pr\u00e9sid\u00e9 par l&rsquo;ancien PDG de Endesa, Rafael Miranda, dont l&rsquo;actionnaire est Georges Soros, vient de racheter un h\u00f4tel \u00e0 Marbella pour une valeur de 21,4 millions d&rsquo;euros. Il s&rsquo;agit de l&rsquo;h\u00f4tel Guadalmina SPA &amp; Resort de 4 *. L&rsquo;h\u00f4tel jouit d&rsquo;un fort potentiel touristique. Avec 178 chambres, une situation au bord [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[2262,749,2032,2943],"class_list":["post-74430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hispania","tag-hotel","tag-marbella","tag-soros"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74430"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/44132"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}