{"id":74364,"date":"2026-03-22T17:37:45","date_gmt":"2026-03-22T17:37:45","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/ferrovial-sattribue-les-travaux-dagrandissement-du-metro-de-londres-2\/"},"modified":"2026-08-22T06:23:47","modified_gmt":"2026-08-22T06:23:47","slug":"ferrovial-sattribue-les-travaux-dagrandissement-du-metro-de-londres-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/ferrovial-sattribue-les-travaux-dagrandissement-du-metro-de-londres-2\/","title":{"rendered":"Ferrovial s\u2019attribue les travaux d\u2019agrandissement du m\u00e9tro de Londres"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 9 sep. (EP)  Ferrovial s\u2019est attribu\u00e9 le contrat de travaux d\u2019agrandissement d\u2019une ligne du m\u00e9tro de Londres pour un montant de 500 millions de livres (environ 628 millions d\u2019euros), d\u2019apr\u00e8s l\u2019annonce faite par le groupe.  Avec ce projet, la soci\u00e9t\u00e9 pr\u00e9sid\u00e9e par Rafael del Pino renforce sa pr\u00e9sence d\u00e9j\u00e0 \u00e9minente au Royaume-Uni, puisqu\u2019il constitue le premier march\u00e9 de la soci\u00e9t\u00e9 en mati\u00e8re de revenus, devant l\u2019Espagne.  Le contrat pass\u00e9 avec London Underground consiste en l\u2019ex\u00e9cution, avec le consortium local Laing O&rsquo;Rourke, de l\u2019agrandissement de la ligne Northern Line \u00e0 partir de la station de Kennington, au sud de la ville.  Les travaux comprennent l\u2019excavation d\u2019un tunnel de 6 kilom\u00e8tres de long et de deux stations, dont l\u2019ach\u00e8vement est pr\u00e9vu en 2020.  Gr\u00e2ce \u00e0 cette nouvelle infrastructure, le train de banlieue londonien couvrira une r\u00e9gion o\u00f9 travailleront 25.000 personnes et r\u00e9sideront 16.000 familles, r\u00e9duisant ainsi \u00e0 moins de quinze minutes le trajet jusqu\u2019au West End et la zone d\u2019affaires de la City londonienne.  Avec ce nouveau projet, outre favoriser son activit\u00e9 au Royaume-Uni, Ferrovial renforce son exp\u00e9rience en mati\u00e8re de construction de syst\u00e8mes souterrains de transports, ainsi que se consolide au sein du secteur ferroviaire britannique.  Actuellement, le groupe, \u00e9galement en consortium, participe \u00e0 la construction du Crossrail, une connexion ferroviaire qui circulera sous le centre de la capitale, pour laquelle elle ex\u00e9cute deux tunnels, une station, les acc\u00e8s et les cavit\u00e9s de deux autres stations.  R\u00e9cemment, en outre, elle a remport\u00e9 le fonctionnement et l\u2019entretien pendant six ans et demi du train l\u00e9ger de Londres, le Docklands Light Railway, pour environ 700 millions de livres (870 millions d\u2019euros) et divers contrats d\u2019entretien d\u2019infrastructures ferroviaires ces derniers mois.  Ferrovial se renforce au Royaume-Uni, pays o\u00f9 sa pr\u00e9sence est \u00e9galement \u00e9minente en mati\u00e8re de services et de concessions (elle participe dans l\u2019a\u00e9roport londonien de Heathrow), qui g\u00e9n\u00e8rent actuellement 42% de sa facturation totale, face aux 28% obtenus sur le march\u00e9 domestique. <\/p>\n<div id=\"CuerpoNoticia\">\u00a0 \u00a0EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/div>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 9 sep. (EP) Ferrovial s\u2019est attribu\u00e9 le contrat de travaux d\u2019agrandissement d\u2019une ligne du m\u00e9tro de Londres pour un montant de 500 millions de livres (environ 628 millions d\u2019euros), d\u2019apr\u00e8s l\u2019annonce faite par le groupe. Avec ce projet, la soci\u00e9t\u00e9 pr\u00e9sid\u00e9e par Rafael del Pino renforce sa pr\u00e9sence d\u00e9j\u00e0 \u00e9minente au Royaume-Uni, puisqu\u2019il constitue [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1235,2325,1435],"class_list":["post-74364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-ferrovial","tag-londres","tag-metro"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74364"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/43806"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}