{"id":74338,"date":"2026-03-22T17:15:13","date_gmt":"2026-03-22T17:15:13","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/airbnb-sallie-a-concur-dans-le-domaine-des-voyages-daffaires-2\/"},"modified":"2026-08-22T04:48:56","modified_gmt":"2026-08-22T04:48:56","slug":"airbnb-sallie-a-concur-dans-le-domaine-des-voyages-daffaires-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/airbnb-sallie-a-concur-dans-le-domaine-des-voyages-daffaires-2\/","title":{"rendered":"Airbnb s&rsquo;allie \u00e0 Concur dans le domaine des voyages d&rsquo;affaires"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 15 sep. (EP)  La plate-forme locative Airbnb a annonc\u00e9 sa collaboration avec Concur, soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e en services de gestion de voyages corporatifs, afin de d\u00e9velopper son service de clients &lsquo;business&rsquo;.  D\u2019apr\u00e8s les informations de la compagnie lors d\u2019un communiqu\u00e9, Concur incorporera l\u2019offre d\u2019Airbnb \u00e0 son service TripLink.  Ceci permettra aux voyageurs d\u2019affaires de r\u00e9server des espaces publi\u00e9s sur le Web de la soci\u00e9t\u00e9.  Ainsi, les donn\u00e9es des rapports de frais seront enregistr\u00e9es pr\u00e9alablement et de mani\u00e8re automatique, et les responsables recevront leurs itin\u00e9raires.  La plate-forme, constitu\u00e9e en ao\u00fbt 2008 et dont le si\u00e8ge se trouve en Californie, \u00e0 San Francisco, offre des logements dans plus de 35.000 villes et 192 pays.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 15 sep. (EP) La plate-forme locative Airbnb a annonc\u00e9 sa collaboration avec Concur, soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e en services de gestion de voyages corporatifs, afin de d\u00e9velopper son service de clients &lsquo;business&rsquo;. D\u2019apr\u00e8s les informations de la compagnie lors d\u2019un communiqu\u00e9, Concur incorporera l\u2019offre d\u2019Airbnb \u00e0 son service TripLink. Ceci permettra aux voyageurs d\u2019affaires de r\u00e9server [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43687,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[384],"class_list":["post-74338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74338"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/43687"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}