{"id":74323,"date":"2026-03-22T16:54:34","date_gmt":"2026-03-22T16:54:34","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-jour-mondial-de-la-tapa-demarre-a-madrid-2\/"},"modified":"2026-08-22T04:00:51","modified_gmt":"2026-08-22T04:00:51","slug":"le-jour-mondial-de-la-tapa-demarre-a-madrid-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-jour-mondial-de-la-tapa-demarre-a-madrid-2\/","title":{"rendered":"Le Jour Mondial de la Tapa d\u00e9marre \u00e0 Madrid"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 29 sep. (EP) &#8211;  Madrid comm\u00e9more aujourd\u2019hui la Journ\u00e9e Mondiale de la Tapa lors d\u2019une manifestation organis\u00e9e par la FEHR (F\u00e9d\u00e9ration Espagnole de l\u2019H\u00f4tellerie et de la Restauration) et LA VI\u00d1A (Association d\u2019Entreprises de l\u2019H\u00f4tellerie de la Communaut\u00e9 de Madrid), avec le soutien et la collaboration de Mahou San Miguel.  Cet \u00e9v\u00e8nement inaugural comptera sur la pr\u00e9sence des Pr\u00e9sidents de la FEHR, Jos\u00e9 Mar\u00eda Rubio et de LA VI\u00d1A, Tom\u00e1s Guti\u00e9rrez, le chef r\u00e9put\u00e9 Pedro Larumbe, Pr\u00e9sident de Saborea Espa\u00f1a, ainsi que de nombreuses autorit\u00e9s locales et nationales.  Les quartiers madril\u00e8nes de Salamanca-Retiro r\u00e9v\u00e8leront aujourd\u2019hui le fonctionnement de l\u2019itin\u00e9raire Devora Tapas, une initiative \u00e0 laquelle 52 locaux de cette zone de Madrid se sont joints, qui offriront jusqu\u2019au 12 octobre une tapa pour le prix de 1 euro ou de 2,40 si cette derni\u00e8re est accompagn\u00e9e d\u2019une bouteille de Mahou.  David Mu\u00f1oz, repr\u00e9sentant de la meilleure gastronomie espagnole et seul cuisinier poss\u00e9dant trois \u00e9toiles Michelin, sera le parrain exceptionnel de cet \u00e9v\u00e8nement.  Le Jour Mondial de la Tapa, qui se tient le 29 septembre depuis deux ans, a pour objectif de mettre en valeur \u00ab\u00a0la marque de l\u2019identit\u00e9 gastronomique mondialement reconnue\u00a0: la tapa\u00a0\u00bb.  \u00c0 cette fin, de nombreux \u00e9v\u00e8nements gastronomiques se succ\u00e8deront dans tout le pays au cours des mois de septembre et d\u2019octobre en vue de rendre hommage \u00e0 \u00ab\u00a0la meilleure repr\u00e9sentation de notre gastronomie en miniature\u00a0\u00bb.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 29 sep. (EP) &#8211; Madrid comm\u00e9more aujourd\u2019hui la Journ\u00e9e Mondiale de la Tapa lors d\u2019une manifestation organis\u00e9e par la FEHR (F\u00e9d\u00e9ration Espagnole de l\u2019H\u00f4tellerie et de la Restauration) et LA VI\u00d1A (Association d\u2019Entreprises de l\u2019H\u00f4tellerie de la Communaut\u00e9 de Madrid), avec le soutien et la collaboration de Mahou San Miguel. Cet \u00e9v\u00e8nement inaugural comptera [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43615,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1279,660],"class_list":["post-74323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-gastronomie","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74323"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/43615"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}