{"id":74318,"date":"2026-03-22T16:48:39","date_gmt":"2026-03-22T16:48:39","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/nouvel-hotel-pour-vincci-hoteles-sur-la-gran-via-madrilene-2\/"},"modified":"2026-08-22T03:44:47","modified_gmt":"2026-08-22T03:44:47","slug":"nouvel-hotel-pour-vincci-hoteles-sur-la-gran-via-madrilene-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/nouvel-hotel-pour-vincci-hoteles-sur-la-gran-via-madrilene-2\/","title":{"rendered":"Nouvel h\u00f4tel pour Vincci Hoteles sur la Gran V\u00eda madril\u00e8ne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 30 sep. (EP)  Vincci Hoteles, cha\u00eene sp\u00e9cialis\u00e9e en \u00e9tablissements de quatre et cinq \u00e9toiles, a sign\u00e9 avec le Groupe Generali l\u2019acquisition d\u2019un nouvel h\u00f4tel sur la Gran V\u00eda madril\u00e8ne, au num\u00e9ro 10, portant ainsi \u00e0 trois ses \u00e9tablissements dans l\u2019une des principales rues de Madrid et \u00e0 six les h\u00f4tels dont elle dispose dans la capitale, a inform\u00e9 la compagnie h\u00f4teli\u00e8re.  Gr\u00e2ce \u00e0 cette incorporation, la soci\u00e9t\u00e9 disposera de six h\u00f4tels au total, r\u00e9partis sur la Gran V\u00eda, le Barrio de las Letras et la rue Goya, trois des meilleures zones de Madrid.  L\u2019ouverture de l\u2019h\u00f4tel est pr\u00e9vue d\u00e9but 2016.  Ce dernier comprendra 88 chambres doubles, 10 junior suites parmi elles.  \u00ab\u00a0Ce projet nous rend particuli\u00e8rement heureux car nous agrandissons notre portefeuille, en outre dans l\u2019une des zones les plus importantes de Madrid et dans un immeuble embl\u00e9matique.  Il s\u2019agit, par ailleurs, de l\u2019exemple clair du fait que nous continuons de parier sur la capitale en tant que destination touristique et d\u2019affaires\u00a0\u00bb, \u00a0a affirm\u00e9 le Conseiller D\u00e9l\u00e9gu\u00e9 et Directeur G\u00e9n\u00e9ral de la cha\u00eene, Carlos Calero.  Le Groupe Generali est propri\u00e9taire de l\u2019immeuble et poss\u00e8de en outre 28 autres immeubles en Espagne, ainsi que g\u00e8re, par le biais de Generali Real Estate, 2.500 actifs dans le monde, d\u2019une valeur de march\u00e9 de 28 milliards d\u2019euros.  En qualit\u00e9 de propri\u00e9taire, Generali se chargera de financer un projet complexe de r\u00e9habilitation int\u00e9grale avec changement d\u2019usage (travaux, installations, r\u00e9novation, finitions, etc&#8230;) qui durera 12 mois.  L\u2019Architecte \u00c1ngel Serrano Ceballos et l\u2019ing\u00e9nieur Technique Industriel Antonio P\u00e9rez \u00dabeda se chargeront de r\u00e9aliser les travaux n\u00e9cessaires.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 30 sep. (EP) Vincci Hoteles, cha\u00eene sp\u00e9cialis\u00e9e en \u00e9tablissements de quatre et cinq \u00e9toiles, a sign\u00e9 avec le Groupe Generali l\u2019acquisition d\u2019un nouvel h\u00f4tel sur la Gran V\u00eda madril\u00e8ne, au num\u00e9ro 10, portant ainsi \u00e0 trois ses \u00e9tablissements dans l\u2019une des principales rues de Madrid et \u00e0 six les h\u00f4tels dont elle dispose dans [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[521,2932],"class_list":["post-74318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hotel-madrid","tag-vincci-hoteles"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74318"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/43591"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}