{"id":74269,"date":"2026-03-22T15:58:34","date_gmt":"2026-03-22T15:58:34","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/les-travaux-publics-a-la-hausse-2\/"},"modified":"2026-08-22T01:06:47","modified_gmt":"2026-08-22T01:06:47","slug":"les-travaux-publics-a-la-hausse-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/les-travaux-publics-a-la-hausse-2\/","title":{"rendered":"Les travaux publics \u00e0 la hausse !"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 23 oct. (EP)  Le Minist\u00e8re de l\u2019\u00c9quipement a adjug\u00e9 des contrats de travaux pour un montant de de 667,45 millions d\u2019euros au cours des huit premiers mois de l\u2019ann\u00e9e, 21,5% de plus que lors de la m\u00eame p\u00e9riode en 2013, gr\u00e2ce \u00e0 l\u2019impulsion donn\u00e9e aux projets ferroviaires de Grande Vitesse (AVE) et \u00e0 l\u2019entretien des autoroutes, d\u2019apr\u00e8s les donn\u00e9es du D\u00e9partement.  De janvier \u00e0 ao\u00fbt, le Minist\u00e8re de l\u2019\u00c9quipement a sign\u00e9 des contrats de travaux de lignes AVE pour un montant de 420 millions d\u2019euros, 20% de plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente.  Ainsi, les projets Grande Vitesse ont presque occup\u00e9 les deux tiers (63%) de la totalit\u00e9 des travaux publics adjug\u00e9s par le D\u00e9partement que dirige Ana Pastor au cours des huit premiers mois de l\u2019exercice.  Par ailleurs, les contrats de travaux routiers adjug\u00e9s jusqu\u2019au mois de septembre ont doubl\u00e9 (+117%) et repr\u00e9sentent 118,6 millions d\u2019euros, gr\u00e2ce \u00e0 la reprise de l\u2019investissement en mati\u00e8re de conservation.  De juin \u00e0 ao\u00fbt, le volume de travaux souscrit par Aena a \u00e9galement augment\u00e9 (22,1%), pour repr\u00e9senter 28,4 millions d\u2019euros, tandis que Renfe a quadrupl\u00e9 (+318%) son adjudication de travaux, pour un montant de cinq millions d\u2019euros.  En revanche, Puertos del Estado (Ports de l\u2019\u00c9tat) a r\u00e9duit de 19,9% le volume d\u2019adjudication des travaux, de mani\u00e8re \u00e0 repr\u00e9senter 96 millions d\u2019euros \u00e0 la cl\u00f4ture du mois d\u2019ao\u00fbt dernier.  En ce qui la concerne, la Soci\u00e9t\u00e9 \u00c9tatique d\u2019Infrastructures Terrestres (Seittsa) n\u2019a sign\u00e9 aucun contrat en juillet et cumule plus de deux ans (depuis le mois de juin 2012) sans adjuger de travaux.  Malgr\u00e9 tout, si le Minist\u00e8re de l\u2019\u00c9quipement continue sur sa lanc\u00e9e le reste de l\u2019ann\u00e9e, l\u2019adjudication de travaux \u00e0 la cl\u00f4ture de l\u2019exercice d\u00e9passera la cote de 1.000 millions d\u2019euros pour la premi\u00e8re fois depuis 2009.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 23 oct. (EP) Le Minist\u00e8re de l\u2019\u00c9quipement a adjug\u00e9 des contrats de travaux pour un montant de de 667,45 millions d\u2019euros au cours des huit premiers mois de l\u2019ann\u00e9e, 21,5% de plus que lors de la m\u00eame p\u00e9riode en 2013, gr\u00e2ce \u00e0 l\u2019impulsion donn\u00e9e aux projets ferroviaires de Grande Vitesse (AVE) et \u00e0 l\u2019entretien [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[384,2128,639],"class_list":["post-74269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-business","tag-croissance","tag-investissement"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74269"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/43390"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}