{"id":74248,"date":"2026-03-22T15:38:00","date_gmt":"2026-03-22T15:38:00","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lemploi-touristique-croit-le-taux-de-chomage-descend-2\/"},"modified":"2026-08-21T23:46:57","modified_gmt":"2026-08-21T23:46:57","slug":"lemploi-touristique-croit-le-taux-de-chomage-descend-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/lemploi-touristique-croit-le-taux-de-chomage-descend-2\/","title":{"rendered":"L&#8217;emploi touristique cro\u00eet, le taux de ch\u00f4mage descend"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 30 oct. (EP)  Le nombre de ch\u00f4meurs du secteur touristique espagnol est de 383.275 au troisi\u00e8me trimestre 2014, 20.009 de moins que l\u2019ann\u00e9e pr\u00e9c\u00e9dente, le taux de ch\u00f4mage se repr\u00e9sentant donc 14%, 1,4 points en pourcentage de moins qu\u2019\u00e0 la m\u00eame p\u00e9riode en 2013, d\u2019apr\u00e8s les donn\u00e9es du Sondage sur la Population Active (EPA) diffus\u00e9es par la Sous-direction G\u00e9n\u00e9rale pour la Connaissance et les \u00c9tudes Touristiques.  Ce taux se situe 9,7 points en-dessous de la moyenne du taux de ch\u00f4mage de l\u2019\u00e9conomie nationale, qui repr\u00e9sentait 23,7% au troisi\u00e8me trimestre, par rapport \u00e0 25,7% le m\u00eame trimestre en 2013.  Au troisi\u00e8me trimestre, les personnes employ\u00e9es dans le secteur du tourisme augment\u00e8rent de 6%,1% jusqu\u2019\u00e0 d\u00e9passer 2,35 millions de travailleurs, 123.274 employ\u00e9s de plus, c\u2019est-\u00e0-dire 13,5% de la totalit\u00e9 de l\u2019emploi de l\u2019\u00e9conomie espagnole.  Les activit\u00e9s touristiques comptaient sur 2,7 millions de travailleurs actifs au troisi\u00e8me trimestre, \u00e0 savoir 4,4% de plus que l\u2019ann\u00e9e derni\u00e8re, avec 107.802 personnes de plus qu\u2019il y a un an.  Dans le secteur touristique, les travailleurs ont augment\u00e9 aussi bien en tant que salari\u00e9s (+5,5%), pr\u00e8s de 97.000 personnes de plus, comme en travailleurs ind\u00e9pendants (+8,2%), environ 38.154 employ\u00e9s de plus.  Les salari\u00e9s repr\u00e9sent\u00e8rent 78,5% de la totalit\u00e9, avec 1,85 millions de personnes.  Ces r\u00e9sultats confirment les pr\u00e9visions expos\u00e9es par le Rapport Coyuntur du troisi\u00e8me trimestre, \u00e9labor\u00e9 par le Minist\u00e8re de l\u2019Industrie, de l\u2019\u00c9nergie et du Tourisme, qui pr\u00e9sageait une hausse des affili\u00e9s \u00e0 la S\u00e9curit\u00e9 Sociale associ\u00e9s aux activit\u00e9s touristiques \u00e9galement au cours du quatri\u00e8me trimestre, la tendance positive initi\u00e9e \u00e0 la mi 2013 se poursuivant.  <strong>COMMUNAUT\u00c9S AUTONOMES DONT LE VOLUME D\u2019EMPLOI EST LE PLUS IMPORTANT<\/strong>  Parmi les six communaut\u00e9s autonomes o\u00f9 l\u2019emploi touristique est le plus important, \u00a0\u00e0 souligner\u00a0: la Catalogne (+12,3%), la Communaut\u00e9 de Valence (+10,3%), l\u2019Andalousie (+9,1%) et la Communaut\u00e9 de Madrid (+1,6%).  En revanche, les Bal\u00e9ares (5,6%) et les Canaries (-0,7%) accus\u00e8rent une chute.  Dans le reste des Communaut\u00e9s Autonomes, dans l\u2019ensemble, l\u2019emploi dans le secteur touristique a augment\u00e9 de 5,9%. L\u2019emploi touristique dans les archipels continue d\u2019\u00eatre la cl\u00e9 de leurs \u00e9conomies, \u00e9tant donn\u00e9 que 25,2% des personnes aux Canaries et 29,6% aux Bal\u00e9ares travaillent dans le tourisme, surpassant la moyenne nationale (13,5%).  Dans toutes les communaut\u00e9s principales, aussi bien les salari\u00e9s que les travailleurs ind\u00e9pendants ont augment\u00e9, sous r\u00e9serve des Bal\u00e9ares et des Canaries accusant une chute des salari\u00e9s, et la Communaut\u00e9 de Madrid dont le nombre de travailleurs ind\u00e9pendants a \u00e9galement chut\u00e9.  <strong>LE SECTEUR H\u00d4TELIER CRO\u00ceT DE 5,9%<\/strong>  Par branche d\u2019activit\u00e9, toutes ont enregistr\u00e9 une croissance, bien que la hausse la plus importante ait eu lieu dans d\u2019autres activit\u00e9s touristiques o\u00f9 le nombre de travailleurs a augment\u00e9 de 8,9%, suivies du secteur h\u00f4telier (h\u00e9bergement et restauration), qui r\u00e9ussit \u00e0 cumuler sept mois de hausses, avec une croissance de 5,9% et 84.959 travailleurs de plus.  Concr\u00e8tement, ce secteur a enregistr\u00e9 des hausses dans les services de repas et boissons (+6,9%) et ceux d\u2019h\u00e9bergement (+3%).  Par volume de travailleurs, le pourcentage le plus important se concentre dans la restauration (repas et boissons), \u00e0 savoir 48,6% de la totalit\u00e9.  Le taux de ch\u00f4mage dans le secteur h\u00f4telier repr\u00e9sente 15,8%, tandis que celui du transport de voyageurs s\u2019est \u00e9lev\u00e9 \u00e0 11.837 ch\u00f4meurs de plus, \u00e0 savoir un taux de 4,25%, le plus faible de toutes les branches.  Au cours du troisi\u00e8me trimestre, la Catalogne est la r\u00e9gion qui poss\u00e8de le plus de travailleurs dans ce secteur, avec 410.857 personnes, suivie de l\u2019Andalousie qui emploie 389.435 personnes dans cette industrie, devant la Communaut\u00e9 de Madrid, avec 309.720 travailleurs dans ce secteur.  La Communaut\u00e9 de Valence suit, avec 247.806 travailleurs, puis les Canaries (182.716 travailleurs) et les Bal\u00e9ares (157.550 travailleurs).  <strong>TEMPORALIT\u00c9 DE 38,2%<\/strong>  Le taux de temporalit\u00e9 dans le secteur touristique (proportion de salari\u00e9s en CDD) a repr\u00e9sent\u00e9 38,2% au troisi\u00e8me trimestre, sup\u00e9rieur \u00e0 celui de l\u2019ann\u00e9e derni\u00e8re (37,6%), par rapport \u00e0 un taux de temporalit\u00e9 de l\u2019\u00e9conomie de 24,6%.  Le rapport attribue ce chiffre \u00e0 la croissance interannuelle des salari\u00e9s temporaires (+7,3%).  L\u2019emploi temporaire a augment\u00e9 dans toutes les branches, sous r\u00e9serve de celle du transport de voyageurs (-7%), branche qui enregistre les taux de temporalit\u00e9 les plus faibles (18,8%).  Par branche d\u2019activit\u00e9, le transport de voyageurs enregistre la plus forte hausse de salari\u00e9s en CDD, avec une croissance de 37,6%, bien que cette branche soit celle o\u00f9 le taux de temporalit\u00e9 soit le plus faible (20,7%).  Pour le troisi\u00e8me trimestre cons\u00e9cutif, les salari\u00e9s en CDI dans le secteur touristique ont augment\u00e9 jusqu\u2019\u00e0 4,4%.  Par branches, les personnes en CDI ont augment\u00e9 dans l\u2019h\u00f4tellerie (+4,8%), le transport (+0,8%) et autres activit\u00e9s (+5,65).  Les travailleurs \u00e9trangers dans le secteur touristique espagnol ont baiss\u00e9 de 1,1% (4.667 travailleurs de moins) au troisi\u00e8me trimestre, repr\u00e9sentant 421.581 travailleurs, \u00e0 savoir 17,9% de l\u2019emploi total dans le secteur touristique.  82,7% \u00e9taient salari\u00e9s &#8212; 6,1% de moins&#8211; et 17,3% travailleurs ind\u00e9pendants, \u00e0 savoir 31,5%.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 30 oct. (EP) Le nombre de ch\u00f4meurs du secteur touristique espagnol est de 383.275 au troisi\u00e8me trimestre 2014, 20.009 de moins que l\u2019ann\u00e9e pr\u00e9c\u00e9dente, le taux de ch\u00f4mage se repr\u00e9sentant donc 14%, 1,4 points en pourcentage de moins qu\u2019\u00e0 la m\u00eame p\u00e9riode en 2013, d\u2019apr\u00e8s les donn\u00e9es du Sondage sur la Population Active (EPA) [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42897,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[384,2128,270,660],"class_list":["post-74248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-business","tag-croissance","tag-hotels","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74248"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42897"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}