{"id":74172,"date":"2026-03-22T14:18:38","date_gmt":"2026-03-22T14:18:38","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-mexique-sera-le-pays-que-nous-supporterons-le-plus-2\/"},"modified":"2026-08-21T19:48:51","modified_gmt":"2026-08-21T19:48:51","slug":"le-mexique-sera-le-pays-que-nous-supporterons-le-plus-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/le-mexique-sera-le-pays-que-nous-supporterons-le-plus-2\/","title":{"rendered":"\u00ab\u00a0Le Mexique sera le pays que nous supporterons le plus\u00a0\u00bb"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">La Pr\u00e9sidente de Banco Santander a confirm\u00e9 que le groupe fait du Mexique une priorit\u00e9, en y investissant plus de 15 milliards de dollars les 4 prochaines ann\u00e9es. 10 milliards seraient allou\u00e9s aux infrastructures et 5 milliards en cr\u00e9dits pour les PME. \u00a0Banco Santander a plus de 3.500 employ\u00e9s au Mexique. La banque va aussi investir 10 milliards dans les infrastructures au Br\u00e9sil. La pr\u00e9sence des entreprises du secteur bancaire et de la construction en Am\u00e9rique Latine n&rsquo;est pas nouvelle. Depuis une quinzaine d&rsquo;ann\u00e9es, les grandes entreprises de l&rsquo;IBEX y ont fortement investi, contrairement aux autres pays europ\u00e9ens, et r\u00e9coltent aujourd&rsquo;hui le fruit de ces investissements dans ce continent \u00e9mergeant. L&rsquo;IBEX repr\u00e9sente 30% des b\u00e9n\u00e9fices des entreprises l&rsquo;IBEX. R\u00e9cemment, Carlos Slim, la\u00a0premi\u00e8re fortune mexicaine et mondiale, vient d&rsquo;annoncer la prise de contr\u00f4le de 49% de FCC, l\u2019un des principaux constructeurs espagnols. Il est fort probable que via ses filiales ou participations en Am\u00e9rique latine, l&rsquo;Espagne ait son mot \u00e0 dire en mati\u00e8re de futurs investissements en Europe provenant de ce continent. Banco Santander poss\u00e8de \u00e9galement des participations dans\u00a0Buenos Aires, S.A. (Argentine, 7,57\u00a0%), Banco De Galicia y Buenos Aires, S.A. (Argentine, 7,57\u00a0%),\u00a0CommerzBank\u00a0(Allemagne, 4\u00a0%), la Soci\u00e9t\u00e9 G\u00e9n\u00e9rale\u00a0(France, 1,5\u00a0%), ainsi que dans les m\u00e9dias comme Antena3 (Espagne, 30,21\u00a0%). En octobre 2014, elle a aussi annonc\u00e9 qu\u2019elle r\u00e9cup\u00e8rerait 88% du capital de sa filiale br\u00e9silienne.<\/p>\n<p class=\"entradilla\">Philippe Chevassus<\/p>\n<p class=\"entradilla\">\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pr\u00e9sidente de Banco Santander a confirm\u00e9 que le groupe fait du Mexique une priorit\u00e9, en y investissant plus de 15 milliards de dollars les 4 prochaines ann\u00e9es. 10 milliards seraient allou\u00e9s aux infrastructures et 5 milliards en cr\u00e9dits pour les PME. \u00a0Banco Santander a plus de 3.500 employ\u00e9s au Mexique. La banque va aussi [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42995,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[866,2214],"class_list":["post-74172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-mexique","tag-santander"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74172"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42995"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}