{"id":74165,"date":"2026-03-22T14:13:04","date_gmt":"2026-03-22T14:13:04","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/air-europa-inaugure-son-nouveau-trajet-madrid-ouarzazate-maroc-2\/"},"modified":"2026-08-21T19:17:14","modified_gmt":"2026-08-21T19:17:14","slug":"air-europa-inaugure-son-nouveau-trajet-madrid-ouarzazate-maroc-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/air-europa-inaugure-son-nouveau-trajet-madrid-ouarzazate-maroc-2\/","title":{"rendered":"Air Europa inaugure son nouveau trajet Madrid-Ouarzazate (Maroc)"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 11 d\u00e9c. (EP)  Air Europa a inaugur\u00e9 hier son nouveau trajet au d\u00e9part de l\u2019a\u00e9roport Adolfo Su\u00e1rez Madrid-Barajas et \u00e0 l\u2019arriv\u00e9e \u00e0 Ouarzazate, au Maroc, vol qui sera mis en service deux fois par semaine, a inform\u00e9 la compagnie a\u00e9rienne du Groupe Globalia.  La compagnie a\u00e9rienne op\u00e9rera ce nouveau trajet qui reliera la capitale d\u2019Espagne au joyau touristique du Maroc, consid\u00e9r\u00e9 comme la \u00ab\u00a0porte du d\u00e9sert\u00a0\u00bb, avec un avion \u00a0Embraer 145 d\u2019une capacit\u00e9 pour 50 passagers, d\u2019o\u00f9 elle pourra connecter avec son r\u00e9seau de destinations en Europe et Am\u00e9rique.  La nouvelle route Madrid-Ouarzazate fonctionnera le jeudi, au d\u00e9part de Madrid \u00e0 11 heures 20, arriv\u00e9e \u00e0 la ville marocaine \u00e0 12 heures 50, puis partira de cette derni\u00e8re \u00e0 13 heures 35 afin d\u2019atterrir \u00e0 l\u2019a\u00e9roport d\u2019Adolfo Su\u00e1rez Madrid-Barajas \u00e0 17 heures.  Le dimanche, le d\u00e9part s\u2019effectuera \u00e0 14 heures de Madrid, arriv\u00e9e \u00e0 15 heures 30, puis d\u00e9part de nouveau \u00e0 16 heures 05 afin d\u2019arriver \u00e0 Madrid \u00e0 19 heures 30.  \u00ab\u00a0En deux heures et demie \u00e0 peine, il est possible de d\u00e9couvrir une r\u00e9alit\u00e9 totalement diff\u00e9rente, marqu\u00e9e par une culture \u00e9pur\u00e9e, un climat b\u00e9nin et la traditionnelle hospitalit\u00e9 du peuple marocain\u00a0\u00bb, a soulign\u00e9 le Directeur des Relations Institutionnelles d\u2019Air Europa, Manuel Panadero, lors de l\u2019arriv\u00e9e du vol d\u2019inauguration.  Par ailleurs, le Directeur de l\u2019Office du Tourisme du Maroc en Espagne, Mohamed Sofi, a qualifi\u00e9 Ouarzazate comme la \u00ab\u00a0crois\u00e9e des chemins\u00a0\u00bb entre les vall\u00e9es du Draa, du Dades et du Ziz, outre \u00eatre le gardien des tr\u00e9sors les plus recherch\u00e9s par les grands de Hollywood, de par sa luminosit\u00e9 exceptionnelle et ses d\u00e9cors naturels\u00a0\u00bb.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 11 d\u00e9c. (EP) Air Europa a inaugur\u00e9 hier son nouveau trajet au d\u00e9part de l\u2019a\u00e9roport Adolfo Su\u00e1rez Madrid-Barajas et \u00e0 l\u2019arriv\u00e9e \u00e0 Ouarzazate, au Maroc, vol qui sera mis en service deux fois par semaine, a inform\u00e9 la compagnie a\u00e9rienne du Groupe Globalia. La compagnie a\u00e9rienne op\u00e9rera ce nouveau trajet qui reliera la capitale [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42194,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[897,2847,384,660],"class_list":["post-74165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-aeroports","tag-barajas","tag-business","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74165"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42194"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}