{"id":74148,"date":"2026-03-22T13:52:16","date_gmt":"2026-03-22T13:52:16","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/gap-debarque-en-espagne-avec-son-premier-magasin-dans-laeroport-de-malaga-2\/"},"modified":"2026-08-21T18:29:52","modified_gmt":"2026-08-21T18:29:52","slug":"gap-debarque-en-espagne-avec-son-premier-magasin-dans-laeroport-de-malaga-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/gap-debarque-en-espagne-avec-son-premier-magasin-dans-laeroport-de-malaga-2\/","title":{"rendered":"Gap d\u00e9barque en Espagne avec son premier magasin dans l&rsquo;a\u00e9roport de M\u00e1laga"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 9 jan. 2015 (EP)  Gap, la cha\u00eene de mode nord-am\u00e9ricaine d\u00e9barque finalement cette ann\u00e9e en Espagne avec son premier magasin, situ\u00e9 au T3 de l\u2019a\u00e9roport de M\u00e1laga-Costa del Sol, d\u2019apr\u00e8s les informations de la soci\u00e9t\u00e9 de &lsquo;retail&rsquo; a\u00e9roportuaire, Dufry.  L\u2019enseigne textile, qui compte d\u00e9j\u00e0 sur un magasin en ligne en Espagne, inaugure ainsi son premier \u00e9tablissement dans le pays, un march\u00e9 sur lequel elle pourrait entrer avec un nombre encore plus important de magasins au cours de cette ann\u00e9e de la main d\u2019El Corte Ingl\u00e9s.  Par ailleurs, Gap a pr\u00e9sent\u00e9 les chiffres de vente de la campagne de No\u00ebl, avec une hausse de 4% au cours des mois de novembre et de d\u00e9cembre.  La soci\u00e9t\u00e9 nord-am\u00e9ricaine, propri\u00e9taire entre autres des marques GAP, Old Navy et Banana Republic, parie sur l\u2019ouverture des march\u00e9s internationaux et le positionnement au sein du secteur textile, o\u00f9 elle occupe la troisi\u00e8me place \u00e0 \u00e9chelle mondiale, avec pr\u00e8s de 3.500 magasins, derri\u00e8re Inditex et H&amp;M.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 9 jan. 2015 (EP) Gap, la cha\u00eene de mode nord-am\u00e9ricaine d\u00e9barque finalement cette ann\u00e9e en Espagne avec son premier magasin, situ\u00e9 au T3 de l\u2019a\u00e9roport de M\u00e1laga-Costa del Sol, d\u2019apr\u00e8s les informations de la soci\u00e9t\u00e9 de &lsquo;retail&rsquo; a\u00e9roportuaire, Dufry. L\u2019enseigne textile, qui compte d\u00e9j\u00e0 sur un magasin en ligne en Espagne, inaugure ainsi son [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[895,384],"class_list":["post-74148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-aeroport","tag-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74148"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42893"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}