{"id":74140,"date":"2026-03-22T13:47:43","date_gmt":"2026-03-22T13:47:43","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/air-europa-compagnie-aerienne-officielle-du-carnaval-de-salvador-de-bahia-2\/"},"modified":"2026-08-21T17:57:55","modified_gmt":"2026-08-21T17:57:55","slug":"air-europa-compagnie-aerienne-officielle-du-carnaval-de-salvador-de-bahia-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/air-europa-compagnie-aerienne-officielle-du-carnaval-de-salvador-de-bahia-2\/","title":{"rendered":"Air Europa : compagnie a\u00e9rienne officielle du carnaval de Salvador de Bahia"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid (EP)  Air Europa, la compagnie a\u00e9rienne du Groupe Globalia a pass\u00e9 un accord avec la Mairie de Salvador de Bahia (Br\u00e9sil) afin d&rsquo;\u00eatre la compagnie a\u00e9rienne officielle du carnaval 2015 de cette ville br\u00e9silienne.  L\u2019accord a pr\u00e9vu\u00a0la pr\u00e9sence d\u2019Air Europa dans toutes les activit\u00e9s du carnaval qui, chaque ann\u00e9e, attire plus d\u2019un demi-million de visiteurs provenant du monde entier.  Le carnaval de Bahia, \u00e0 diff\u00e9rence de celui de Rio de Janeiro, isol\u00e9 dans l\u2019enceinte du samb\u00f3dromo, se tient dans les rues de la ville et son acc\u00e8s est gratuit pour tous entre le 12 et le 17 f\u00e9vrier.  Deux millions de personnes ont profit\u00e9\u00a0des actes programm\u00e9s tout au long de 25 kilom\u00e8tres de rues et d\u2019avenues, parmi eux, 400 repr\u00e9sentations musicales et 250 heures de diffusion t\u00e9l\u00e9vis\u00e9e.  La tradition veut que les plus grands de la musique br\u00e9silienne, comme Carlinhos Brown, Gilberto Gil et beaucoup d\u2019autres, habituels des concerts ambulants, se donnent rendez-vous \u00e0 Salvador.  \u00ab\u00a0\u00catre la vedette de cet \u00e9v\u00e8nement d\u2019envergure mondiale a offert\u00a0une extraordinaire visibilit\u00e9 \u00e0 notre compagnie, \u00e0 un moment de nette expansion sur le continent am\u00e9ricain et le Br\u00e9sil plus particuli\u00e8rement\u00a0\u00bb, a assur\u00e9 le Directeur G\u00e9n\u00e9ral de la compagnie au Br\u00e9sil, Enrique Mart\u00edn-Ambrosio.  <strong>PROMOTION D\u2019AIR EUROPA AU BR\u00c9SIL<\/strong>  Air Europa vole depuis maintenant 11 ans entre Madrid et Salvador de Bahia.  Depuis le mois de d\u00e9cembre 2013, elle vole \u00e9galement cinq fois par semaine \u00e0 Sao Paulo, un trajet qui deviendra quotidien \u00e0 compter du mois de mai prochain.  En un peu plus d\u2019un an, elle est pass\u00e9e de trois vols hebdomadaires \u00e0 13.  L\u2019accord sign\u00e9 entre Enrique Martin-Ambrosio et le maire de la ville, ACM Neto, envisage la pr\u00e9sence du logo d\u2019Air Europa sur tout le mobilier urbain et les actions relatives au carnaval, ainsi que la d\u00e9coration des rues et les informations dans les moyens de communication.  Air Europa, quant \u00e0 elle, peindra l\u2019un de ses avions avec des sc\u00e8nes ayant trait au carnaval de Bahia et d\u00e9veloppera des actions promotionnelles en 2015 afin d\u2019attirer les touristes \u00e0 Salvador.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid (EP) Air Europa, la compagnie a\u00e9rienne du Groupe Globalia a pass\u00e9 un accord avec la Mairie de Salvador de Bahia (Br\u00e9sil) afin d&rsquo;\u00eatre la compagnie a\u00e9rienne officielle du carnaval 2015 de cette ville br\u00e9silienne. L\u2019accord a pr\u00e9vu\u00a0la pr\u00e9sence d\u2019Air Europa dans toutes les activit\u00e9s du carnaval qui, chaque ann\u00e9e, attire plus d\u2019un demi-million de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42861,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[894,384,660],"class_list":["post-74140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-bresil","tag-business","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74140"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42861"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}