{"id":74064,"date":"2026-03-22T12:22:18","date_gmt":"2026-03-22T12:22:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/talgo-signe-un-accord-avec-la-societe-turque-albayrak-afin-dentrer-dans-le-pays-2\/"},"modified":"2026-08-21T13:59:48","modified_gmt":"2026-08-21T13:59:48","slug":"talgo-signe-un-accord-avec-la-societe-turque-albayrak-afin-dentrer-dans-le-pays-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/talgo-signe-un-accord-avec-la-societe-turque-albayrak-afin-dentrer-dans-le-pays-2\/","title":{"rendered":"Talgo signe un accord avec la soci\u00e9t\u00e9 turque Albayrak afin d&rsquo;entrer dans le pays"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 5 mar. (EP)  Talgo a sign\u00e9 un accord avec le groupe turc Albayrak dans le cadre de la strat\u00e9gie du fabricant ferroviaire espagnol d\u2019entrer en Turquie, un march\u00e9 qu\u2019il consid\u00e8re \u00ab\u00a0tr\u00e8s important\u00a0\u00bb, \u00e9tant donn\u00e9 les projets ferroviaires Grande Vitesse (AVE) pr\u00e9vus dans ce pays.  En vertu de cet accord, Talgo et Albayrak, gr\u00e2ce \u00e0 sa filiale turque T\u00fcmosan, ont convenu de d\u00e9velopper des projets de mani\u00e8re conjointe et de c\u00e9der les technologies afin de se positionner au sein de ces projets.  Talgo consid\u00e8re que l\u2019alliance avec cette compagnie lui ouvre de \u00ab\u00a0grandes possibilit\u00e9s dans ce pays\u00a0\u00bb, o\u00f9 elle cherche \u00e0 se positionner dans le cadre de la strat\u00e9gie d\u2019internationalisation qu\u2019elle m\u00e8ne \u00e0 bien depuis des ann\u00e9es.  Dans le cadre de cette politique, Talgo a de nouveau \u00e9t\u00e9 pr\u00e9sente cette ann\u00e9e lors du salon &lsquo;Euroasia Rail&rsquo;, qui se tient \u00e0 Istanbul.  D\u2019apr\u00e8s la compagnie au cours d\u2019un communiqu\u00e9, lors du concours, le Ministre des Transports turc, L\u00fcti Elvan, a visit\u00e9 le stand du fabricant o\u00f9 il a pu prendre connaissance \u00ab\u00a0des derniers d\u00e9veloppements\u00a0\u00bb de la compagnie.  Talgo a pr\u00e9sent\u00e9 lors de ce salon son \u00ab\u00a0clou du spectacle\u00a0\u00bb, l\u2019Avril, le train tr\u00e8s grande vitesse et capacit\u00e9 tr\u00e8s \u00e9lev\u00e9e que la compagnie a d\u00e9velopp\u00e9.  Le v\u00e9hicule peut transporter 600 passagers au maximum gr\u00e2ce \u00e0 l\u2019incorporation d\u2019une rang\u00e9e de si\u00e8ges additionnelle en clase touriste.  En outre, les acc\u00e8s au train sont au m\u00eame niveau que les plates-formes et les quais, ce qui am\u00e9liore l\u2019accessibilit\u00e9 des passagers handicap\u00e9s et contribue \u00e0 r\u00e9duire de 20% les d\u00e9lais lors d\u2019arr\u00eats interm\u00e9diaires.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 5 mar. (EP) Talgo a sign\u00e9 un accord avec le groupe turc Albayrak dans le cadre de la strat\u00e9gie du fabricant ferroviaire espagnol d\u2019entrer en Turquie, un march\u00e9 qu\u2019il consid\u00e8re \u00ab\u00a0tr\u00e8s important\u00a0\u00bb, \u00e9tant donn\u00e9 les projets ferroviaires Grande Vitesse (AVE) pr\u00e9vus dans ce pays. En vertu de cet accord, Talgo et Albayrak, gr\u00e2ce \u00e0 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42532,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[580,384],"class_list":["post-74064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-ave","tag-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74064"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42532"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}