{"id":74030,"date":"2026-03-22T11:33:11","date_gmt":"2026-03-22T11:33:11","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/acs-ferrovial-et-fcc-se-disputent-un-troncon-de-lave-aux-etats-unis-2\/"},"modified":"2026-08-21T11:52:51","modified_gmt":"2026-08-21T11:52:51","slug":"acs-ferrovial-et-fcc-se-disputent-un-troncon-de-lave-aux-etats-unis-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/22\/acs-ferrovial-et-fcc-se-disputent-un-troncon-de-lave-aux-etats-unis-2\/","title":{"rendered":"ACS, Ferrovial et FCC se disputent un tron\u00e7on de l&rsquo;AVE aux \u00c9tats-Unis"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 21 avr. (EP)  ACS, Ferrovial et le consortium compos\u00e9 par FCC et Isolux sont en concurrence pour le march\u00e9 de travaux de construction d\u2019un nouveau tron\u00e7on de la ligne ferroviaire Grande Vitesse qui reliera Los Angeles et San Francisco, et qui sera le premier AVE aux \u00c9tats-Unis.  Les groupes espagnols sont \u00e0 la t\u00eate de trois des cinq consortiums que la California High-Speed, autorit\u00e9 promotrice du projet, a invit\u00e9s \u00e0 pr\u00e9senter une offre afin de remporter le march\u00e9.  Les soci\u00e9t\u00e9s espagnoles ench\u00e9rissent pour ce march\u00e9 apr\u00e8s qu\u2019ACS ait obtenu le premier march\u00e9 relatif \u00e0 cet AVE au mois de d\u00e9cembre dernier.  Concr\u00e8tement, la soci\u00e9t\u00e9 pr\u00e9sid\u00e9e par Forentino P\u00e9rez a obtenu le deuxi\u00e8me tron\u00e7on de la ligne, un trac\u00e9 de l\u2019AVE de 65 milles (105 kilom\u00e8tres de longueur environ), qui relie Fresno et le nord de Bakersfield, \u00e0 Central Valley, \u00e9valu\u00e9 en 1.000 milliards d\u2019euros.  \u00c0 cette occasion, les grands groupes constructeurs espagnols ench\u00e9rissent afin d\u2019ex\u00e9cuter le quatri\u00e8me tron\u00e7on, un trac\u00e9 de 35 kilom\u00e8tres de long qui reliera les villes de Wasco et Shafter, a inform\u00e9 la California High-Speed au cours d\u2019un communiqu\u00e9.  Le march\u00e9 est d\u2019un montant de 400 \u00e0 500 millions de dollars (de 374 \u00e0 468 millions d\u2019euros).  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 21 avr. (EP) ACS, Ferrovial et le consortium compos\u00e9 par FCC et Isolux sont en concurrence pour le march\u00e9 de travaux de construction d\u2019un nouveau tron\u00e7on de la ligne ferroviaire Grande Vitesse qui reliera Los Angeles et San Francisco, et qui sera le premier AVE aux \u00c9tats-Unis. Les groupes espagnols sont \u00e0 la t\u00eate [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[580,384],"class_list":["post-74030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-ave","tag-business"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74030"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42366"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}