{"id":74002,"date":"2026-03-18T09:22:19","date_gmt":"2026-03-18T09:22:19","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/le-transport-est-aux-avant-postes-pour-les-anticipations-de-tendances-economiques-2\/"},"modified":"2026-08-21T11:04:52","modified_gmt":"2026-08-21T11:04:52","slug":"le-transport-est-aux-avant-postes-pour-les-anticipations-de-tendances-economiques-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/le-transport-est-aux-avant-postes-pour-les-anticipations-de-tendances-economiques-2\/","title":{"rendered":"Le transport est aux avant-postes pour les anticipations de tendances \u00e9conomiques"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p style=\"text-align: justify\"><em> <img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/stephane-e1430748137479.jpg\"> St\u00e9phane de Creisquer, CEO, Volvo Espagne<\/em><\/p>\n<p style=\"text-align: justify\">St\u00e9phane de Creisquer fait partie de ces fran\u00e7ais influents en Espagne et \u00e0 la t\u00eate de filiales de grands groupes. C&rsquo;est le patron de Volvo Espagne, il\u00a0dirige plus de 800 employ\u00e9s. La reprise \u00e9conomique est plus qu&rsquo;une r\u00e9alit\u00e9 pour St\u00e9phane de Creisquer. D&rsquo;ailleurs, la construction et le transport sont\u00a0selon lui les principaux barom\u00e8tres.<\/p>\n<p style=\"text-align: justify\"><strong>La reprise \u00e9conomique\u00a0est bien pr\u00e9sente, comment\u00a0se caract\u00e9rise-t-elle\u00a0dans votre secteur?<\/strong> Le secteur du transport routier\u00a0est fortement corr\u00e9l\u00e9 \u00e0 la situation\u00a0macro\u00e9conomique : en\u00a0effet lorsque la consommation\u00a0est plus forte, il y a plus de\u00a0marchandises \u00e0 transporter et\u00a0inversement. Apr\u00e8s 7 ann\u00e9es\u00a0de dure crise \u00e9conomique en\u00a0Espagne, nous voyons enfin\u00a0des am\u00e9liorations notables en\u00a0terme d\u2019indicateurs \u00e9conomiques\u00a0et de confiance des investisseurs.\u00a0Dans notre secteur,\u00a0cela se traduit par plus de marchandises\u00a0dans les camions, et\u00a0donc par plus de commandes\u00a0de v\u00e9hicules. A fin Mars 2015,\u00a0le march\u00e9 des v\u00e9hicules industriels\u00a0est en hausse de 25% !<\/p>\n<p style=\"text-align: justify\"><strong>Peut-on dire qu&rsquo;il repr\u00e9sente\u00a0avec la construction\u00a0un des principaux\u00a0thermom\u00e8tres?<\/strong> En effet, le secteur du transport\u00a0est aux avant-postes\u00a0pour les anticipations de tendances\u00a0\u00e9conomiques ; apr\u00e8s\u00a0la construction, nous sommes\u00a0les deuxi\u00e8mes \u00e0 descendre en\u00a0temps de crise, les deuxi\u00e8mes\u00a0\u00e0 remonter en temps de reprise.\u00a0Autant dire que le fait de voir\u00a0\u00e0 nouveau des grues et plus\u00a0de camions sur les routes en\u00a0Espagne est un sympt\u00f4me positif.<\/p>\n<p style=\"text-align: justify\"><strong>Vous avez annonc\u00e9 il y\u00a0a peu une nouvelle organisation\u00a0dans votre\u00a0groupe, avec Renault\u00a0entre autres, vous pouvez\u00a0nous en dire plus?<\/strong> Notre industrie a beaucoup\u00a0souffert de cette crise ! La chute\u00a0de la consommation est arriv\u00e9e\u00a0\u00e0 une vitesse foudroyante. En Espagne, le march\u00e9 du\u00a0v\u00e9hicule industriel a baiss\u00e9 de\u00a060% en 24 mois ! Comment\u00a0peut-on s\u2019adapter aussi rapidement\u00a0dans un secteur qui\u00a0allie des processus industriels\u00a0lourds de fabrication de v\u00e9hicules\u00a0et des offres service qui\u00a0doivent \u00eatre disponibles dans\u00a0tous nos points de vente &amp; service\u00a0en Europe ? Aujourd\u2019hui, le secteur du\u00a0transport routier est plus\u00a0concentr\u00e9. La crise a oblig\u00e9\u00a0nos clients \u00e0 se r\u00e9organiser : il\u00a0y a un peu moins d\u2019acteurs sur\u00a0le march\u00e9 mais ce sont des acteurs\u00a0plus grands, plus forts. Ce\u00a0qui leur permet de mieux couvrir\u00a0leurs frais fixes et d\u2019avoir\u00a0une capacit\u00e9 d\u2019achat plus puissante.\u00a0Nous avons aussi eu\u00a0confirmation qu\u2019en temps de\u00a0crise, le client qui survit est celui\u00a0qui investit dans la qualit\u00e9.\u00a0Comme on dit en espagnol \u00ab a\u00a0lo largo, lo barato sale caro \u00bb ! Autrement dit, mieux vaut bien\u00a0investir d\u00e8s le d\u00e9part dans un\u00a0produit de qualit\u00e9\u2026 Afin de\u00a0minimiser l\u2019immobilisation du\u00a0v\u00e9hicule, ce qui pourrait mettre\u00a0en p\u00e9ril la relation avec vos\u00a0propres clients. Avec ces enseignements,\u00a0nous nous sommes donc adapt\u00e9s\u00a0nous aussi. Nous avons\u00a0chang\u00e9 notre organisation afin\u00a0de cr\u00e9er un groupe d\u2019entreprises,\u00a0d\u00e9sormais appel\u00e9 \u00ab Volvo\u00a0Group Espa\u00f1a \u00bb. Cette nouvelle\u00a0structure nous permettra\u00a0de mieux optimiser la gestion\u00a0de nos deux marques prestigieuses,\u00a0Renault Trucks et Volvo\u00a0Trucks. Tout en gardant sa\u00a0propre identit\u00e9, chacune pourra\u00a0s\u2019enrichir de l\u2019exp\u00e9rience de\u00a0l\u2019autre pour offrir le meilleur\u00a0v\u00e9hicule et les meilleurs services\u00a0apr\u00e8s-vente \u00e0 ses clients\u00a0respectifs. En m\u00eame temps,\u00a0nous cr\u00e9erons des optimisations\u00a0de co\u00fbts dans notre fa\u00e7on\u00a0de travailler ; les unit\u00e9s\u00a0de support seront d\u00e9sormais\u00a0regroup\u00e9es par process et non par marque. En interne, chacun aura un d\u00e9fi nouveau \u00e0 relever, ce qui sera certainement source de motivation et de d\u00e9veloppement de son talent.<\/p>\n<p style=\"text-align: justify\"><strong>En quoi cela va-t-il renforcer\u00a0le Groupe Volvo en\u00a0Espagne ?<\/strong> L\u2019union fait la force dit le proverbe\u00a0! Aujourd\u2019hui, on parle\u00a0de partage de meilleures exp\u00e9riences\u00a0(\u00ab to share best practices\u00a0\u00bb en anglais). Je crois que\u00a0l\u2019actif principalement d\u2019une\u00a0entreprise est l\u2019actif Humain.\u00a0En regroupant nos collaborateurs\u00a0dans un m\u00eame site, en\u00a0cr\u00e9ant un climat de confiance\u00a0o\u00f9 l\u2019h\u00e9ritage de chaque marque\u00a0est respect\u00e9, o\u00f9 la parole\u00a0est libre et o\u00f9 les id\u00e9es sont\u00a0constructives, nous cr\u00e9erons un\u00a0environnement propice \u00e0 am\u00e9liorer\u00a0de fa\u00e7on exponentielle\u00a0la qualit\u00e9 de service que nous\u00a0offrons \u00e0 nos clients. Qui sera\u00a0le premier b\u00e9n\u00e9ficiaire de cette\u00a0nouvelle organisation !<\/p>\n<p style=\"text-align: justify\"><strong>Comment vous situez-vous\u00a0par rapport au reste des acteurs\u00a0du march\u00e9 ?<\/strong> Nous sommes d\u00e9finitivement\u00a0leaders ! A fin Mars, notre part\u00a0de march\u00e9 (v\u00e9hicules plus de\u00a016t) est de 30%, soit 4% de\u00a0plus par rapport au suivant.\u00a0Ceci gr\u00e2ce \u00e0 la confiance d\u00e9pos\u00e9e\u00a0par nos clients dans nos\u00a0marques. Je crois que nos valeurs\u00a0corporatives (s\u00e9curit\u00e9,\u00a0qualit\u00e9, respect pour l\u2019environnement)\u00a0ont guid\u00e9 toutes\u00a0les actions mises en oeuvre\u00a0par notre Groupe et je suis\u00a0heureux de constater que nos\u00a0clients d\u2019hier sont encore op\u00e9rationnels\u00a0aujourd\u2019hui et pour\u00a0nombre d\u2019entre eux, sortent\u00a0de la crise plus forts qu\u2019ils n\u2019y\u00a0\u00e9taient entr\u00e9s.<\/p>\n<p style=\"text-align: justify\"><strong>Plus personnellement,\u00a0pensez-vous que l&rsquo;Espagne\u00a0va devenir une\u00a0locomotive \u00e9conomique\u00a0en Europe ? Plus g\u00e9n\u00e9ralement,\u00a0quelle est la force\u00a0du pays aujourd&rsquo;hui ? <\/strong>Je le crois ! Et son redressement\u00a0est impressionnant. Il y\u00a03 ans, les experts \u00e9conomiques\u00a0de Bruxelles se demandaient\u00a0quand on allait devoir intervenir\u00a0pour \u00ab sauver \u00bb le pays\u2026\u00a0Depuis, nombre de r\u00e9formes\u00a0ont \u00e9t\u00e9 introduites et elles commencent\u00a0\u00e0 donner leurs fruits.Certes, la facture sociale est\u00a0lourde ; l\u2019\u00e9rosion du pouvoir\u00a0d\u2019achat est forte, mais l\u2019urgence\u00a0de la situation dictait la mise en\u00a0place de r\u00e9formes fortes.\u00a0Aujourd\u2019hui, je crois que\u00a0l\u2019Espagne est sur la bonne\u00a0voie et je veux croire que sa\u00a0force r\u00e9side d\u00e9sormais dans\u00a0les enseignements de la crise ;\u00a0il n\u2019est pas sain de \u00ab sur financer\u00a0\u00bb, on ne peut faillir sur la\u00a0transparence et l\u2019anticipation\u00a0du moyen terme est une obligation.\u00a0Enfin, je suis impressionn\u00e9\u00a0par la capacit\u00e9 d\u2019innovation\u00a0de l\u2019Espagne, par sa solidarit\u00e9\u00a0et par son optimisme.<\/p>\n<p> Phillipe Chevassus<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>St\u00e9phane de Creisquer, CEO, Volvo Espagne St\u00e9phane de Creisquer fait partie de ces fran\u00e7ais influents en Espagne et \u00e0 la t\u00eate de filiales de grands groupes. C&rsquo;est le patron de Volvo Espagne, il\u00a0dirige plus de 800 employ\u00e9s. La reprise \u00e9conomique est plus qu&rsquo;une r\u00e9alit\u00e9 pour St\u00e9phane de Creisquer. D&rsquo;ailleurs, la construction et le transport sont\u00a0selon [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":42321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-74002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=74002"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/74002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/42321"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=74002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=74002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=74002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}