{"id":73985,"date":"2026-03-18T09:05:44","date_gmt":"2026-03-18T09:05:44","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/le-plus-grand-bateau-du-monde-rapportera-27-millions-deuros-a-lespagne-2\/"},"modified":"2026-08-21T10:17:04","modified_gmt":"2026-08-21T10:17:04","slug":"le-plus-grand-bateau-du-monde-rapportera-27-millions-deuros-a-lespagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/le-plus-grand-bateau-du-monde-rapportera-27-millions-deuros-a-lespagne-2\/","title":{"rendered":"Le plus grand bateau du monde rapportera 27 millions d&rsquo;euros \u00e0 l&rsquo;Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p style=\"text-align: justify\">MADRID, 19 May. (EUROPA PRESS)<\/p>\n<p style=\"text-align: justify\">The Allure of the Seas, le bateau le plus grand monde qui partira du port de Barcelone la semaine prochaine produira un b\u00e9n\u00e9fice colossal pour l&rsquo;Espagne de 27 millions d&rsquo;euros. 150.000 voyageurs sont pr\u00e9vus en 2015 soit au total 300.000 avec ceux effectuant des escales et des embarquements.<\/p>\n<p style=\"text-align: justify\">Le cargo qui a la taille de 4 stades de football a choisi la ville olympique pour partir effectuer ses croisi\u00e8res dans la M\u00e9diterran\u00e9e jusqu&rsquo;en octobre.<\/p>\n<p style=\"text-align: justify\">Des 27 millions de b\u00e9n\u00e9fice pr\u00e9vus, 17,5 millions iront \u00e0 Barcelone, 8 millions \u00e0 Palma de Majorque et le reste sera distribu\u00e9 \u00e0 Malaga, premier port europ\u00e9en dans lequel atterrira le bateau.\u00a0C&rsquo;est depuis Barcelone que s&rsquo;effectuera les premi\u00e8res croisi\u00e8res ou sont pr\u00e9vus des voyages de 5 nuits avec des escales a Rome et Naples. Par la suite, il effectuera 22 trajets de 7 nuits \u00a0jusqu&rsquo;\u00e0 sa derni\u00e8re sorti en Octobre.<\/p>\n<p style=\"text-align: justify\">Apres la capitale catalane, le cargo visitera successivement les ports de Palma de Majorque, Marseille, La Spezia et Naples.<\/p>\n<p style=\"text-align: justify\">Le cargo de 362 m\u00e8tres a une capacit\u00e9 d&rsquo;accueil de 6318 passagers et 2384 membres \u00e9quipages. il s&rsquo;agit de la premi\u00e8re fois qu&rsquo;une embarcation de ce type s&rsquo;effectue en Europe. Auparavant cela s&rsquo;effectuait au Caribe.<\/p>\n<h5 style=\"text-align: justify\">Une navigation en haute mer<\/h5>\n<p style=\"text-align: justify\">Le cargo offrira 5 types de logements ainsi que 37 sortes de chambres et de suites. Les suites de type \u00ab\u00a0loft\u00a0\u00bb d&rsquo;une superficie de 185 m\u00e8tres carr\u00e9s compteront de nombreuses zones de bien \u00eatre et des balcons offrant une vue sur la mer. Le bateau dispose \u00e9galement de deux murs d\u2019escalades de 13 m\u00e8tres de hauteur, une piste de patinage, 10 jacuzzis dont deux d&rsquo;entre eux ont une vue sur l&rsquo;oc\u00e9an.<\/p>\n<p style=\"text-align: justify\">Les voyageurs pourront aussi profiter d&rsquo;une com\u00e9die musicale, d&rsquo;une grande zone de gastronomie et de commerce. Cette zone comprendra un cin\u00e9ma 3D, un Casino du m\u00eame style que Las Vegas de 1672 m\u00e8tres carr\u00e9s ainsi qu&rsquo;un club de jazz.<\/p>\n<p> EUROPA PRESS \/ Le Courrier d\u2019Espagne traduction : Nejma Djelloudi  &nbsp;<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 19 May. (EUROPA PRESS) The Allure of the Seas, le bateau le plus grand monde qui partira du port de Barcelone la semaine prochaine produira un b\u00e9n\u00e9fice colossal pour l&rsquo;Espagne de 27 millions d&rsquo;euros. 150.000 voyageurs sont pr\u00e9vus en 2015 soit au total 300.000 avec ceux effectuant des escales et des embarquements. Le cargo [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[941,660],"class_list":["post-73985","post","type-post","status-publish","format-standard","hentry","category-breaking-news","tag-croisiere","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=73985"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73985\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=73985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=73985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=73985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}