{"id":73919,"date":"2026-03-18T07:17:29","date_gmt":"2026-03-18T07:17:29","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/lhomme-daffaires-carlos-slim-favorable-a-une-retraite-a-75-ans-2\/"},"modified":"2026-08-21T05:49:48","modified_gmt":"2026-08-21T05:49:48","slug":"lhomme-daffaires-carlos-slim-favorable-a-une-retraite-a-75-ans-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/lhomme-daffaires-carlos-slim-favorable-a-une-retraite-a-75-ans-2\/","title":{"rendered":"L&rsquo;homme d&rsquo;affaires Carlos Slim favorable \u00e0 une retraite \u00e0 75 ans"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><strong>Invit\u00e9 au congr\u00e8s annuel de la CEDE (conf\u00e9d\u00e9ration espagnole des dirigeants et cadres sup\u00e9rieurs), l&rsquo;homme d&rsquo;affaires mexicain a plaid\u00e9 pour un nouvel mod\u00e8le de travail : moins d&rsquo;heures hebdomadaires et une retraite \u00e0 70 ou 75 ans.<\/strong>  Carlos Slim, pr\u00e9sident d&rsquo;Am\u00e9rica M\u00f3vil et deuxi\u00e8me homme le plus riche du monde selon Forbes, \u00e9tait l&rsquo;un des orateurs invit\u00e9s au congr\u00e8s de la CEDE ce mardi 6 octobre \u00e0 La Corogne. L&rsquo;homme d&rsquo;affaires y a d\u00e9fendu une nouvelle organisation du travail. <em>\u00ab\u00a0Ne prenons plus notre retraite \u00e0 65 ans mais \u00e0 75 ans, et nos syst\u00e8mes ne seront plus en faillite\u00a0\u00bb<\/em>, a-t-il lanc\u00e9 aux dirigeants les plus influents d&rsquo;Espagne, <em>\u00ab\u00a0prendre sa retraite trop t\u00f4t n&rsquo;est pas viable pour notre \u00e9conomie\u00a0\u00bb<\/em>. Carlos Slim s&rsquo;est en revanche d\u00e9clar\u00e9 favorable \u00e0 une r\u00e9duction du temps hebdomadaire de travail, qu&rsquo;il consid\u00e8re n\u00e9cessaire pour allier vie familiale et professionnelle, mais \u00e9galement pour faciliter l&rsquo;entr\u00e9e de nouveaux actifs sur le march\u00e9 du travail. Il estime que la cr\u00e9ation d&#8217;emploi permettra de combattre la pauvret\u00e9, tout en pr\u00e9cisant que le monde vivait actuellement un <em>\u00ab\u00a0changement de civilisation : d&rsquo;un pouvoir monolithique \u00e0 une participation accrue de la soci\u00e9t\u00e9\u00a0\u00bb<\/em>.  <strong> Le \u00ab\u00a0march\u00e9 naturel\u00a0\u00bb de l&rsquo;Am\u00e9rique latine<\/strong>  Autre invit\u00e9 du Congr\u00e8s, le PDG de Telef\u00f3nica C\u00e9sar Alierta a profit\u00e9 de son intervention pour r\u00e9clamer un <em>\u00ab\u00a0changement des normes et r\u00e9gulations\u00a0\u00bb<\/em> dans le secteur des t\u00e9l\u00e9communications, en Europe comme en Am\u00e9rique latine, afin de rester <em>\u00ab\u00a0comp\u00e9titifs\u00a0\u00bb<\/em> face \u00e0 la concurrence anglo-saxonne. Il a notamment fustig\u00e9 le manque de prospective des instances europ\u00e9ennes: <em>\u00ab\u00a0peu de personnes arrivent \u00e0 se projeter dans le futur et cela se voit \u00e0 Bruxelles\u00a0\u00bb<\/em>. C\u00e9sar Alierta a ensuite encourag\u00e9 les entreprises espagnoles de taille moyenne \u00e0 profiter du <em>\u00ab\u00a0march\u00e9 naturel\u00a0\u00bb<\/em> de l&rsquo;Espagne, l&rsquo;Am\u00e9rique latine, et appel\u00e9 l&rsquo;ensemble des dirigeants \u00e0 faire preuve <em>\u00ab\u00a0d&rsquo;esprit de d\u00e9passement de soi\u00a0\u00bb<\/em> et \u00e0 <em>\u00ab\u00a0s&rsquo;entourer de gens plus brillants que soi\u00a0\u00bb<\/em>. Carlos Slim a pour sa part conclu en recommandant aux chefs d&rsquo;entreprises <em>\u00ab\u00a0d&rsquo;apprendre de leurs erreurs et surtout d&rsquo;apprendre des erreurs des autres\u00a0\u00bb<\/em>.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Invit\u00e9 au congr\u00e8s annuel de la CEDE (conf\u00e9d\u00e9ration espagnole des dirigeants et cadres sup\u00e9rieurs), l&rsquo;homme d&rsquo;affaires mexicain a plaid\u00e9 pour un nouvel mod\u00e8le de travail : moins d&rsquo;heures hebdomadaires et une retraite \u00e0 70 ou 75 ans. Carlos Slim, pr\u00e9sident d&rsquo;Am\u00e9rica M\u00f3vil et deuxi\u00e8me homme le plus riche du monde selon Forbes, \u00e9tait l&rsquo;un des [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[871,2629,2864,2865],"class_list":["post-73919","post","type-post","status-publish","format-standard","hentry","category-breaking-news","tag-amerique-latine","tag-carlos-slim","tag-cede","tag-cesar-alierta"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=73919"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73919\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=73919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=73919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=73919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}