{"id":73901,"date":"2026-03-18T06:46:54","date_gmt":"2026-03-18T06:46:54","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/easyjet-met-en-vente-36-millions-de-places-en-espagne-2\/"},"modified":"2026-08-21T04:45:37","modified_gmt":"2026-08-21T04:45:37","slug":"easyjet-met-en-vente-36-millions-de-places-en-espagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/easyjet-met-en-vente-36-millions-de-places-en-espagne-2\/","title":{"rendered":"easyJet met en vente 3,6 millions de places en Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 22 oct. (EP)  easyJet a mis en vente aujourd\u2019hui 3,6 millions de places en Espagne, en vue de la saison estivale 2016 (jusqu\u2019au 4 septembre), a inform\u00e9 la compagnie a\u00e9rienne britannique low cost.  Au cours de la prochaine campagne, la compagnie a\u00e9rienne a pr\u00e9vu d\u2019exploiter 21.860 vols au total, soit 146 vols de plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente \u00e0 la m\u00eame \u00e9poque.  \u00ab\u00a0L\u2019Espagne est l\u2019un des march\u00e9s cl\u00e9s d\u2019easyJet qui continue d\u2019y cro\u00eetre de mani\u00e8re durable\u00a0\u00bb, a assur\u00e9 le Directeur G\u00e9n\u00e9ral d\u2019easyJet en Espagne, Javier G\u00e1ndara.  Parmi les principales destinations europ\u00e9ennes qu\u2019easyjet relie \u00e0 l\u2019Espagne figurent Londres, Berlin, Paris, Lisbonne, Gen\u00e8ve, Amsterdam, Milan ou B\u00e2le.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 22 oct. (EP) easyJet a mis en vente aujourd\u2019hui 3,6 millions de places en Espagne, en vue de la saison estivale 2016 (jusqu\u2019au 4 septembre), a inform\u00e9 la compagnie a\u00e9rienne britannique low cost. Au cours de la prochaine campagne, la compagnie a\u00e9rienne a pr\u00e9vu d\u2019exploiter 21.860 vols au total, soit 146 vols de plus [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":41882,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[897,660],"class_list":["post-73901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-aeroports","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=73901"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/41882"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=73901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=73901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=73901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}